{"id":199571,"date":"2021-11-18T15:50:30","date_gmt":"2021-11-18T14:50:30","guid":{"rendered":"https:\/\/www.intoscana.it\/it\/?p=199571"},"modified":"2021-11-19T12:30:02","modified_gmt":"2021-11-19T11:30:02","slug":"covid-in-toscana-341-nuovi-casi-eta-media-41-anni-i-decessi-sono-sei","status":"publish","type":"post","link":"https:\/\/www.intoscana.it\/it\/covid-in-toscana-341-nuovi-casi-eta-media-41-anni-i-decessi-sono-sei\/","title":{"rendered":"Covid: in Toscana 341 nuovi casi, et\u00e0 media 41 anni. I decessi sono sei"},"content":{"rendered":"<p>I casi di positivit\u00e0 in Toscana sono <strong>341 in pi\u00f9 rispetto a ieri<\/strong> (332 confermati con tampone molecolare e 9 da test rapido antigenico) con un&#8217;<strong>et\u00e0 media di 41 anni<\/strong>. Ad oggi sono in totale 295.946 i casi accertati.\u00a0 I guariti raggiungono quota 281.040 (95% dei casi totali). Oggi sono stati eseguiti 9.110 tamponi molecolari e 25.943 tamponi antigenici rapidi, di questi il 1% \u00e8 risultato positivo. Sono invece 9.300 i soggetti testati oggi (con tampone antigenico e\/o molecolare, escludendo i tamponi di controllo), di cui il 3,7% \u00e8 risultato positivo. Gli attualmente <strong>positivi sono oggi 7.545<\/strong>, +1% rispetto a ieri. <strong>I ricoverati sono 309<\/strong> (4 in pi\u00f9 rispetto a ieri), di cui <strong>41 in terapia intensiva<\/strong> (2 in pi\u00f9). Si registrano <strong>6 nuovi decessi<\/strong>: 4 uomini e 2 donne con un&#8217;et\u00e0 media di 82,3 anni (2 a Firenze, 2 a Massa Carrara, 1 a Lucca, 1 a Pisa).<\/p>\n<p>Sono 81.981 i casi complessivi ad oggi a Firenze (82 in pi\u00f9 rispetto a ieri), 27.107 a Prato (21 in pi\u00f9), 28.031 a Pistoia (38 in pi\u00f9), 15.454 a Massa Carrara\u00a0 (25 in pi\u00f9), 30.047 a Lucca (19 in pi\u00f9), 34.715 a Pisa (36 in pi\u00f9), 21.917 a Livorno (35 in pi\u00f9), 26.579 ad Arezzo (11 in pi\u00f9), 17.581 a Siena (39 in pi\u00f9), 11.979 a Grosseto (35 in pi\u00f9). Sono 555 i casi positivi notificati in Toscana, ma residenti in altre regioni.<\/p>\n<p>Sono 149 i casi riscontrati oggi nell&#8217;Asl Centro, 107 nella Nord Ovest, 85 nella Sud est.<\/p>\n<h3>Persone in isolamento e ricoverate<\/h3>\n<p>Complessivamente, <strong>7.236 persone<\/strong> sono <strong>in isolamento a casa<\/strong>, poich\u00e9 presentano sintomi lievi che non richiedono cure ospedaliere, o risultano prive di sintomi (72 in pi\u00f9 rispetto a ieri, pi\u00f9 1%).<br \/>\n<strong>Sono 15.829<\/strong> (17 in pi\u00f9 rispetto a ieri, pi\u00f9 0,1%) le persone, anch&#8217;esse isolate, <strong>in sorveglianza attiva<\/strong> perch\u00e9 hanno avuto contatti con persone contagiate (ASL Centro 5.187, Nord Ovest 6.388, Sud Est 4.254).<br \/>\nLe persone <strong>ricoverate oggi sono 309<\/strong> (4 in pi\u00f9 rispetto a ieri, pi\u00f9 1,3%), <strong>41 in terapia intensiva<\/strong> (2 in pi\u00f9 rispetto a ieri, pi\u00f9 5,1%).<\/p>\n<h3>Guarigioni e decessi<\/h3>\n<p><span style=\"color: #000000;\">Le <strong>persone guarite sono 281.040<\/strong> (259 in pi\u00f9 rispetto a ieri, pi\u00f9 0,1%): 0 persone clinicamente guarite (stabili rispetto a ieri), divenute cio\u00e8 asintomatiche dopo aver presentato manifestazioni cliniche associate all&#8217;infezione e 281.040 (259 in pi\u00f9 rispetto a ieri, pi\u00f9 0,1%) dichiarate guarite a tutti gli effetti, le cosiddette guarigioni virali, con tampone negativo.<\/span><\/p>\n<p>Sono <strong>7.361 i deceduti dall&#8217;inizio dell&#8217;epidemia<\/strong> cosi ripartiti: 2.378 a Firenze, 650 a Prato, 684 a Pistoia, 543 a Massa Carrara, 698 a Lucca, 735 a Pisa, 428 a Livorno, 565 ad Arezzo, 364 a Siena, 221 a Grosseto, 95 persone sono decedute sul suolo toscano ma erano residenti fuori regione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In lieve aumento i ricoverati: oggi sono 309 (4 in pi\u00f9 rispetto a ieri) mentre sono 41 le persone in terapia intensiva<\/p>\n","protected":false},"author":525,"featured_media":156481,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[494],"tags":[5470],"class_list":["post-199571","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","tag-vaccinazioni-covid-toscana"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v25.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Covid: in Toscana 341 nuovi casi, et\u00e0 media 41 anni. I decessi sono sei - intoscana<\/title>\n<meta name=\"description\" content=\"In lieve aumento i ricoverati: oggi sono 309 (4 in pi\u00f9 rispetto a ieri) mentre sono 41 le persone in terapia intensiva\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.intoscana.it\/it\/covid-in-toscana-341-nuovi-casi-eta-media-41-anni-i-decessi-sono-sei\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Covid: in Toscana 341 nuovi casi, et\u00e0 media 41 anni. I decessi sono sei\" \/>\n<meta property=\"og:description\" content=\"In lieve aumento i ricoverati: oggi sono 309 (4 in pi\u00f9 rispetto a ieri) mentre sono 41 le persone in terapia intensiva\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.intoscana.it\/it\/covid-in-toscana-341-nuovi-casi-eta-media-41-anni-i-decessi-sono-sei\/\" \/>\n<meta property=\"og:site_name\" content=\"intoscana\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/intoscana.it\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-18T14:50:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-19T11:30:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/shutterstock_1841794108-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1366\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@intoscana\" \/>\n<meta name=\"twitter:site\" content=\"@intoscana\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.intoscana.it\/it\/covid-in-toscana-341-nuovi-casi-eta-media-41-anni-i-decessi-sono-sei\/\",\"url\":\"https:\/\/www.intoscana.it\/it\/covid-in-toscana-341-nuovi-casi-eta-media-41-anni-i-decessi-sono-sei\/\",\"name\":\"Covid: in Toscana 341 nuovi casi, et\u00e0 media 41 anni. I decessi sono sei - intoscana\",\"isPartOf\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/covid-in-toscana-341-nuovi-casi-eta-media-41-anni-i-decessi-sono-sei\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/covid-in-toscana-341-nuovi-casi-eta-media-41-anni-i-decessi-sono-sei\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/shutterstock_1841794108-scaled.jpg\",\"datePublished\":\"2021-11-18T14:50:30+00:00\",\"dateModified\":\"2021-11-19T11:30:02+00:00\",\"author\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8\"},\"description\":\"In lieve aumento i ricoverati: oggi sono 309 (4 in pi\u00f9 rispetto a ieri) mentre sono 41 le persone in terapia intensiva\",\"breadcrumb\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/covid-in-toscana-341-nuovi-casi-eta-media-41-anni-i-decessi-sono-sei\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.intoscana.it\/it\/covid-in-toscana-341-nuovi-casi-eta-media-41-anni-i-decessi-sono-sei\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.intoscana.it\/it\/covid-in-toscana-341-nuovi-casi-eta-media-41-anni-i-decessi-sono-sei\/#primaryimage\",\"url\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/shutterstock_1841794108-scaled.jpg\",\"contentUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/shutterstock_1841794108-scaled.jpg\",\"width\":2048,\"height\":1366,\"caption\":\"Screening con tamponi e tracciamento fondamentali per arginare la diffusione del Covid-19\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.intoscana.it\/it\/covid-in-toscana-341-nuovi-casi-eta-media-41-anni-i-decessi-sono-sei\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.intoscana.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Covid: in Toscana 341 nuovi casi, et\u00e0 media 41 anni. I decessi sono sei\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\",\"url\":\"https:\/\/www.intoscana.it\/it\/\",\"name\":\"intoscana\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.intoscana.it\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8\",\"name\":\"Redazione\",\"url\":\"https:\/\/www.intoscana.it\/it\/author\/redazione\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Covid: in Toscana 341 nuovi casi, et\u00e0 media 41 anni. I decessi sono sei - intoscana","description":"In lieve aumento i ricoverati: oggi sono 309 (4 in pi\u00f9 rispetto a ieri) mentre sono 41 le persone in terapia intensiva","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.intoscana.it\/it\/covid-in-toscana-341-nuovi-casi-eta-media-41-anni-i-decessi-sono-sei\/","og_locale":"it_IT","og_type":"article","og_title":"Covid: in Toscana 341 nuovi casi, et\u00e0 media 41 anni. I decessi sono sei","og_description":"In lieve aumento i ricoverati: oggi sono 309 (4 in pi\u00f9 rispetto a ieri) mentre sono 41 le persone in terapia intensiva","og_url":"https:\/\/www.intoscana.it\/it\/covid-in-toscana-341-nuovi-casi-eta-media-41-anni-i-decessi-sono-sei\/","og_site_name":"intoscana","article_publisher":"https:\/\/www.facebook.com\/intoscana.it","article_published_time":"2021-11-18T14:50:30+00:00","article_modified_time":"2021-11-19T11:30:02+00:00","og_image":[{"width":2048,"height":1366,"url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/shutterstock_1841794108-scaled.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@intoscana","twitter_site":"@intoscana","twitter_misc":{"Written by":"Redazione","Est. reading time":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.intoscana.it\/it\/covid-in-toscana-341-nuovi-casi-eta-media-41-anni-i-decessi-sono-sei\/","url":"https:\/\/www.intoscana.it\/it\/covid-in-toscana-341-nuovi-casi-eta-media-41-anni-i-decessi-sono-sei\/","name":"Covid: in Toscana 341 nuovi casi, et\u00e0 media 41 anni. I decessi sono sei - intoscana","isPartOf":{"@id":"https:\/\/www.intoscana.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.intoscana.it\/it\/covid-in-toscana-341-nuovi-casi-eta-media-41-anni-i-decessi-sono-sei\/#primaryimage"},"image":{"@id":"https:\/\/www.intoscana.it\/it\/covid-in-toscana-341-nuovi-casi-eta-media-41-anni-i-decessi-sono-sei\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/shutterstock_1841794108-scaled.jpg","datePublished":"2021-11-18T14:50:30+00:00","dateModified":"2021-11-19T11:30:02+00:00","author":{"@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8"},"description":"In lieve aumento i ricoverati: oggi sono 309 (4 in pi\u00f9 rispetto a ieri) mentre sono 41 le persone in terapia intensiva","breadcrumb":{"@id":"https:\/\/www.intoscana.it\/it\/covid-in-toscana-341-nuovi-casi-eta-media-41-anni-i-decessi-sono-sei\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.intoscana.it\/it\/covid-in-toscana-341-nuovi-casi-eta-media-41-anni-i-decessi-sono-sei\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.intoscana.it\/it\/covid-in-toscana-341-nuovi-casi-eta-media-41-anni-i-decessi-sono-sei\/#primaryimage","url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/shutterstock_1841794108-scaled.jpg","contentUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/shutterstock_1841794108-scaled.jpg","width":2048,"height":1366,"caption":"Screening con tamponi e tracciamento fondamentali per arginare la diffusione del Covid-19"},{"@type":"BreadcrumbList","@id":"https:\/\/www.intoscana.it\/it\/covid-in-toscana-341-nuovi-casi-eta-media-41-anni-i-decessi-sono-sei\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.intoscana.it\/it\/"},{"@type":"ListItem","position":2,"name":"Covid: in Toscana 341 nuovi casi, et\u00e0 media 41 anni. I decessi sono sei"}]},{"@type":"WebSite","@id":"https:\/\/www.intoscana.it\/it\/#website","url":"https:\/\/www.intoscana.it\/it\/","name":"intoscana","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intoscana.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8","name":"Redazione","url":"https:\/\/www.intoscana.it\/it\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/199571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/users\/525"}],"replies":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/comments?post=199571"}],"version-history":[{"count":0,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/199571\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media\/156481"}],"wp:attachment":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media?parent=199571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/categories?post=199571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/tags?post=199571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}