{"id":201049,"date":"2021-11-27T12:23:02","date_gmt":"2021-11-27T11:23:02","guid":{"rendered":"https:\/\/www.intoscana.it\/it\/?p=201049"},"modified":"2021-11-27T12:28:52","modified_gmt":"2021-11-27T11:28:52","slug":"mita-premiata-lacademy-che-forgia-i-nuovi-tecnici-della-moda","status":"publish","type":"post","link":"https:\/\/www.intoscana.it\/it\/mita-premiata-lacademy-che-forgia-i-nuovi-tecnici-della-moda\/","title":{"rendered":"Mita, premiata l&#8217;Academy che forgia i nuovi tecnici della moda"},"content":{"rendered":"<p>L\u2019<strong>Its Mita di Scandicci<\/strong> si conferma ai vertici del <strong>monitoraggio Indire 2021<\/strong> sul sistema italiano di <strong>Istruzione Tecnica Superiore post-diploma<\/strong>. I <strong>percorsi di studio <\/strong>per formare i nuovi<strong> tecnici specializzati della moda<\/strong>, una volta terminati, aprono le porte del <strong>mondo del lavoro<\/strong> a oltre <strong>il 90% dei neo-diplomati<\/strong>.<\/p>\n<p>I percorsi Its dedicati ad \u201c<strong>accessori metallici e complementi<\/strong>\u201d e \u201c<strong>abbigliamento e accessori di pelle<\/strong>\u201d si sono piazzati rispettivamente <strong>al secondo e terzo posto<\/strong> nella classifica per aree tecnologica (settore <strong>Nuove tecnologie per il made in Italy<\/strong>) e <strong>al 24\u00b0 e 30\u00b0 posto<\/strong> del <strong>ranking generale<\/strong> elaborato dal rapporto dell\u2019Istituto nazionale di documentazione innovazione e ricerca educativa su 201 percorsi.<\/p>\n<p>L\u2019<strong>ITS Mita <\/strong>\u00e8 stata premiata a <strong>Job Orienta<\/strong>, il salone dedicato a orientamento, scuola, formazione e lavoro in corso a <strong>Verona Fiere<\/strong>. \u201c<em>Questo riconoscimento<\/em> \u2013 ha affermato l\u2019assessora a istruzione, formazione e lavoro <strong>Alessandra Nardini<\/strong>, che a Verona ha partecipato alla premiazione \u2013 <em>ci sprona a qualificare e investire sempre di pi\u00f9 nel nostro sistema Its, che in questi anni ha conosciuto uno sviluppo notevole e ci restituisce risultati importante sul fronte delle competenze e dell\u2019occupazione dei nostri giovani<\/em>\u201d.<\/p>\n<figure id=\"post-201052 media-201052\" class=\"align-none\"><img decoding=\"async\" src=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/La-premiazione-dellIts-Mita-di-Scandicci.jpg\" alt=\"\" \/><\/figure>\n<div class=\"titleimg\">La premiazione dell\u2019Its Mita di Scandicci, presente anche l&#8217;assessora Alessandra Nardini<\/div>\n<p>Il <strong>monitoraggio Indire<\/strong> \u00e8 il risultato dell\u2019analisi di percorsi terminati nel 2019 e valutati ad un anno dal diploma. I criteri di costruzione del ranking riguardano qualit\u00e0 didattica, numero dei diplomati e numero degli occupati a 12 mesi. L\u2019edizione 2021 del monitoraggio 2021 evidenzia che <strong>l\u201980% dei diplomati<\/strong> ha trovato <strong>lavoro a un anno dal diploma<\/strong>, di questi il 92% in un\u2019area coerente con il percorso concluso.<\/p>\n<h3>Le Fondazioni Its in Toscana<\/h3>\n<p>Le <strong>Fondazioni Its<\/strong> sono istituti ad alta specializzazione tecnologica, nati per rispondere alla domanda di nuove ed elevate competenze tecniche e tecnologiche da parte delle imprese e costituiscono il segmento di formazione terziaria non universitaria. Nel corso della programmazione 2014-2020 del Fondo sociale europeo <mark>la Toscana ha investito su questo sistema di istruzione professionalizzante oltre 23 milioni di euro<\/mark> che si sono tradotti in <strong>oltre 80 percorsi<\/strong>. Attualmente sono attive <strong>in Toscana 7 fondazioni<\/strong>, a cui di recente se ne sono aggiunte due nuove, la <strong>Fondazione Prodigi<\/strong> per il settore Ict e la <strong>Fondazione Ate<\/strong> per il sistema casa.<\/p>\n<p>La <strong>Fondazione Its Mita<\/strong> \u00e8 una realt\u00e0 di <strong>eccellenza in Toscana<\/strong> ed organizza corsi biennali post diploma di <strong>alta formazione per il settore moda<\/strong> del made in Italy raggiungendo <strong>tassi di occupabilit\u00e0<\/strong> dei propri diplomati <strong>oltre il 90%<\/strong>. Opera dal 2010 in Toscana ed \u00e8 insieme alle Fondazioni Its Energia e Ambiente e Prime <strong>una delle prime 3 Fondazioni Its toscane<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Its di Scandicci si conferma ai vertici del monitoraggio Indire 2021 nel corso di Job Orienta a Verona Fiere<\/p>\n","protected":false},"author":525,"featured_media":201051,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[494],"tags":[6226,361],"class_list":["post-201049","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","tag-alessandra-nardini","tag-formazione"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v25.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mita, premiata l&#039;Academy che forgia i nuovi tecnici della moda - intoscana<\/title>\n<meta name=\"description\" content=\"L\u2019Its di Scandicci si conferma ai vertici del monitoraggio Indire 2021 nel corso di Job Orienta a Verona Fiere\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.intoscana.it\/it\/mita-premiata-lacademy-che-forgia-i-nuovi-tecnici-della-moda\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mita, premiata l&#039;Academy che forgia i nuovi tecnici della moda\" \/>\n<meta property=\"og:description\" content=\"L\u2019Its di Scandicci si conferma ai vertici del monitoraggio Indire 2021 nel corso di Job Orienta a Verona Fiere\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.intoscana.it\/it\/mita-premiata-lacademy-che-forgia-i-nuovi-tecnici-della-moda\/\" \/>\n<meta property=\"og:site_name\" content=\"intoscana\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/intoscana.it\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-27T11:23:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-27T11:28:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/Una-studentessa-della-Mita-Academy-di-Scandicci.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1138\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@intoscana\" \/>\n<meta name=\"twitter:site\" content=\"@intoscana\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.intoscana.it\/it\/mita-premiata-lacademy-che-forgia-i-nuovi-tecnici-della-moda\/\",\"url\":\"https:\/\/www.intoscana.it\/it\/mita-premiata-lacademy-che-forgia-i-nuovi-tecnici-della-moda\/\",\"name\":\"Mita, premiata l'Academy che forgia i nuovi tecnici della moda - intoscana\",\"isPartOf\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/mita-premiata-lacademy-che-forgia-i-nuovi-tecnici-della-moda\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/mita-premiata-lacademy-che-forgia-i-nuovi-tecnici-della-moda\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/Una-studentessa-della-Mita-Academy-di-Scandicci.jpg\",\"datePublished\":\"2021-11-27T11:23:02+00:00\",\"dateModified\":\"2021-11-27T11:28:52+00:00\",\"author\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8\"},\"description\":\"L\u2019Its di Scandicci si conferma ai vertici del monitoraggio Indire 2021 nel corso di Job Orienta a Verona Fiere\",\"breadcrumb\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/mita-premiata-lacademy-che-forgia-i-nuovi-tecnici-della-moda\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.intoscana.it\/it\/mita-premiata-lacademy-che-forgia-i-nuovi-tecnici-della-moda\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.intoscana.it\/it\/mita-premiata-lacademy-che-forgia-i-nuovi-tecnici-della-moda\/#primaryimage\",\"url\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/Una-studentessa-della-Mita-Academy-di-Scandicci.jpg\",\"contentUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/Una-studentessa-della-Mita-Academy-di-Scandicci.jpg\",\"width\":1138,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.intoscana.it\/it\/mita-premiata-lacademy-che-forgia-i-nuovi-tecnici-della-moda\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.intoscana.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mita, premiata l&#8217;Academy che forgia i nuovi tecnici della moda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\",\"url\":\"https:\/\/www.intoscana.it\/it\/\",\"name\":\"intoscana\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.intoscana.it\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8\",\"name\":\"Redazione\",\"url\":\"https:\/\/www.intoscana.it\/it\/author\/redazione\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mita, premiata l'Academy che forgia i nuovi tecnici della moda - intoscana","description":"L\u2019Its di Scandicci si conferma ai vertici del monitoraggio Indire 2021 nel corso di Job Orienta a Verona Fiere","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.intoscana.it\/it\/mita-premiata-lacademy-che-forgia-i-nuovi-tecnici-della-moda\/","og_locale":"it_IT","og_type":"article","og_title":"Mita, premiata l'Academy che forgia i nuovi tecnici della moda","og_description":"L\u2019Its di Scandicci si conferma ai vertici del monitoraggio Indire 2021 nel corso di Job Orienta a Verona Fiere","og_url":"https:\/\/www.intoscana.it\/it\/mita-premiata-lacademy-che-forgia-i-nuovi-tecnici-della-moda\/","og_site_name":"intoscana","article_publisher":"https:\/\/www.facebook.com\/intoscana.it","article_published_time":"2021-11-27T11:23:02+00:00","article_modified_time":"2021-11-27T11:28:52+00:00","og_image":[{"width":1138,"height":800,"url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/Una-studentessa-della-Mita-Academy-di-Scandicci.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@intoscana","twitter_site":"@intoscana","twitter_misc":{"Written by":"Redazione","Est. reading time":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.intoscana.it\/it\/mita-premiata-lacademy-che-forgia-i-nuovi-tecnici-della-moda\/","url":"https:\/\/www.intoscana.it\/it\/mita-premiata-lacademy-che-forgia-i-nuovi-tecnici-della-moda\/","name":"Mita, premiata l'Academy che forgia i nuovi tecnici della moda - intoscana","isPartOf":{"@id":"https:\/\/www.intoscana.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.intoscana.it\/it\/mita-premiata-lacademy-che-forgia-i-nuovi-tecnici-della-moda\/#primaryimage"},"image":{"@id":"https:\/\/www.intoscana.it\/it\/mita-premiata-lacademy-che-forgia-i-nuovi-tecnici-della-moda\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/Una-studentessa-della-Mita-Academy-di-Scandicci.jpg","datePublished":"2021-11-27T11:23:02+00:00","dateModified":"2021-11-27T11:28:52+00:00","author":{"@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8"},"description":"L\u2019Its di Scandicci si conferma ai vertici del monitoraggio Indire 2021 nel corso di Job Orienta a Verona Fiere","breadcrumb":{"@id":"https:\/\/www.intoscana.it\/it\/mita-premiata-lacademy-che-forgia-i-nuovi-tecnici-della-moda\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.intoscana.it\/it\/mita-premiata-lacademy-che-forgia-i-nuovi-tecnici-della-moda\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.intoscana.it\/it\/mita-premiata-lacademy-che-forgia-i-nuovi-tecnici-della-moda\/#primaryimage","url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/Una-studentessa-della-Mita-Academy-di-Scandicci.jpg","contentUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/Una-studentessa-della-Mita-Academy-di-Scandicci.jpg","width":1138,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.intoscana.it\/it\/mita-premiata-lacademy-che-forgia-i-nuovi-tecnici-della-moda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.intoscana.it\/it\/"},{"@type":"ListItem","position":2,"name":"Mita, premiata l&#8217;Academy che forgia i nuovi tecnici della moda"}]},{"@type":"WebSite","@id":"https:\/\/www.intoscana.it\/it\/#website","url":"https:\/\/www.intoscana.it\/it\/","name":"intoscana","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intoscana.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8","name":"Redazione","url":"https:\/\/www.intoscana.it\/it\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/201049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/users\/525"}],"replies":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/comments?post=201049"}],"version-history":[{"count":0,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/201049\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media\/201051"}],"wp:attachment":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media?parent=201049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/categories?post=201049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/tags?post=201049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}