{"id":206021,"date":"2022-01-05T14:57:08","date_gmt":"2022-01-05T13:57:08","guid":{"rendered":"https:\/\/www.intoscana.it\/it\/?p=206021"},"modified":"2022-01-05T15:18:27","modified_gmt":"2022-01-05T14:18:27","slug":"beni-confiscati-mafie-contributi-regione","status":"publish","type":"post","link":"https:\/\/www.intoscana.it\/it\/beni-confiscati-mafie-contributi-regione\/","title":{"rendered":"Beni confiscati alle mafie, la Regione sostiene gli enti locali con 3,5 milioni"},"content":{"rendered":"<p>Sostenere gli enti locali che investono sul recupero e la ristrutturazione a fini istituzionali o sociali di beni confiscati alla criminalit\u00e0 organizzata. \u00c8 l\u2019obiettivo che la Regione Toscana intende perseguire con l&#8217;introduzione della legge regionale n. 44 del 29 novembre scorso, che prevede c<strong>ontributi regionali per gli investimenti su questa particolare tipologia di immobili.<\/strong> <mark>In totale la giunta ha stanziato 3 milioni e mezzo di euro: 1,5 milioni per il 2022 e 2 milioni di euro per il 2023 <\/mark><\/p>\n<p>\u201cSono molto orgoglioso di questa misura \u2013 ha dichiarato il presidente <strong>Eugenio Giani<\/strong> \u2013 perch\u00e9 ci consente di perseguire il triplice scopo di dare un segnale contro le mafie, di dare un contributo alla ripartenza e di <strong>sostenere i comuni nella riqualificazione di immobili a vantaggio delle proprie comunit\u00e0, evitando il rischio che gli edifici finiscano in preda all\u2019abbandono<\/strong>. Sono certo che le amministrazioni non si lasceranno sfuggire questa occasione\u201d.<\/p>\n<p>In vista del provvedimento attuativo, l\u2019assessorato alla cultura della legalit\u00e0 guidato da<strong> Stefano Ciuoffo<\/strong> ha inviato una lettera a tutti i sindaci dei comuni toscani, ai presidenti della Citt\u00e0 metropolitana di Firenze e delle Province, ad Anci e a Upi, invitandoli a segnalare agli uffici regionali la propria manifestazione di interesse <strong>entro il prossimo 31 gennaio, con l\u2019indicazione dei principali adempimenti necessari per l\u2019attivazione delle procedure.<\/strong> In particolare, la manifestazione di interesse dovr\u00e0 contenere informazioni su: identificazione del bene immobile e avvenuto trasferimento all\u2019ente; descrizione dell\u2019intervento che si intende realizzare; l\u2019eventuale compartecipazione alla spesa per la progettazione e realizzazione dell\u2019intervento; l\u2019uso a cui il bene \u00e8 destinato; l\u2019eventuale svolgimento di processi partecipativi o di attivit\u00e0 di co-programmazione o co-progettazione; l\u2019indicazione del responsabile del procedimento.<\/p>\n<p>&#8220;E&#8217; un provvedimento importante con il quale la Regione &#8211; <strong>ha detto l&#8217;assessore Ciuoffo<\/strong> &#8211; \u00a0si fa parte attiva nell&#8217;impegno di restituzione alla societ\u00e0 dei beni frutto di attivit\u00e0 illegali e criminali, e lo fa in modo concreto a fianco dei comuni cui sono stati destinati i beni dallo stato. Non si tratta solo di elargizione di risorse per ristrutturazioni immobili di propriet\u00e0 di un altro ente: il ridare vita a luoghi come questi con finalit\u00e0 istituzionali o sociali \u00e8 un simbolo per la lotta alla criminalit\u00e0. I comuni molto spesso, sopratutto quelli piccoli, non hanno le necessarie risorse per la riconversione degli immobili e quindi questa azione nel tempo rischia di arenarsi. Con questa legge vogliamo porre rimedio a ci\u00f2 per velocizzare la realizzazione dei tanti progetti ancora fermi&#8221;.<\/p>\n<p>La comunicazione dovr\u00e0 essere inviata alla Giunta regionale \u2013 Settore affari istituzionali e delle autonomie locali e cultura della legalit\u00e0 attraverso il protocollo interoperabile (InterPRO) o mediante PEC trasmessa a regionetoscana@postacert.toscana.it.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Contributi regionali per gli investimenti in immobili confiscati alla criminalit\u00e0 cos\u00ec da sottrarli all&#8217;abbandono. Giani: &#8220;Forte segnale contro le mafie&#8221;. I comuni hanno tempo fino al 31 gennaio per richiedere il finanziamento<\/p>\n","protected":false},"author":525,"featured_media":147053,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[494],"tags":[3622],"class_list":["post-206021","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","tag-mafia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v25.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Beni confiscati alle mafie, la Regione sostiene gli enti locali con 3,5 milioni - intoscana<\/title>\n<meta name=\"description\" content=\"Giani: &quot;Forte segnale contro le mafie&quot;. I comuni hanno tempo fino al 31 gennaio per richiedere il finanziamento\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.intoscana.it\/it\/beni-confiscati-mafie-contributi-regione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Beni confiscati alle mafie, la Regione sostiene gli enti locali con 3,5 milioni\" \/>\n<meta property=\"og:description\" content=\"Giani: &quot;Forte segnale contro le mafie&quot;. I comuni hanno tempo fino al 31 gennaio per richiedere il finanziamento\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.intoscana.it\/it\/beni-confiscati-mafie-contributi-regione\/\" \/>\n<meta property=\"og:site_name\" content=\"intoscana\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/intoscana.it\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-05T13:57:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-05T14:18:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/12suvignano-tenuta-aperta-2020.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@intoscana\" \/>\n<meta name=\"twitter:site\" content=\"@intoscana\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.intoscana.it\/it\/beni-confiscati-mafie-contributi-regione\/\",\"url\":\"https:\/\/www.intoscana.it\/it\/beni-confiscati-mafie-contributi-regione\/\",\"name\":\"Beni confiscati alle mafie, la Regione sostiene gli enti locali con 3,5 milioni - intoscana\",\"isPartOf\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/beni-confiscati-mafie-contributi-regione\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/beni-confiscati-mafie-contributi-regione\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/12suvignano-tenuta-aperta-2020.jpg\",\"datePublished\":\"2022-01-05T13:57:08+00:00\",\"dateModified\":\"2022-01-05T14:18:27+00:00\",\"author\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8\"},\"description\":\"Giani: \\\"Forte segnale contro le mafie\\\". I comuni hanno tempo fino al 31 gennaio per richiedere il finanziamento\",\"breadcrumb\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/beni-confiscati-mafie-contributi-regione\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.intoscana.it\/it\/beni-confiscati-mafie-contributi-regione\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.intoscana.it\/it\/beni-confiscati-mafie-contributi-regione\/#primaryimage\",\"url\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/12suvignano-tenuta-aperta-2020.jpg\",\"contentUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/12suvignano-tenuta-aperta-2020.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.intoscana.it\/it\/beni-confiscati-mafie-contributi-regione\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.intoscana.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Beni confiscati alle mafie, la Regione sostiene gli enti locali con 3,5 milioni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\",\"url\":\"https:\/\/www.intoscana.it\/it\/\",\"name\":\"intoscana\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.intoscana.it\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8\",\"name\":\"Redazione\",\"url\":\"https:\/\/www.intoscana.it\/it\/author\/redazione\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Beni confiscati alle mafie, la Regione sostiene gli enti locali con 3,5 milioni - intoscana","description":"Giani: \"Forte segnale contro le mafie\". I comuni hanno tempo fino al 31 gennaio per richiedere il finanziamento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.intoscana.it\/it\/beni-confiscati-mafie-contributi-regione\/","og_locale":"it_IT","og_type":"article","og_title":"Beni confiscati alle mafie, la Regione sostiene gli enti locali con 3,5 milioni","og_description":"Giani: \"Forte segnale contro le mafie\". I comuni hanno tempo fino al 31 gennaio per richiedere il finanziamento","og_url":"https:\/\/www.intoscana.it\/it\/beni-confiscati-mafie-contributi-regione\/","og_site_name":"intoscana","article_publisher":"https:\/\/www.facebook.com\/intoscana.it","article_published_time":"2022-01-05T13:57:08+00:00","article_modified_time":"2022-01-05T14:18:27+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/12suvignano-tenuta-aperta-2020.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@intoscana","twitter_site":"@intoscana","twitter_misc":{"Written by":"Redazione","Est. reading time":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.intoscana.it\/it\/beni-confiscati-mafie-contributi-regione\/","url":"https:\/\/www.intoscana.it\/it\/beni-confiscati-mafie-contributi-regione\/","name":"Beni confiscati alle mafie, la Regione sostiene gli enti locali con 3,5 milioni - intoscana","isPartOf":{"@id":"https:\/\/www.intoscana.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.intoscana.it\/it\/beni-confiscati-mafie-contributi-regione\/#primaryimage"},"image":{"@id":"https:\/\/www.intoscana.it\/it\/beni-confiscati-mafie-contributi-regione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/12suvignano-tenuta-aperta-2020.jpg","datePublished":"2022-01-05T13:57:08+00:00","dateModified":"2022-01-05T14:18:27+00:00","author":{"@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8"},"description":"Giani: \"Forte segnale contro le mafie\". I comuni hanno tempo fino al 31 gennaio per richiedere il finanziamento","breadcrumb":{"@id":"https:\/\/www.intoscana.it\/it\/beni-confiscati-mafie-contributi-regione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.intoscana.it\/it\/beni-confiscati-mafie-contributi-regione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.intoscana.it\/it\/beni-confiscati-mafie-contributi-regione\/#primaryimage","url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/12suvignano-tenuta-aperta-2020.jpg","contentUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/12suvignano-tenuta-aperta-2020.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.intoscana.it\/it\/beni-confiscati-mafie-contributi-regione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.intoscana.it\/it\/"},{"@type":"ListItem","position":2,"name":"Beni confiscati alle mafie, la Regione sostiene gli enti locali con 3,5 milioni"}]},{"@type":"WebSite","@id":"https:\/\/www.intoscana.it\/it\/#website","url":"https:\/\/www.intoscana.it\/it\/","name":"intoscana","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intoscana.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8","name":"Redazione","url":"https:\/\/www.intoscana.it\/it\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/206021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/users\/525"}],"replies":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/comments?post=206021"}],"version-history":[{"count":0,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/206021\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media\/147053"}],"wp:attachment":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media?parent=206021"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/categories?post=206021"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/tags?post=206021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}