{"id":206066,"date":"2022-01-07T09:36:12","date_gmt":"2022-01-07T08:36:12","guid":{"rendered":"https:\/\/www.intoscana.it\/it\/?p=206066"},"modified":"2022-01-07T16:11:06","modified_gmt":"2022-01-07T15:11:06","slug":"stop-alle-vibrazioni-in-piazza-santissima-annunziata","status":"publish","type":"post","link":"https:\/\/www.intoscana.it\/it\/stop-alle-vibrazioni-in-piazza-santissima-annunziata\/","title":{"rendered":"Traffico, stop alle vibrazioni in Piazza Santissima Annunziata"},"content":{"rendered":"<p>E&#8217; una nuova <strong>soletta in cemento armato<\/strong> l&#8217;arma in pi\u00f9 per ridurre <strong>le vibrazioni in piazza Santissima Annunziat<\/strong>a a Firenze. Ogni giorno il passaggio di migliaia di veicoli, in particolare dei <strong>bus del trasporto pubblico<\/strong>, causano movimenti, non sempre impercettibili. Con tutte le conseguenze immaginabili, alla lunga, sulla tenuta di palazzi e monumenti. Sono sotto gli occhi di tutti <strong>le crepe e le piccole perdite d&#8217;intonaco<\/strong> nel loggiato della basilica.<\/p>\n<p><strong>Palazzo Vecchio<\/strong> ha deciso di procedere anche alla sistemazione della <strong>pavimentazione in lastrico<\/strong> della carreggiata e del marciapiede antistante al loggiato della Basilica oltre al <strong>rifacimento di via della Colonna<\/strong> tra la piazza e via della Pergola. Il <strong>progetto definitivo<\/strong> approvato dalla giunta comunale nell\u2019ultima seduta del 2021 su proposta dell\u2019assessore alla Mobilit\u00e0 <strong>Stefano Giorgetti<\/strong> va a completare cos\u00ec gli interventi lungo l&#8217;asse viario interessato.<\/p>\n<p>\u201c<em>Piazza Santissima Annunziata riveste un ruolo di primaria importanza nell\u2019ambito della mobilit\u00e0 urbana, sia per quanto riguarda i pedoni, visti gli edifici presenti e la vicinanza di numerosi altri centri di interesse culturale e turistico, sia per quanto riguarda i veicoli, con particolare riferimento al Tpl<\/em> \u2013 sottolinea <strong>l\u2019assessore Giorgetti<\/strong> -. <em>La Basilica di Santissima Annunziata, in particolar modo il loggiato, risente degli effetti delle vibrazioni causate dal traffico veicolare che transita nell\u2019area stradale adiacente, soprattutto dai bus che percorrono la direttrice piazza San Marco\u2013piazza D\u2019Azeglio nei due sensi. Per questo abbiamo deciso di intervenire con una riqualificazione profonda della sede stradale: prima il rifacimento della soletta in cemento armato sottostante la pavimentazione in modo da ridurre le vibrazioni, a seguire con la posa del nuovo lastrico sulla carreggiata<\/em>\u201d.<\/p>\n<p>Ma il progetto riguarda anche <strong>via della Colonna<\/strong> dove, nel tratto compreso <strong>tra piazza Santissima Annunziata e via della Pergola<\/strong>, si proceder\u00e0 al ripristino della <strong>sede stradale in asfalto<\/strong>, con anche rifacimento del sottofondo, e di importanti porzioni dei <strong>marciapiedi in lastrichino<\/strong>. Per questo intervento sono stati stanziati 500mila euro.<br \/>\n\u201c<em>Con questo progetto si completa la riqualificazione dell\u2019asse piazza D\u2019Azeglio-piazza Santissima Annunziata: negli ultimi anni sono stati eseguiti interventi sul tratto in pietra di piazza D\u2019Azeglio, ma anche su via Niccolini e su via della Colonna<\/em>\u201d conclude <strong>l\u2019assessore Giorgetti<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una nuova soletta in cemento armato per limitare gli effetti del quotidiano passaggio dei bus del trasporto pubblico<\/p>\n","protected":false},"author":525,"featured_media":70149,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[494],"tags":[202,5057],"class_list":["post-206066","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","tag-firenze","tag-lavori"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v25.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Traffico, stop alle vibrazioni in Piazza Santissima Annunziata - intoscana<\/title>\n<meta name=\"description\" content=\"Una nuova soletta in cemento armato per limitare gli effetti del quotidiano passaggio dei bus del trasporto pubblico\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.intoscana.it\/it\/stop-alle-vibrazioni-in-piazza-santissima-annunziata\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Traffico, stop alle vibrazioni in Piazza Santissima Annunziata\" \/>\n<meta property=\"og:description\" content=\"Una nuova soletta in cemento armato per limitare gli effetti del quotidiano passaggio dei bus del trasporto pubblico\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.intoscana.it\/it\/stop-alle-vibrazioni-in-piazza-santissima-annunziata\/\" \/>\n<meta property=\"og:site_name\" content=\"intoscana\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/intoscana.it\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-07T08:36:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-07T15:11:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/c28l-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"677\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@intoscana\" \/>\n<meta name=\"twitter:site\" content=\"@intoscana\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.intoscana.it\/it\/stop-alle-vibrazioni-in-piazza-santissima-annunziata\/\",\"url\":\"https:\/\/www.intoscana.it\/it\/stop-alle-vibrazioni-in-piazza-santissima-annunziata\/\",\"name\":\"Traffico, stop alle vibrazioni in Piazza Santissima Annunziata - intoscana\",\"isPartOf\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/stop-alle-vibrazioni-in-piazza-santissima-annunziata\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/stop-alle-vibrazioni-in-piazza-santissima-annunziata\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/c28l-1.jpg\",\"datePublished\":\"2022-01-07T08:36:12+00:00\",\"dateModified\":\"2022-01-07T15:11:06+00:00\",\"author\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8\"},\"description\":\"Una nuova soletta in cemento armato per limitare gli effetti del quotidiano passaggio dei bus del trasporto pubblico\",\"breadcrumb\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/stop-alle-vibrazioni-in-piazza-santissima-annunziata\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.intoscana.it\/it\/stop-alle-vibrazioni-in-piazza-santissima-annunziata\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.intoscana.it\/it\/stop-alle-vibrazioni-in-piazza-santissima-annunziata\/#primaryimage\",\"url\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/c28l-1.jpg\",\"contentUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/c28l-1.jpg\",\"width\":1000,\"height\":677,\"caption\":\"Piazza Santissima Annunziata\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.intoscana.it\/it\/stop-alle-vibrazioni-in-piazza-santissima-annunziata\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.intoscana.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Traffico, stop alle vibrazioni in Piazza Santissima Annunziata\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\",\"url\":\"https:\/\/www.intoscana.it\/it\/\",\"name\":\"intoscana\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.intoscana.it\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8\",\"name\":\"Redazione\",\"url\":\"https:\/\/www.intoscana.it\/it\/author\/redazione\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Traffico, stop alle vibrazioni in Piazza Santissima Annunziata - intoscana","description":"Una nuova soletta in cemento armato per limitare gli effetti del quotidiano passaggio dei bus del trasporto pubblico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.intoscana.it\/it\/stop-alle-vibrazioni-in-piazza-santissima-annunziata\/","og_locale":"it_IT","og_type":"article","og_title":"Traffico, stop alle vibrazioni in Piazza Santissima Annunziata","og_description":"Una nuova soletta in cemento armato per limitare gli effetti del quotidiano passaggio dei bus del trasporto pubblico","og_url":"https:\/\/www.intoscana.it\/it\/stop-alle-vibrazioni-in-piazza-santissima-annunziata\/","og_site_name":"intoscana","article_publisher":"https:\/\/www.facebook.com\/intoscana.it","article_published_time":"2022-01-07T08:36:12+00:00","article_modified_time":"2022-01-07T15:11:06+00:00","og_image":[{"width":1000,"height":677,"url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/c28l-1.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@intoscana","twitter_site":"@intoscana","twitter_misc":{"Written by":"Redazione","Est. reading time":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.intoscana.it\/it\/stop-alle-vibrazioni-in-piazza-santissima-annunziata\/","url":"https:\/\/www.intoscana.it\/it\/stop-alle-vibrazioni-in-piazza-santissima-annunziata\/","name":"Traffico, stop alle vibrazioni in Piazza Santissima Annunziata - intoscana","isPartOf":{"@id":"https:\/\/www.intoscana.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.intoscana.it\/it\/stop-alle-vibrazioni-in-piazza-santissima-annunziata\/#primaryimage"},"image":{"@id":"https:\/\/www.intoscana.it\/it\/stop-alle-vibrazioni-in-piazza-santissima-annunziata\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/c28l-1.jpg","datePublished":"2022-01-07T08:36:12+00:00","dateModified":"2022-01-07T15:11:06+00:00","author":{"@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8"},"description":"Una nuova soletta in cemento armato per limitare gli effetti del quotidiano passaggio dei bus del trasporto pubblico","breadcrumb":{"@id":"https:\/\/www.intoscana.it\/it\/stop-alle-vibrazioni-in-piazza-santissima-annunziata\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.intoscana.it\/it\/stop-alle-vibrazioni-in-piazza-santissima-annunziata\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.intoscana.it\/it\/stop-alle-vibrazioni-in-piazza-santissima-annunziata\/#primaryimage","url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/c28l-1.jpg","contentUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/c28l-1.jpg","width":1000,"height":677,"caption":"Piazza Santissima Annunziata"},{"@type":"BreadcrumbList","@id":"https:\/\/www.intoscana.it\/it\/stop-alle-vibrazioni-in-piazza-santissima-annunziata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.intoscana.it\/it\/"},{"@type":"ListItem","position":2,"name":"Traffico, stop alle vibrazioni in Piazza Santissima Annunziata"}]},{"@type":"WebSite","@id":"https:\/\/www.intoscana.it\/it\/#website","url":"https:\/\/www.intoscana.it\/it\/","name":"intoscana","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intoscana.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8","name":"Redazione","url":"https:\/\/www.intoscana.it\/it\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/206066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/users\/525"}],"replies":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/comments?post=206066"}],"version-history":[{"count":0,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/206066\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media\/70149"}],"wp:attachment":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media?parent=206066"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/categories?post=206066"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/tags?post=206066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}