{"id":206821,"date":"2022-01-12T15:45:10","date_gmt":"2022-01-12T14:45:10","guid":{"rendered":"https:\/\/www.intoscana.it\/it\/?p=206821"},"modified":"2022-01-13T10:38:53","modified_gmt":"2022-01-13T09:38:53","slug":"covid-13-341-nuovi-casi","status":"publish","type":"post","link":"https:\/\/www.intoscana.it\/it\/covid-13-341-nuovi-casi\/","title":{"rendered":"Covid, 13.341 nuovi casi su poco pi\u00f9 di 25 mila tamponi"},"content":{"rendered":"<p>In Toscana <strong>sono 534.357 i casi di positivit\u00e0 al Coronavirus<\/strong>, <strong>13.341 in pi\u00f9 rispetto a ieri<\/strong>: 5.060 confermati con tampone molecolare e 8.281 da test rapido antigenico.<\/p>\n<h3>I nuovi casi<\/h3>\n<p>I nuovi casi sono il 2,6% in pi\u00f9 rispetto al totale del giorno precedente. <strong>Oggi sono stati eseguiti 25.068 tamponi molecolari<\/strong> e 47.127 tamponi antigenici rapidi, di questi il 18,5% \u00e8 risultato positivo. Sono invece 19.163 i soggetti testati oggi (con tampone antigenico e\/o molecolare, escludendo i tamponi di controllo), di cui il 69,6% \u00e8 risultato positivo. Gli attualmente positivi sono oggi 178.714, +1,7% rispetto a ieri. La buona notizia \u00e8 che crescono anche i guariti:\u00a0crescono del 3,1% e raggiungono quota 347.888 (65,1% dei casi totali)<\/p>\n<h3>I casi di positivit\u00e0<\/h3>\n<p><strong>L&#8217;et\u00e0 media dei 13.341 nuovi positivi odierni \u00e8 di 38 anni circa<\/strong> (21% ha meno di 20 anni, 26% tra 20 e 39 anni, 36% tra 40 e 59 anni, 14% tra 60 e 79 anni, 3% ha 80 anni o pi\u00f9).<\/p>\n<p>Di seguito i casi di positivit\u00e0 sul territorio con la variazione rispetto a ieri (5.060 confermati con tampone molecolare e 8.281 da test rapido antigenico). Sono 159.600 i casi complessivi ad oggi a Firenze (4.110 in pi\u00f9 rispetto a ieri), 43.662 a Prato (856 in pi\u00f9), 46.474 a Pistoia (1.081 in pi\u00f9), 26.101 a Massa (714 in pi\u00f9), 52.639 a Lucca (1.339 in pi\u00f9), 61.794 a Pisa (1.644 in pi\u00f9), 39.229 a Livorno (1.073 in pi\u00f9), 47.766 ad Arezzo (1.210 in pi\u00f9), 34.851 a Siena (738 in pi\u00f9), 21.686 a Grosseto (576 in pi\u00f9). Sono 555 i casi positivi notificati in Toscana, ma residenti in altre regioni.<\/p>\n<p>Sono 6.282 i casi riscontrati oggi nell&#8217;Asl Centro, 4.535 nella Nord Ovest, 2.524 nella Sud est.<\/p>\n<p>La Toscana si trova al 9\u00b0 posto in Italia come numerosit\u00e0 di casi (comprensivi di residenti e non residenti), con circa 14.470 casi per 100.000 abitanti (media italiana circa 13.125 x100.000, dato di ieri). Le province di notifica con il tasso pi\u00f9 alto sono Prato con 16.460 casi x100.000 abitanti, Pistoia con 16.012, Firenze con 15.985, la pi\u00f9 bassa Grosseto con 9.955.<\/p>\n<h3>Ricoveri e decessi<\/h3>\n<p>Complessivamente, 177.438 persone sono in isolamento a casa, poich\u00e9 presentano sintomi lievi che non richiedono cure ospedaliere, o risultano prive di sintomi (2.862 in pi\u00f9 rispetto a ieri, pi\u00f9 1,6%).<br \/>\nSono 17.710 (2.290 in pi\u00f9 rispetto a ieri, pi\u00f9 14,9%) le persone, anch&#8217;esse isolate, in sorveglianza attiva perch\u00e9 hanno avuto contatti con persone contagiate (ASL Centro 5.710, Nord Ovest 7.684, Sud Est 4.316).<br \/>\n<strong>Le persone ricoverate nei posti letto dedicati ai pazienti COVID oggi sono complessivamente 1.276<\/strong> (46 in pi\u00f9 rispetto a ieri, pi\u00f9 3,7%), 123 in terapia intensiva (1 in pi\u00f9 rispetto a ieri, pi\u00f9 0,8%).\u00a0 Come accennato, le persone complessivamente guarite sono 347.888 (10.362 in pi\u00f9 rispetto a ieri, pi\u00f9 3,1%): 0 persone clinicamente guarite (stabili rispetto a ieri), divenute cio\u00e8 asintomatiche dopo aver presentato manifestazioni cliniche associate all&#8217;infezione e 347.888 (10.362 in pi\u00f9 rispetto a ieri, pi\u00f9 3,1%) dichiarate guarite a tutti gli effetti, le cosiddette guarigioni virali, con tampone negativo.<\/p>\n<p><strong>Sono 34 i decessi:<\/strong> 11 a Firenze, 2 a Prato, 2 a Pistoia, 1 a Massa Carrara, 4 a Lucca, 4 a Pisa, 5 a Livorno, 3 a Siena, 2 a Grosseto.<\/p>\n<p>Una verifica effettuata nell\u2019ambito territoriale di Livorno ha permesso di individuare 37 pazienti con Covid deceduti nell\u2019arco di 6 mesi, dal 15\u00a0giugno\u00a0al 6 gennaio, che non erano stati comunicati nei mesi passati. Si tratta di 26 uomini e 11 donne con et\u00e0 media 78,6 anni. Relativamente alla provincia di residenza, 35 sono a Livorno, 1 a Pisa e 1 a Lucca.<\/p>\n<p>Sono 7.755 i deceduti dall&#8217;inizio dell&#8217;epidemia cosi ripartiti: 2.476 a Firenze, 682 a Prato, 716 a Pistoia, 563 a Massa Carrara, 734 a Lucca, 778 a Pisa, 491 a Livorno, 573 ad Arezzo, 397 a Siena, 246 a Grosseto, 99 persone sono decedute sul suolo toscano ma erano residenti fuori regione.<\/p>\n<p>Il tasso grezzo di mortalit\u00e0 toscano (numero di deceduti\/popolazione residente) per Covid-19 \u00e8 di 210,0 x100.000 residenti contro il 235,6 x100.000 della media italiana (12\u00b0 regione). Per quanto riguarda le province, il tasso di mortalit\u00e0 pi\u00f9 alto si riscontra a Massa Carrara (296,6 x100.000), Prato (257,1 x100.000) e Firenze (248,0 x100.000), il pi\u00f9 basso a Grosseto (112,9 x100.000).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;et\u00e0 media dei 13.341 nuovi positivi odierni \u00e8 di 38 anni circa (21% ha meno di 20 anni, 26% tra 20 e 39 anni, 36% tra 40 e 59 anni, 14% tra 60 e 79 anni, 3% ha 80 anni o pi\u00f9). Oggi si registrano 34 decessi<\/p>\n","protected":false},"author":525,"featured_media":194287,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[494],"tags":[4809],"class_list":["post-206821","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","tag-covid"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v25.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Covid, 13.341 nuovi casi su poco pi\u00f9 di 25 mila tamponi - intoscana<\/title>\n<meta name=\"description\" content=\"L&#039;et\u00e0 media dei 13.341 nuovi positivi odierni \u00e8 di 38 anni circa (21% ha meno di 20 anni). Oggi si registrano 34 decessi\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.intoscana.it\/it\/covid-13-341-nuovi-casi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Covid, 13.341 nuovi casi su poco pi\u00f9 di 25 mila tamponi\" \/>\n<meta property=\"og:description\" content=\"L&#039;et\u00e0 media dei 13.341 nuovi positivi odierni \u00e8 di 38 anni circa (21% ha meno di 20 anni). Oggi si registrano 34 decessi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.intoscana.it\/it\/covid-13-341-nuovi-casi\/\" \/>\n<meta property=\"og:site_name\" content=\"intoscana\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/intoscana.it\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-12T14:45:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-13T09:38:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/creaf_prato_vaccini_2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1363\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@intoscana\" \/>\n<meta name=\"twitter:site\" content=\"@intoscana\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.intoscana.it\/it\/covid-13-341-nuovi-casi\/\",\"url\":\"https:\/\/www.intoscana.it\/it\/covid-13-341-nuovi-casi\/\",\"name\":\"Covid, 13.341 nuovi casi su poco pi\u00f9 di 25 mila tamponi - intoscana\",\"isPartOf\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/covid-13-341-nuovi-casi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/covid-13-341-nuovi-casi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/creaf_prato_vaccini_2-scaled.jpg\",\"datePublished\":\"2022-01-12T14:45:10+00:00\",\"dateModified\":\"2022-01-13T09:38:53+00:00\",\"author\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8\"},\"description\":\"L'et\u00e0 media dei 13.341 nuovi positivi odierni \u00e8 di 38 anni circa (21% ha meno di 20 anni). Oggi si registrano 34 decessi\",\"breadcrumb\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/covid-13-341-nuovi-casi\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.intoscana.it\/it\/covid-13-341-nuovi-casi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.intoscana.it\/it\/covid-13-341-nuovi-casi\/#primaryimage\",\"url\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/creaf_prato_vaccini_2-scaled.jpg\",\"contentUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/creaf_prato_vaccini_2-scaled.jpg\",\"width\":2048,\"height\":1363,\"caption\":\"Infermieri e personale sanitario in reparto Covid (Centro Pegaso di Prato)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.intoscana.it\/it\/covid-13-341-nuovi-casi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.intoscana.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Covid, 13.341 nuovi casi su poco pi\u00f9 di 25 mila tamponi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\",\"url\":\"https:\/\/www.intoscana.it\/it\/\",\"name\":\"intoscana\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.intoscana.it\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8\",\"name\":\"Redazione\",\"url\":\"https:\/\/www.intoscana.it\/it\/author\/redazione\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Covid, 13.341 nuovi casi su poco pi\u00f9 di 25 mila tamponi - intoscana","description":"L'et\u00e0 media dei 13.341 nuovi positivi odierni \u00e8 di 38 anni circa (21% ha meno di 20 anni). Oggi si registrano 34 decessi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.intoscana.it\/it\/covid-13-341-nuovi-casi\/","og_locale":"it_IT","og_type":"article","og_title":"Covid, 13.341 nuovi casi su poco pi\u00f9 di 25 mila tamponi","og_description":"L'et\u00e0 media dei 13.341 nuovi positivi odierni \u00e8 di 38 anni circa (21% ha meno di 20 anni). Oggi si registrano 34 decessi","og_url":"https:\/\/www.intoscana.it\/it\/covid-13-341-nuovi-casi\/","og_site_name":"intoscana","article_publisher":"https:\/\/www.facebook.com\/intoscana.it","article_published_time":"2022-01-12T14:45:10+00:00","article_modified_time":"2022-01-13T09:38:53+00:00","og_image":[{"width":2048,"height":1363,"url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/creaf_prato_vaccini_2-scaled.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@intoscana","twitter_site":"@intoscana","twitter_misc":{"Written by":"Redazione","Est. reading time":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.intoscana.it\/it\/covid-13-341-nuovi-casi\/","url":"https:\/\/www.intoscana.it\/it\/covid-13-341-nuovi-casi\/","name":"Covid, 13.341 nuovi casi su poco pi\u00f9 di 25 mila tamponi - intoscana","isPartOf":{"@id":"https:\/\/www.intoscana.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.intoscana.it\/it\/covid-13-341-nuovi-casi\/#primaryimage"},"image":{"@id":"https:\/\/www.intoscana.it\/it\/covid-13-341-nuovi-casi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/creaf_prato_vaccini_2-scaled.jpg","datePublished":"2022-01-12T14:45:10+00:00","dateModified":"2022-01-13T09:38:53+00:00","author":{"@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8"},"description":"L'et\u00e0 media dei 13.341 nuovi positivi odierni \u00e8 di 38 anni circa (21% ha meno di 20 anni). Oggi si registrano 34 decessi","breadcrumb":{"@id":"https:\/\/www.intoscana.it\/it\/covid-13-341-nuovi-casi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.intoscana.it\/it\/covid-13-341-nuovi-casi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.intoscana.it\/it\/covid-13-341-nuovi-casi\/#primaryimage","url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/creaf_prato_vaccini_2-scaled.jpg","contentUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/creaf_prato_vaccini_2-scaled.jpg","width":2048,"height":1363,"caption":"Infermieri e personale sanitario in reparto Covid (Centro Pegaso di Prato)"},{"@type":"BreadcrumbList","@id":"https:\/\/www.intoscana.it\/it\/covid-13-341-nuovi-casi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.intoscana.it\/it\/"},{"@type":"ListItem","position":2,"name":"Covid, 13.341 nuovi casi su poco pi\u00f9 di 25 mila tamponi"}]},{"@type":"WebSite","@id":"https:\/\/www.intoscana.it\/it\/#website","url":"https:\/\/www.intoscana.it\/it\/","name":"intoscana","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intoscana.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8","name":"Redazione","url":"https:\/\/www.intoscana.it\/it\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/206821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/users\/525"}],"replies":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/comments?post=206821"}],"version-history":[{"count":0,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/206821\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media\/194287"}],"wp:attachment":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media?parent=206821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/categories?post=206821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/tags?post=206821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}