{"id":215932,"date":"2022-03-07T08:22:55","date_gmt":"2022-03-07T07:22:55","guid":{"rendered":"https:\/\/www.intoscana.it\/it\/?p=215932"},"modified":"2022-03-07T15:59:31","modified_gmt":"2022-03-07T14:59:31","slug":"un-fenomeno-ancora-sommerso-la-violenza-sulle-donne-anziane","status":"publish","type":"post","link":"https:\/\/www.intoscana.it\/it\/un-fenomeno-ancora-sommerso-la-violenza-sulle-donne-anziane\/","title":{"rendered":"Violenza sulle donne anziane, un fenomeno ancora sommerso"},"content":{"rendered":"<p>L&#8217;ultimo <a href=\"https:\/\/www.intoscana.it\/it\/articolo\/violenza-sulle-donne-in-toscana-121-femminicidi-in-15-anni-sono-anziane-e-straniere\/\" target=\"_blank\" rel=\"noopener\"><strong>Rapporto sulla violenza di genere in Toscana<\/strong><\/a> realizzato dall\u2019<strong>Osservatorio della Regione Toscana<\/strong> che \u00e8 stato presentato a novembre 2021 ha rilevato che <strong>dal 2006 al 2020 sono 121 i femminicidi avvenuti<\/strong> nella nostra regione, parallelamente sono 41 i minori rimasti orfani per questi fatti di sangue. Il 73% di loro era di nazionalit\u00e0 italiana. Quattro le donne uccise per motivi di genere nel 2020.<\/p>\n<p><strong>Il dato che desta maggiore preoccupazione<\/strong> \u00e8 che<strong> in Toscana<\/strong> <strong>\u00e8 elevato il numero di femminicidi di donne anziane<\/strong> (negli ultimi 5 anni il 35,1% del totale erano donne sopra i 75 anni, contro il 16% del livello nazionale) e straniere (32,4% contro il 23,4% del livello nazionale) <strong>rispetto al contesto nazionale.<\/strong><\/p>\n<p>Ne parliamo con la fiorentina <strong>Alessandra Minello ricercatrice in demografia al Dipartimento di scienze statistiche dell&#8217;Universit\u00e0 di Padova.<\/strong><\/p>\n<p>&#8220;Quello che abbiamo notato studiando i <strong>dati forniti dal Ministero dell&#8217;Interno<\/strong>&#8211; <strong>ci ha raccontato Alessandra Minello<\/strong> &#8211; \u00a0\u00e8 che il tasso di omicidi di donne anziane compiuti da partner ed ex partner rimane stabile nel tempo. Mentre negli altri casi il tasso decresce leggermente.<\/p>\n<p>Nel corso della nostra ricerca abbiamo elaborato\u00a0una riflessione rispetto al fatto che <strong>per quanto riguarda le donne anziane non c&#8217;\u00e8 solo una violenza da parte dei partner e ex-partner\u00a0ma anche da parte dei figli<\/strong>.<\/p>\n<p>La violenza \u00e8 in particolar modo acuita dalla <strong>pressione data dalla pandemia e dalla crisi economica,<\/strong> spesso \u00e8 l&#8217;unione delle due cose.<\/p>\n<p>Le donne anziane fanno parte di una generazione che non ha lavorato e in cui<strong> la divisione dei ruoli in casa \u00e8 quella tradizionale<\/strong>, la questione economica e abitativa hanno un ruolo fondamentale.<\/p>\n<p>Spesso nel rapporto delle donne anziane con i figli infatti\u00a0<strong>c&#8217;\u00e8 un&#8217;interdipendenza\u00a0dal punto di vista economico che crea uno squilibrio di potere<\/strong>.<\/p>\n<p>Quello che abbiamo rilevato con i <strong>colloqui ai centri antiviolenza<\/strong> \u00e8 che la violenza in questo caso specifico si scatena <strong>quando ci sono difficolt\u00e0 economiche,<\/strong> una difficolt\u00e0\u00a0lavorativa per i figli per esempio, \u00e8 una miccia che fa esplodere la situazione.&#8221;<\/p>\n<h3>L&#8217;omicidio da parte del partner<\/h3>\n<p>Ci sono poi\u00a0<strong>molti casi di omicidio-suicidio di donne anziane malate<\/strong> da parte del partner che<strong> la stampa fatica a definire &#8220;femminicidi&#8221;.<\/strong><\/p>\n<p>&#8220;La riflessione che stiamo facendo &#8211;<strong> ci ha raccontato Alessandra Minello<\/strong> &#8211; \u00e8 che invece<strong> sotto c&#8217;\u00e8 una componente di genere molto forte<\/strong> che \u00e8 legata a una <strong>divisione tradizionale dei ruoli di cura<\/strong> che nel momento in cui vengono ribaltati sostanzialmente diventano troppo pesanti da sostenere dall&#8217;uomo per cui si arriva nei casi estremi a questo tipo di esito.<\/p>\n<p><strong>L&#8217;uomo non ha la capacit\u00e0<\/strong> di sostenere questo<strong> nuovo equilibrio.<\/strong><\/p>\n<p>Sicuramente <strong>il sommerso, cio\u00e8 il non denunciato \u00e8 sempre difficile da quantificare<\/strong>, spesso se il partner agisce violenza sono i figli che proteggono\u00a0la madre e denunciano al suo posto.<\/p>\n<p>Inoltre spesso <strong>ci sono squilibri che le donne della generazione prima della nostra non riconoscono come violenza<\/strong>. Per esempio<strong> la gestione economica non libera<\/strong>, dare pochi soldi alla moglie, contati\u00a0per fare la spesa, questo \u00e8 gi\u00e0 un tratto non sano della relazione,<strong> nelle coppie pi\u00f9 anziane spesso \u00e8 la norma<\/strong>.&#8221;<\/p>\n<h3>La necessit\u00e0 di protocolli specifici<\/h3>\n<p>&#8220;Per i casi di violenza sulle donne anziane &#8211; <strong>prosegue la studiosa Alessandra Minello<\/strong>&#8211; <strong>non esistono ad oggi protocolli specifici<\/strong>. Nei centri antiviolenza cio\u00e8 viene proposto sostanzialmente\u00a0lo stesso protocollo che viene proposto alle altre donne che prevede per esempio incontri di gruppo.<\/p>\n<p><strong>Per il segmento di popolazione delle donne anziane<\/strong> questo tipo di approccio \u00e8 difficile da contemplare. C&#8217;\u00e8 la tendenza ad essere <strong>meno propense ai percorsi psicologici<\/strong> o alla condivisione e c&#8217;\u00e8 maggiore intimit\u00e0 per quanto riguarda la relazione familiare.<\/p>\n<p>Ad una donna giovane con figli puoi proporre di cambiare luogo in cui vive, <strong>con le donne anziane \u00e8 molto pi\u00f9 difficile<\/strong> perch\u00e8 toglierle dall&#8217;ambiente abituale in cui vivono e <strong>pensare di ricollocarle\u00a0altrove \u00e8 un percorso molto pi\u00f9 complicato.<\/strong><\/p>\n<p>Inizia ad esserci attenzione su questo tema ma<strong> c&#8217;\u00e8 poca raccolta di dati e informazioni specifiche<\/strong> e non c&#8217;\u00e8 ancora una costruzione diffusa per i protocolli di trattamento di questo specifico tipo di violenza che ha appunto delle componenti peculiari.&#8221;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Intervista alla studiosa fiorentina Alessandra Minello ricercatrice in demografia al Dipartimento di scienze statistiche dell&#8217;Universit\u00e0 di Padova<\/p>\n","protected":false},"author":518,"featured_media":215696,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[494],"tags":[385,411,5676,4615,4611],"class_list":["post-215932","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","tag-8-marzo","tag-donne","tag-giornata-internazionale-della-donna","tag-violenza-di-genere","tag-violenza-sulle-donne"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v25.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Violenza sulle donne anziane, un fenomeno ancora sommerso - intoscana<\/title>\n<meta name=\"description\" content=\"Intervista alla studiosa Alessandra Minello ricercatrice in demografia al Dipartimento di scienze statistiche dell&#039;Universit\u00e0 di Padova\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.intoscana.it\/it\/un-fenomeno-ancora-sommerso-la-violenza-sulle-donne-anziane\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Violenza sulle donne anziane, un fenomeno ancora sommerso\" \/>\n<meta property=\"og:description\" content=\"Intervista alla studiosa Alessandra Minello ricercatrice in demografia al Dipartimento di scienze statistiche dell&#039;Universit\u00e0 di Padova\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.intoscana.it\/it\/un-fenomeno-ancora-sommerso-la-violenza-sulle-donne-anziane\/\" \/>\n<meta property=\"og:site_name\" content=\"intoscana\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/intoscana.it\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-07T07:22:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-07T14:59:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/violenza-sugli-anziani-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Costanza Baldini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@intoscana\" \/>\n<meta name=\"twitter:site\" content=\"@intoscana\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Costanza Baldini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.intoscana.it\/it\/un-fenomeno-ancora-sommerso-la-violenza-sulle-donne-anziane\/\",\"url\":\"https:\/\/www.intoscana.it\/it\/un-fenomeno-ancora-sommerso-la-violenza-sulle-donne-anziane\/\",\"name\":\"Violenza sulle donne anziane, un fenomeno ancora sommerso - intoscana\",\"isPartOf\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/un-fenomeno-ancora-sommerso-la-violenza-sulle-donne-anziane\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/un-fenomeno-ancora-sommerso-la-violenza-sulle-donne-anziane\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/violenza-sugli-anziani-scaled.jpg\",\"datePublished\":\"2022-03-07T07:22:55+00:00\",\"dateModified\":\"2022-03-07T14:59:31+00:00\",\"author\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/d469f35f09739bdf00bf5dd3f0647a82\"},\"description\":\"Intervista alla studiosa Alessandra Minello ricercatrice in demografia al Dipartimento di scienze statistiche dell'Universit\u00e0 di Padova\",\"breadcrumb\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/un-fenomeno-ancora-sommerso-la-violenza-sulle-donne-anziane\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.intoscana.it\/it\/un-fenomeno-ancora-sommerso-la-violenza-sulle-donne-anziane\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.intoscana.it\/it\/un-fenomeno-ancora-sommerso-la-violenza-sulle-donne-anziane\/#primaryimage\",\"url\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/violenza-sugli-anziani-scaled.jpg\",\"contentUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/violenza-sugli-anziani-scaled.jpg\",\"width\":2048,\"height\":1365,\"caption\":\"violenza sugli anziani\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.intoscana.it\/it\/un-fenomeno-ancora-sommerso-la-violenza-sulle-donne-anziane\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.intoscana.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Violenza sulle donne anziane, un fenomeno ancora sommerso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\",\"url\":\"https:\/\/www.intoscana.it\/it\/\",\"name\":\"intoscana\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.intoscana.it\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/d469f35f09739bdf00bf5dd3f0647a82\",\"name\":\"Costanza Baldini\",\"url\":\"https:\/\/www.intoscana.it\/it\/author\/costanza-baldini\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Violenza sulle donne anziane, un fenomeno ancora sommerso - intoscana","description":"Intervista alla studiosa Alessandra Minello ricercatrice in demografia al Dipartimento di scienze statistiche dell'Universit\u00e0 di Padova","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.intoscana.it\/it\/un-fenomeno-ancora-sommerso-la-violenza-sulle-donne-anziane\/","og_locale":"it_IT","og_type":"article","og_title":"Violenza sulle donne anziane, un fenomeno ancora sommerso","og_description":"Intervista alla studiosa Alessandra Minello ricercatrice in demografia al Dipartimento di scienze statistiche dell'Universit\u00e0 di Padova","og_url":"https:\/\/www.intoscana.it\/it\/un-fenomeno-ancora-sommerso-la-violenza-sulle-donne-anziane\/","og_site_name":"intoscana","article_publisher":"https:\/\/www.facebook.com\/intoscana.it","article_published_time":"2022-03-07T07:22:55+00:00","article_modified_time":"2022-03-07T14:59:31+00:00","og_image":[{"width":2048,"height":1365,"url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/violenza-sugli-anziani-scaled.jpg","type":"image\/jpeg"}],"author":"Costanza Baldini","twitter_card":"summary_large_image","twitter_creator":"@intoscana","twitter_site":"@intoscana","twitter_misc":{"Written by":"Costanza Baldini","Est. reading time":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.intoscana.it\/it\/un-fenomeno-ancora-sommerso-la-violenza-sulle-donne-anziane\/","url":"https:\/\/www.intoscana.it\/it\/un-fenomeno-ancora-sommerso-la-violenza-sulle-donne-anziane\/","name":"Violenza sulle donne anziane, un fenomeno ancora sommerso - intoscana","isPartOf":{"@id":"https:\/\/www.intoscana.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.intoscana.it\/it\/un-fenomeno-ancora-sommerso-la-violenza-sulle-donne-anziane\/#primaryimage"},"image":{"@id":"https:\/\/www.intoscana.it\/it\/un-fenomeno-ancora-sommerso-la-violenza-sulle-donne-anziane\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/violenza-sugli-anziani-scaled.jpg","datePublished":"2022-03-07T07:22:55+00:00","dateModified":"2022-03-07T14:59:31+00:00","author":{"@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/d469f35f09739bdf00bf5dd3f0647a82"},"description":"Intervista alla studiosa Alessandra Minello ricercatrice in demografia al Dipartimento di scienze statistiche dell'Universit\u00e0 di Padova","breadcrumb":{"@id":"https:\/\/www.intoscana.it\/it\/un-fenomeno-ancora-sommerso-la-violenza-sulle-donne-anziane\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.intoscana.it\/it\/un-fenomeno-ancora-sommerso-la-violenza-sulle-donne-anziane\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.intoscana.it\/it\/un-fenomeno-ancora-sommerso-la-violenza-sulle-donne-anziane\/#primaryimage","url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/violenza-sugli-anziani-scaled.jpg","contentUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/violenza-sugli-anziani-scaled.jpg","width":2048,"height":1365,"caption":"violenza sugli anziani"},{"@type":"BreadcrumbList","@id":"https:\/\/www.intoscana.it\/it\/un-fenomeno-ancora-sommerso-la-violenza-sulle-donne-anziane\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.intoscana.it\/it\/"},{"@type":"ListItem","position":2,"name":"Violenza sulle donne anziane, un fenomeno ancora sommerso"}]},{"@type":"WebSite","@id":"https:\/\/www.intoscana.it\/it\/#website","url":"https:\/\/www.intoscana.it\/it\/","name":"intoscana","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intoscana.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/d469f35f09739bdf00bf5dd3f0647a82","name":"Costanza Baldini","url":"https:\/\/www.intoscana.it\/it\/author\/costanza-baldini\/"}]}},"_links":{"self":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/215932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/users\/518"}],"replies":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/comments?post=215932"}],"version-history":[{"count":0,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/215932\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media\/215696"}],"wp:attachment":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media?parent=215932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/categories?post=215932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/tags?post=215932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}