{"id":217525,"date":"2022-03-14T14:00:53","date_gmt":"2022-03-14T13:00:53","guid":{"rendered":"https:\/\/www.intoscana.it\/it\/?p=217525"},"modified":"2022-03-14T14:56:55","modified_gmt":"2022-03-14T13:56:55","slug":"ucraina-trasporti-gratuiti-profughi-in-arrivo-in-italia","status":"publish","type":"post","link":"https:\/\/www.intoscana.it\/it\/ucraina-trasporti-gratuiti-profughi-in-arrivo-in-italia\/","title":{"rendered":"Ucraina, trasporti gratuiti per i profughi in arrivo in Italia"},"content":{"rendered":"<p>Ucraina: firmata l&#8217;ordinanza sulla <strong>gratuit\u00e0 dei trasporti<\/strong> per i cittadini <strong>ucraini in Italia<\/strong>: potranno viaggiare gratuitamente <strong>entro 5 giorni dal loro arrivo<\/strong> nel Paese.<\/p>\n<p>A firmare l&#8217;ordinanza il Capo del Dipartimento della Protezione civile, <strong>Fabrizio Curcio<\/strong>: con questo atto dispone importanti <strong>agevolazioni in materia di trasporto<\/strong> per la popolazione in fuga dalla guerra. L\u2019ordinanza di protezione civile ha lo scopo di <strong>garantire ai cittadini<\/strong> provenienti dall\u2019Ucraina di viaggiare gratuitamente sul nostro territorio, entro 5 giorni massimo dall\u2019ingresso in Italia, <mark>per raggiungere il primo luogo di destinazione o di accoglienza<\/mark>.<\/p>\n<p>Il provvedimento comprende la gratuit\u00e0 del trasporto sui treni della societ\u00e0 <strong>Trenitalia (Gruppo FS)<\/strong> che effettuano servizio di <strong>Intercity, Eurocity e Regionali<\/strong>, sui <strong>servizi marittimi<\/strong> e sulla <strong>rete autostradale<\/strong>.<\/p>\n<p>&#8220;<em>La fattiva collaborazione con il Ministero delle Infrastrutture e della Mobilit\u00e0 Sostenibili, Trenitalia e Aiscat ha portato a questa importante misura che rappresenta un ulteriore tassello nel piano di accoglienza della popolazione in fuga dalla guerra<\/em> \u2013 ha detto il Capo Dipartimento, <strong>Fabrizio Curcio<\/strong> \u2013. <em>Siamo di fronte a uno scenario delicato e complesso che il nostro Paese deve affrontare in modo sinergico&#8221;<\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Potranno viaggiare entro i primi cinque giorni sui convogli della societ\u00e0 Trenitalia-Gruppo FS, sui servizi marittimi e sulla rete autostradale<\/p>\n","protected":false},"author":525,"featured_media":145409,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[494],"tags":[1577,4295],"class_list":["post-217525","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","tag-muoversi-in-toscana","tag-trasporto-pubblico"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v25.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ucraina, trasporti gratuiti per i profughi in arrivo in Italia - intoscana<\/title>\n<meta name=\"description\" content=\"Potranno viaggiare entro i primi 5 giorni sui convogli della societ\u00e0 Trenitalia-Gruppo FS, sui servizi marittimi e sulla rete autostradale\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.intoscana.it\/it\/ucraina-trasporti-gratuiti-profughi-in-arrivo-in-italia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ucraina, trasporti gratuiti per i profughi in arrivo in Italia\" \/>\n<meta property=\"og:description\" content=\"Potranno viaggiare entro i primi 5 giorni sui convogli della societ\u00e0 Trenitalia-Gruppo FS, sui servizi marittimi e sulla rete autostradale\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.intoscana.it\/it\/ucraina-trasporti-gratuiti-profughi-in-arrivo-in-italia\/\" \/>\n<meta property=\"og:site_name\" content=\"intoscana\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/intoscana.it\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-14T13:00:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-14T13:56:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/whatsapp-image-2020-05-29-at-13.51.35.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@intoscana\" \/>\n<meta name=\"twitter:site\" content=\"@intoscana\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.intoscana.it\/it\/ucraina-trasporti-gratuiti-profughi-in-arrivo-in-italia\/\",\"url\":\"https:\/\/www.intoscana.it\/it\/ucraina-trasporti-gratuiti-profughi-in-arrivo-in-italia\/\",\"name\":\"Ucraina, trasporti gratuiti per i profughi in arrivo in Italia - intoscana\",\"isPartOf\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/ucraina-trasporti-gratuiti-profughi-in-arrivo-in-italia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/ucraina-trasporti-gratuiti-profughi-in-arrivo-in-italia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/whatsapp-image-2020-05-29-at-13.51.35.jpeg\",\"datePublished\":\"2022-03-14T13:00:53+00:00\",\"dateModified\":\"2022-03-14T13:56:55+00:00\",\"author\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8\"},\"description\":\"Potranno viaggiare entro i primi 5 giorni sui convogli della societ\u00e0 Trenitalia-Gruppo FS, sui servizi marittimi e sulla rete autostradale\",\"breadcrumb\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/ucraina-trasporti-gratuiti-profughi-in-arrivo-in-italia\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.intoscana.it\/it\/ucraina-trasporti-gratuiti-profughi-in-arrivo-in-italia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.intoscana.it\/it\/ucraina-trasporti-gratuiti-profughi-in-arrivo-in-italia\/#primaryimage\",\"url\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/whatsapp-image-2020-05-29-at-13.51.35.jpeg\",\"contentUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/whatsapp-image-2020-05-29-at-13.51.35.jpeg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.intoscana.it\/it\/ucraina-trasporti-gratuiti-profughi-in-arrivo-in-italia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.intoscana.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ucraina, trasporti gratuiti per i profughi in arrivo in Italia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\",\"url\":\"https:\/\/www.intoscana.it\/it\/\",\"name\":\"intoscana\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.intoscana.it\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8\",\"name\":\"Redazione\",\"url\":\"https:\/\/www.intoscana.it\/it\/author\/redazione\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ucraina, trasporti gratuiti per i profughi in arrivo in Italia - intoscana","description":"Potranno viaggiare entro i primi 5 giorni sui convogli della societ\u00e0 Trenitalia-Gruppo FS, sui servizi marittimi e sulla rete autostradale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.intoscana.it\/it\/ucraina-trasporti-gratuiti-profughi-in-arrivo-in-italia\/","og_locale":"it_IT","og_type":"article","og_title":"Ucraina, trasporti gratuiti per i profughi in arrivo in Italia","og_description":"Potranno viaggiare entro i primi 5 giorni sui convogli della societ\u00e0 Trenitalia-Gruppo FS, sui servizi marittimi e sulla rete autostradale","og_url":"https:\/\/www.intoscana.it\/it\/ucraina-trasporti-gratuiti-profughi-in-arrivo-in-italia\/","og_site_name":"intoscana","article_publisher":"https:\/\/www.facebook.com\/intoscana.it","article_published_time":"2022-03-14T13:00:53+00:00","article_modified_time":"2022-03-14T13:56:55+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/whatsapp-image-2020-05-29-at-13.51.35.jpeg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@intoscana","twitter_site":"@intoscana","twitter_misc":{"Written by":"Redazione","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.intoscana.it\/it\/ucraina-trasporti-gratuiti-profughi-in-arrivo-in-italia\/","url":"https:\/\/www.intoscana.it\/it\/ucraina-trasporti-gratuiti-profughi-in-arrivo-in-italia\/","name":"Ucraina, trasporti gratuiti per i profughi in arrivo in Italia - intoscana","isPartOf":{"@id":"https:\/\/www.intoscana.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.intoscana.it\/it\/ucraina-trasporti-gratuiti-profughi-in-arrivo-in-italia\/#primaryimage"},"image":{"@id":"https:\/\/www.intoscana.it\/it\/ucraina-trasporti-gratuiti-profughi-in-arrivo-in-italia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/whatsapp-image-2020-05-29-at-13.51.35.jpeg","datePublished":"2022-03-14T13:00:53+00:00","dateModified":"2022-03-14T13:56:55+00:00","author":{"@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8"},"description":"Potranno viaggiare entro i primi 5 giorni sui convogli della societ\u00e0 Trenitalia-Gruppo FS, sui servizi marittimi e sulla rete autostradale","breadcrumb":{"@id":"https:\/\/www.intoscana.it\/it\/ucraina-trasporti-gratuiti-profughi-in-arrivo-in-italia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.intoscana.it\/it\/ucraina-trasporti-gratuiti-profughi-in-arrivo-in-italia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.intoscana.it\/it\/ucraina-trasporti-gratuiti-profughi-in-arrivo-in-italia\/#primaryimage","url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/whatsapp-image-2020-05-29-at-13.51.35.jpeg","contentUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/whatsapp-image-2020-05-29-at-13.51.35.jpeg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.intoscana.it\/it\/ucraina-trasporti-gratuiti-profughi-in-arrivo-in-italia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.intoscana.it\/it\/"},{"@type":"ListItem","position":2,"name":"Ucraina, trasporti gratuiti per i profughi in arrivo in Italia"}]},{"@type":"WebSite","@id":"https:\/\/www.intoscana.it\/it\/#website","url":"https:\/\/www.intoscana.it\/it\/","name":"intoscana","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intoscana.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8","name":"Redazione","url":"https:\/\/www.intoscana.it\/it\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/217525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/users\/525"}],"replies":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/comments?post=217525"}],"version-history":[{"count":0,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/217525\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media\/145409"}],"wp:attachment":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media?parent=217525"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/categories?post=217525"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/tags?post=217525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}