{"id":220107,"date":"2022-03-25T17:12:56","date_gmt":"2022-03-25T16:12:56","guid":{"rendered":"https:\/\/www.intoscana.it\/it\/?p=220107"},"modified":"2022-03-25T17:12:56","modified_gmt":"2022-03-25T16:12:56","slug":"la-ministra-bonetti-incontra-gli-orfani-ucraini-accolti-allistituto-degli-innocenti","status":"publish","type":"post","link":"https:\/\/www.intoscana.it\/it\/la-ministra-bonetti-incontra-gli-orfani-ucraini-accolti-allistituto-degli-innocenti\/","title":{"rendered":"La ministra Bonetti incontra gli orfani ucraini accolti all&#8217;Istituto degli Innocenti"},"content":{"rendered":"<p>Ha incontrato i <strong>21 bambini ucraini<\/strong> che sono stati portati in salvo dal conflitto che sta sconvolgendo il loro paese e sono stati ospitati per la prima accoglienza a Firenze. La ministra per le Pari opportunit\u00e0 e la Famiglia, <strong>Elena Bonetti<\/strong>, questa mattina ha fatto visita all<strong>&#8216;Istituto degli Innocenti<\/strong>. <mark>A darle il benvenuto, la presidente dell&#8217;Istituto degli Innocenti, Maria Grazia Giuffrida, il presidente della Regione Toscana, Eugenio Giani, l&#8217;assessore al Sociale Comune di Firenze, Sara Funaro, il giudice ordinario Tribunale minorenni di Firenze, Silvia Chiaranti, la vice prefetto vicario della Prefettura di Firenze, Grazia La Fauci, e la direttrice programmi Italia-Europa di Save the Children, Rafaella Milano.<\/mark><\/p>\n<figure id=\"post-220099 media-220099\" class=\"align-none\"><img decoding=\"async\" src=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/PRT_1759-scaled.jpg\" alt=\"\" \/><\/figure>\n<p>I<a href=\"https:\/\/www.intoscana.it\/it\/articolo\/bambini-orfani-kiev-istituto-innocenti\/\"> 21 bambini, di et\u00e0 compresa fra i 3 e i 17 anni<\/a> e che vivevano in una casa famiglia nei dintorni di <strong>Kiev<\/strong>, dovevano essere messi in salvo dalle bombe fuggendo a Leopoli. Da qui \u00e8 partita una richiesta di aiuto accolta da Save the Children e dal Consiglio Italiano per i Rifugiati (CIR) che hanno organizzato un trasferimento in sicurezza di piccoli profughi dal confine polacco con l\u2019Ucraina all\u2019Italia, in stretto coordinamento con il Dipartimento nazionale della Protezione Civile, i ministeri competenti e le ambasciate.<\/p>\n<p>Dopo un contatto attivato con Save the children dal Dipartimento per le politiche della famiglia, promosso dalla Ministra per le pari opportunit\u00e0 e la famiglia, <mark>l&#8217;Istituto degli Innocenti ha dato subito la propria disponibilit\u00e0 per garantire una prima accoglienza straordinaria e temporanea destinando alla loro ospitalit\u00e0 spazi originariamente dedicati a altre attivit\u00e0 e che sono stati riconvertiti in due giorni all\u2019ospitalit\u00e0 del gruppo, grazie anche al sostegno economico di Fondazione Cr Firenze.<\/mark><\/p>\n<figure id=\"post-220125 media-220125\" class=\"align-none\"><img decoding=\"async\" src=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/Bonetti-2.jpeg\" alt=\"\" \/><\/figure>\n<div class=\"titleimg\" style=\"text-align: center;\"><em>La ministra Bonetti<\/em><\/div>\n<p><em>\u201cSono molto felice di essere qui oggi: questi bambini<\/em> &#8211; dice la ministra alle Pari Opportunit\u00e0 e alla Famiglia Elena Bonetti &#8211; <em>hanno diritto a un futuro e devono sentire che l\u2019Europa \u00e8 la loro casa. Il modello che abbiamo sperimentato\u00a0 tra Save the Children e l\u2019istituto degli Innocenti di Firenze rappresenta <mark>un primo modello per costruire un\u2019accoglienza diffusa, che punta a creare rete tra le istituzioni, i livelli territoriali e le associazioni del terzo settore. \u00c8 modello di accoglienza che diventer\u00e0 strutturale<\/mark> e per il quale il Dipartimento per la Protezione civile e i ministeri coinvolti nel tavolo di coordinamento stanno predisponendo una piattaforma che faciliti le comunicazioni e la collaborazione tra i soggetti interessati e garantisca la massima sicurezza e il rispetto dei diritti di questi bambini\u201d.<\/em><\/p>\n<p>Ad oggi i minori profughi in Toscana, come spiega il presidente della Regione <strong>Eugenio Giani<\/strong>, <em>&#8220;sono 2581. Una particolare emozione \u00e8 vedere questi bambini e ragazzi estremamente protetti qui all\u2019Istituto degli Innocenti e vederli ora sereni e con il sorriso mi riempie di gioia e dimostra che qui l\u2019accoglienza \u00e8 ai massimi livelli\u201d.<\/em> \u201c<em>Siamo onorati della visita del ministro Elena Bonetti, che conferma l&#8217;attenzione del governo verso la cura, l&#8217;accoglienza, il benessere dei bambini e dei ragazzi, soprattutto quelli in situazione di vulnerabilit\u00e0 e fragilit\u00e0 &#8211; <\/em>afferma la presidente degli Innocenti <strong>Maria Grazia Giuffrida &#8211; <\/strong><em>Da 600 anni siamo dalla parte dei bambini, era naturale per noi essere presenti e dare il nostro contributo anche questa volta\u201d.<\/em><\/p>\n<p><em>\u201cSiamo\u00a0al lavoro con il Tribunale dei minori\u00a0per capire quali sono le necessit\u00e0 dei bambini accolti<\/em> &#8211; ha detto l&#8217;assessore a Welfare ed Educazione <strong>Sara Funaro<\/strong> &#8211; <em>e i percorsi migliori di assistenza e inclusione<\/em>. <em>Siamo tutti al lavoro giorno e notte, Istituzioni, Terzo settore e volontariato, ognuno per la propria competenza<\/em>\u00a0<em>per far s\u00ec che i piccoli ucraini che arrivano in citt\u00e0 siano seguiti per superare la difficile situazione che hanno vissuto nel Paese d&#8217;origine. Hanno diritto a ritrovare la normalit\u00e0 e il nostro compito \u00e8 metterli in condizione di ritrovarla\u201d.<\/em><\/p>\n<p>Per i bambini sono stati subito attivati i necessari\u00a0percorsi di tutela e assistenza, in raccordo con il Tribunale per i minorenni di Firenze, il Comune di Firenze e l\u2019Azienda USL Toscana Centr<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sono 21 i minori non accompagnati scappati da Kiev che oggi vivono a Firenze. &#8220;Un modello di accoglienza che diventer\u00e0 strutturale&#8221;<\/p>\n","protected":false},"author":525,"featured_media":220101,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[494],"tags":[158,6427,6264],"class_list":["post-220107","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","tag-eugenio-giani","tag-guerra-ucraina","tag-istituto-deglinnocenti"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v25.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La ministra Bonetti incontra gli orfani ucraini all&#039;Istituto degli Innocenti<\/title>\n<meta name=\"description\" content=\"Sono 21 i minori non accompagnati scappati da Kiev che oggi vivono a Firenze. &quot;Un modello di accoglienza che diventer\u00e0 strutturale&quot;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.intoscana.it\/it\/la-ministra-bonetti-incontra-gli-orfani-ucraini-accolti-allistituto-degli-innocenti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La ministra Bonetti incontra gli orfani ucraini accolti all&#039;Istituto degli Innocenti\" \/>\n<meta property=\"og:description\" content=\"Sono 21 i minori non accompagnati scappati da Kiev che oggi vivono a Firenze. &quot;Un modello di accoglienza che diventer\u00e0 strutturale&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.intoscana.it\/it\/la-ministra-bonetti-incontra-gli-orfani-ucraini-accolti-allistituto-degli-innocenti\/\" \/>\n<meta property=\"og:site_name\" content=\"intoscana\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/intoscana.it\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-25T16:12:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/PRT_1737-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@intoscana\" \/>\n<meta name=\"twitter:site\" content=\"@intoscana\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.intoscana.it\/it\/la-ministra-bonetti-incontra-gli-orfani-ucraini-accolti-allistituto-degli-innocenti\/\",\"url\":\"https:\/\/www.intoscana.it\/it\/la-ministra-bonetti-incontra-gli-orfani-ucraini-accolti-allistituto-degli-innocenti\/\",\"name\":\"La ministra Bonetti incontra gli orfani ucraini all'Istituto degli Innocenti\",\"isPartOf\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/la-ministra-bonetti-incontra-gli-orfani-ucraini-accolti-allistituto-degli-innocenti\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/la-ministra-bonetti-incontra-gli-orfani-ucraini-accolti-allistituto-degli-innocenti\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/PRT_1737-scaled.jpg\",\"datePublished\":\"2022-03-25T16:12:56+00:00\",\"author\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8\"},\"description\":\"Sono 21 i minori non accompagnati scappati da Kiev che oggi vivono a Firenze. \\\"Un modello di accoglienza che diventer\u00e0 strutturale\\\"\",\"breadcrumb\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/la-ministra-bonetti-incontra-gli-orfani-ucraini-accolti-allistituto-degli-innocenti\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.intoscana.it\/it\/la-ministra-bonetti-incontra-gli-orfani-ucraini-accolti-allistituto-degli-innocenti\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.intoscana.it\/it\/la-ministra-bonetti-incontra-gli-orfani-ucraini-accolti-allistituto-degli-innocenti\/#primaryimage\",\"url\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/PRT_1737-scaled.jpg\",\"contentUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/PRT_1737-scaled.jpg\",\"width\":2048,\"height\":1365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.intoscana.it\/it\/la-ministra-bonetti-incontra-gli-orfani-ucraini-accolti-allistituto-degli-innocenti\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.intoscana.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La ministra Bonetti incontra gli orfani ucraini accolti all&#8217;Istituto degli Innocenti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\",\"url\":\"https:\/\/www.intoscana.it\/it\/\",\"name\":\"intoscana\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.intoscana.it\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8\",\"name\":\"Redazione\",\"url\":\"https:\/\/www.intoscana.it\/it\/author\/redazione\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La ministra Bonetti incontra gli orfani ucraini all'Istituto degli Innocenti","description":"Sono 21 i minori non accompagnati scappati da Kiev che oggi vivono a Firenze. \"Un modello di accoglienza che diventer\u00e0 strutturale\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.intoscana.it\/it\/la-ministra-bonetti-incontra-gli-orfani-ucraini-accolti-allistituto-degli-innocenti\/","og_locale":"it_IT","og_type":"article","og_title":"La ministra Bonetti incontra gli orfani ucraini accolti all'Istituto degli Innocenti","og_description":"Sono 21 i minori non accompagnati scappati da Kiev che oggi vivono a Firenze. \"Un modello di accoglienza che diventer\u00e0 strutturale\"","og_url":"https:\/\/www.intoscana.it\/it\/la-ministra-bonetti-incontra-gli-orfani-ucraini-accolti-allistituto-degli-innocenti\/","og_site_name":"intoscana","article_publisher":"https:\/\/www.facebook.com\/intoscana.it","article_published_time":"2022-03-25T16:12:56+00:00","og_image":[{"width":2048,"height":1365,"url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/PRT_1737-scaled.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@intoscana","twitter_site":"@intoscana","twitter_misc":{"Written by":"Redazione","Est. reading time":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.intoscana.it\/it\/la-ministra-bonetti-incontra-gli-orfani-ucraini-accolti-allistituto-degli-innocenti\/","url":"https:\/\/www.intoscana.it\/it\/la-ministra-bonetti-incontra-gli-orfani-ucraini-accolti-allistituto-degli-innocenti\/","name":"La ministra Bonetti incontra gli orfani ucraini all'Istituto degli Innocenti","isPartOf":{"@id":"https:\/\/www.intoscana.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.intoscana.it\/it\/la-ministra-bonetti-incontra-gli-orfani-ucraini-accolti-allistituto-degli-innocenti\/#primaryimage"},"image":{"@id":"https:\/\/www.intoscana.it\/it\/la-ministra-bonetti-incontra-gli-orfani-ucraini-accolti-allistituto-degli-innocenti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/PRT_1737-scaled.jpg","datePublished":"2022-03-25T16:12:56+00:00","author":{"@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8"},"description":"Sono 21 i minori non accompagnati scappati da Kiev che oggi vivono a Firenze. \"Un modello di accoglienza che diventer\u00e0 strutturale\"","breadcrumb":{"@id":"https:\/\/www.intoscana.it\/it\/la-ministra-bonetti-incontra-gli-orfani-ucraini-accolti-allistituto-degli-innocenti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.intoscana.it\/it\/la-ministra-bonetti-incontra-gli-orfani-ucraini-accolti-allistituto-degli-innocenti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.intoscana.it\/it\/la-ministra-bonetti-incontra-gli-orfani-ucraini-accolti-allistituto-degli-innocenti\/#primaryimage","url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/PRT_1737-scaled.jpg","contentUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/PRT_1737-scaled.jpg","width":2048,"height":1365},{"@type":"BreadcrumbList","@id":"https:\/\/www.intoscana.it\/it\/la-ministra-bonetti-incontra-gli-orfani-ucraini-accolti-allistituto-degli-innocenti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.intoscana.it\/it\/"},{"@type":"ListItem","position":2,"name":"La ministra Bonetti incontra gli orfani ucraini accolti all&#8217;Istituto degli Innocenti"}]},{"@type":"WebSite","@id":"https:\/\/www.intoscana.it\/it\/#website","url":"https:\/\/www.intoscana.it\/it\/","name":"intoscana","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intoscana.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8","name":"Redazione","url":"https:\/\/www.intoscana.it\/it\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/220107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/users\/525"}],"replies":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/comments?post=220107"}],"version-history":[{"count":0,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/220107\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media\/220101"}],"wp:attachment":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media?parent=220107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/categories?post=220107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/tags?post=220107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}