{"id":220951,"date":"2022-03-30T15:37:50","date_gmt":"2022-03-30T13:37:50","guid":{"rendered":"https:\/\/www.intoscana.it\/it\/?p=220951"},"modified":"2022-03-30T17:44:09","modified_gmt":"2022-03-30T15:44:09","slug":"patto-per-lo-sviluppo-regione-unioncamere","status":"publish","type":"post","link":"https:\/\/www.intoscana.it\/it\/patto-per-lo-sviluppo-regione-unioncamere\/","title":{"rendered":"Un patto per lo sviluppo: Regione e Unioncamere insieme per rilanciare il Paese"},"content":{"rendered":"<p>L&#8217;internazionalizzazione del sistema produttivo e la valorizzazione del made in Tuscany e del marchio \u201cValore Toscana\u201d, politiche attive per favorire l\u2019occupazione giovanile, la formazione e l\u2019apprendimento permanente. Sono questi alcuni dei punti contenuti nell&#8217;accordo sottoscritto da Regione e Unioncamere Toscana. <mark>Un sostegno coordinato, ognuna con le proprie competenze e specificit\u00e0, di un tessuto economico regionale che, pur in mezzo a molteplici difficolt\u00e0, ha le capacit\u00e0 per crescere e competere su tutti i mercati <\/mark>.<\/p>\n<p>L&#8217;accordo avr\u00e0 durata triennale, una sorta di \u201c<em>alleanza per lo sviluppo<\/em>\u201d, con l\u2019obiettivo di coordinare le rispettive pianificazioni.\u00a0Regione e Uniocamere Toscana non sono nuove a intese di queste tipo e il protocollo appena siglato, illustrato <strong>dal presidente della Toscana Eugenio Giani<\/strong> e del <strong>presidente di Unioncamere Massimo Guasconi<\/strong>, si inserisce nel solco di una collaborazione consolidata.<\/p>\n<p>\u201cFare squadra e coordinarsi, per ottimizzare al meglio l\u2019uso di risorse ed esperienze, \u00e8 da sempre il modo pi\u00f9 virtuoso in cui gli enti pubblici possono operare \u2013 <strong>ha detto il presidente della Toscana, Eugenio Giani<\/strong> &#8211; . Lo diventa ancor di pi\u00f9 in una fase come questa di rilancio dell\u2019economia, dopo una crisi alle spalle (quella innescata dalla pandemia) e un\u2019altra in corso (conseguente all\u2019aumento dei costi energetici), con risorse straordinarie adesso a disposizione, ma che \u00a0non vanno sprecate, e un pacchetto di investimenti e riforme legate al Pnrr\u201d. \u201cCollaboreremo \u2013 aggiunge \u2013 con l\u2019obiettivo comune di far crescere e diventare ancora pi\u00f9 competitive le nostre imprese\u201d.<\/p>\n<p>&#8220;L&#8217;accordo sottoscritto &#8211;<strong> ha dichiarato il presidente di Unioncamere Toscana Massimo Guasconi<\/strong> &#8211; punta ad offrire maggiori occasioni di sviluppo alle imprese toscane attraverso un coordinamento operativo delle attivit\u00e0 di promozione economica e una puntuale azione informativa sui bandi e le opportunit\u00e0 del Pnrr\u201d. \u201cRingrazio il presidente Giani \u2013 prosegue &#8211; per l&#8217;attenzione e la disponibilit\u00e0 dimostrata e ringrazio il sistema camerale toscano per l&#8217;impegno\u201d. Poi alcuni numeri: \u201cLa nostra economia regionale \u2013 ricorda- , che conta 446 mila imprese e nel 2021 ha visto crescere Pil e export rispettivamente \u00a0del 6,5 e del 16,8 per cento, \u00e8 pienamente in grado di crescere e competere su tutti i mercati, nonostante le molteplici difficolt\u00e0 causate prima dalla pandemia e adesso dalla crisi energetica e dalla contrazione delle relazioni commerciali\u00a0\u00a0innescate dalla guerra\u201d. \u00a0\u201cLa collaborazione tra istituzioni \u2013 conclude &#8211; non pu\u00f2 che favorire e consolidare questa forza\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una collaborazione per favorire e consolidare le rispettive panificazioni per ottimizzare l\u2019uso di risorse ed esperienze. Il presidente della Regione Eugenio Giani: &#8220;L&#8217;obiettivo comune \u00e8 far crescere e diventare ancora pi\u00f9 competitive le nostre imprese\u201d<\/p>\n","protected":false},"author":525,"featured_media":95460,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[494],"tags":[211,267,260],"class_list":["post-220951","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","tag-economia","tag-imprese","tag-lavoro"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v25.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un patto per lo sviluppo: siglato l&#039;accordo tra Regione e Unincamere<\/title>\n<meta name=\"description\" content=\"Il patto avr\u00e0 durata triennale. Il presidente della Regione Giani: &quot;L&#039;obiettivo \u00e8 far diventare ancora pi\u00f9 competitive le nostre imprese\u201d\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.intoscana.it\/it\/patto-per-lo-sviluppo-regione-unioncamere\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un patto per lo sviluppo: Regione e Unioncamere insieme per rilanciare il Paese\" \/>\n<meta property=\"og:description\" content=\"Il patto avr\u00e0 durata triennale. Il presidente della Regione Giani: &quot;L&#039;obiettivo \u00e8 far diventare ancora pi\u00f9 competitive le nostre imprese\u201d\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.intoscana.it\/it\/patto-per-lo-sviluppo-regione-unioncamere\/\" \/>\n<meta property=\"og:site_name\" content=\"intoscana\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/intoscana.it\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-30T13:37:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-30T15:44:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/c59373b9b10494333ce3908a8701bd92.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"449\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@intoscana\" \/>\n<meta name=\"twitter:site\" content=\"@intoscana\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.intoscana.it\/it\/patto-per-lo-sviluppo-regione-unioncamere\/\",\"url\":\"https:\/\/www.intoscana.it\/it\/patto-per-lo-sviluppo-regione-unioncamere\/\",\"name\":\"Un patto per lo sviluppo: siglato l'accordo tra Regione e Unincamere\",\"isPartOf\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/patto-per-lo-sviluppo-regione-unioncamere\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/patto-per-lo-sviluppo-regione-unioncamere\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/c59373b9b10494333ce3908a8701bd92.jpg\",\"datePublished\":\"2022-03-30T13:37:50+00:00\",\"dateModified\":\"2022-03-30T15:44:09+00:00\",\"author\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8\"},\"description\":\"Il patto avr\u00e0 durata triennale. Il presidente della Regione Giani: \\\"L'obiettivo \u00e8 far diventare ancora pi\u00f9 competitive le nostre imprese\u201d\",\"breadcrumb\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/patto-per-lo-sviluppo-regione-unioncamere\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.intoscana.it\/it\/patto-per-lo-sviluppo-regione-unioncamere\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.intoscana.it\/it\/patto-per-lo-sviluppo-regione-unioncamere\/#primaryimage\",\"url\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/c59373b9b10494333ce3908a8701bd92.jpg\",\"contentUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/c59373b9b10494333ce3908a8701bd92.jpg\",\"width\":600,\"height\":449},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.intoscana.it\/it\/patto-per-lo-sviluppo-regione-unioncamere\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.intoscana.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un patto per lo sviluppo: Regione e Unioncamere insieme per rilanciare il Paese\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\",\"url\":\"https:\/\/www.intoscana.it\/it\/\",\"name\":\"intoscana\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.intoscana.it\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8\",\"name\":\"Redazione\",\"url\":\"https:\/\/www.intoscana.it\/it\/author\/redazione\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Un patto per lo sviluppo: siglato l'accordo tra Regione e Unincamere","description":"Il patto avr\u00e0 durata triennale. Il presidente della Regione Giani: \"L'obiettivo \u00e8 far diventare ancora pi\u00f9 competitive le nostre imprese\u201d","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.intoscana.it\/it\/patto-per-lo-sviluppo-regione-unioncamere\/","og_locale":"it_IT","og_type":"article","og_title":"Un patto per lo sviluppo: Regione e Unioncamere insieme per rilanciare il Paese","og_description":"Il patto avr\u00e0 durata triennale. Il presidente della Regione Giani: \"L'obiettivo \u00e8 far diventare ancora pi\u00f9 competitive le nostre imprese\u201d","og_url":"https:\/\/www.intoscana.it\/it\/patto-per-lo-sviluppo-regione-unioncamere\/","og_site_name":"intoscana","article_publisher":"https:\/\/www.facebook.com\/intoscana.it","article_published_time":"2022-03-30T13:37:50+00:00","article_modified_time":"2022-03-30T15:44:09+00:00","og_image":[{"width":600,"height":449,"url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/c59373b9b10494333ce3908a8701bd92.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@intoscana","twitter_site":"@intoscana","twitter_misc":{"Written by":"Redazione","Est. reading time":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.intoscana.it\/it\/patto-per-lo-sviluppo-regione-unioncamere\/","url":"https:\/\/www.intoscana.it\/it\/patto-per-lo-sviluppo-regione-unioncamere\/","name":"Un patto per lo sviluppo: siglato l'accordo tra Regione e Unincamere","isPartOf":{"@id":"https:\/\/www.intoscana.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.intoscana.it\/it\/patto-per-lo-sviluppo-regione-unioncamere\/#primaryimage"},"image":{"@id":"https:\/\/www.intoscana.it\/it\/patto-per-lo-sviluppo-regione-unioncamere\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/c59373b9b10494333ce3908a8701bd92.jpg","datePublished":"2022-03-30T13:37:50+00:00","dateModified":"2022-03-30T15:44:09+00:00","author":{"@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8"},"description":"Il patto avr\u00e0 durata triennale. Il presidente della Regione Giani: \"L'obiettivo \u00e8 far diventare ancora pi\u00f9 competitive le nostre imprese\u201d","breadcrumb":{"@id":"https:\/\/www.intoscana.it\/it\/patto-per-lo-sviluppo-regione-unioncamere\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.intoscana.it\/it\/patto-per-lo-sviluppo-regione-unioncamere\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.intoscana.it\/it\/patto-per-lo-sviluppo-regione-unioncamere\/#primaryimage","url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/c59373b9b10494333ce3908a8701bd92.jpg","contentUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/c59373b9b10494333ce3908a8701bd92.jpg","width":600,"height":449},{"@type":"BreadcrumbList","@id":"https:\/\/www.intoscana.it\/it\/patto-per-lo-sviluppo-regione-unioncamere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.intoscana.it\/it\/"},{"@type":"ListItem","position":2,"name":"Un patto per lo sviluppo: Regione e Unioncamere insieme per rilanciare il Paese"}]},{"@type":"WebSite","@id":"https:\/\/www.intoscana.it\/it\/#website","url":"https:\/\/www.intoscana.it\/it\/","name":"intoscana","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intoscana.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8","name":"Redazione","url":"https:\/\/www.intoscana.it\/it\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/220951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/users\/525"}],"replies":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/comments?post=220951"}],"version-history":[{"count":0,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/220951\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media\/95460"}],"wp:attachment":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media?parent=220951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/categories?post=220951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/tags?post=220951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}