{"id":221596,"date":"2022-04-04T10:09:28","date_gmt":"2022-04-04T08:09:28","guid":{"rendered":"https:\/\/www.intoscana.it\/it\/?p=221596"},"modified":"2022-04-05T12:26:46","modified_gmt":"2022-04-05T10:26:46","slug":"trionfo-per-le-gallerie-degli-uffizi-nel-2021-il-luogo-di-cultura-piu-visitato-ditalia","status":"publish","type":"post","link":"https:\/\/www.intoscana.it\/it\/trionfo-per-le-gallerie-degli-uffizi-nel-2021-il-luogo-di-cultura-piu-visitato-ditalia\/","title":{"rendered":"Trionfo per le Gallerie degli Uffizi: nel 2021 il luogo di cultura pi\u00f9 visitato d&#8217;Italia"},"content":{"rendered":"<p><strong>E&#8217; la prima volta <\/strong>che le<strong> Gallerie degli Uffizi<\/strong> superano il <strong>Colosseo e il Parco Archeologico di Pompei e i Musei Vaticani\u00a0<\/strong>nella classifica del <a href=\"https:\/\/www.ilgiornaledellarte.com\" target=\"_blank\" rel=\"noopener\"><strong>Giornale dell&#8217;Arte<\/strong><\/a> dei luoghi di cultura pi\u00f9 visitati.\u00a0Nel 2021 infatti<strong> il museo fiorentino ha totalizzato 1.721.637 ingressi<\/strong>.<\/p>\n<p><strong>Il direttore Eike Schmidt:<\/strong> <em>\u201cSiamo di nuovo su una linea ascendente che fa ben sperare per il futuro. <strong>Si \u00e8 trattato di un impegno di squadra che ha coinvolto tutti i colleghi che lavorano agli Uffizi con le pi\u00f9 diverse mansioni<\/strong>. Insieme \u00e8 stato possibile realizzare i <strong>tre fattori decisivi<\/strong> che hanno potuto attirare e fidelizzare i visitatori: le nuove sale del Cinquecento aperte lo scorso maggio, le mostre che spaziano dall\u2019antichit\u00e0 classica al contemporaneo e l\u2019offerta culturale che diramiamo anche<strong> sul web e sui social\u201d.<\/strong><\/em><\/p>\n<p>Non solo: secondo i numeri diffusi dalla rivista, <strong>gli Uffizi primeggiano ancora<\/strong>, <strong>tra le mostre tenute in Italia lo scorso anno<\/strong>, con <strong><em>Giuseppe Penone, Alberi in versi<\/em><\/strong>\u00a0435.283 visitatori, ed occupano anche il secondo e terzo posto con il focus <strong><em>\u00a0L\u2019ultimo sigillo <\/em><\/strong>sul dipinto di Bartolomeo della Gatta con le <strong><em>Stimmate di San Francesco<\/em><\/strong> portato agli Uffizi dalla Pinacoteca di Castiglion Fiorentino (22, 404.843 presenze) e <strong><em>Leone X torna a Firenze<\/em><\/strong>, a Palazzo Pitti (256.305 presenze).\u00a0Si classifica al quinto posto nella classifica la mostra degli Uffizi <strong><em>Lo Sfregio. Bernini \u2013 Sagaria<\/em><\/strong>, con 191.410 presenze.<\/p>\n<p><strong>Molto alto anche il posizionamento tra le mostre pi\u00f9 visitate al mondo<\/strong>: con Penone e San Francesco le Gallerie occupano <strong>il terzo e quarto posto della classifica<\/strong>, dietro la National Gallery of Victoria (Melbourne) con <em>Ngv Triennial 2020\u00a0<\/em>(548.257) e MoMa (New York) con <em>Automania<\/em> (475.279). In questo contesto il <em>Leone X<\/em> di Raffaello ha garantito a Palazzo Pitti il dodicesimo posto; <em>Lo Sfregio. Bernini \u2013 Sagaria<\/em> si colloca al 22esimo.<\/p>\n<p>Per concludere, <strong>tra i musei pi\u00f9 visitati al mondo<\/strong>, dove in testa con 2.825.000 presenze sta il Louvre di Parigi, la <strong>Galleria delle statue e delle pitture degli Uffizi occupa il ventesimo posto con 969.695 presenze<\/strong>.<\/p>\n<p>Intanto il <strong>primo weekend con domenica gratuita<\/strong>, <strong>iniziativa appena riattivata dal Ministero della Cultura dopo la sospensione per la pandemia<\/strong>, segna un <strong>ulteriore primato<\/strong> per le Gallerie degli Uffizi: \u00e8 stato infatti il <strong>fine settimana pi\u00f9 frequentato dal 2019<\/strong>, con <strong>32.912 visitatori tra sabato e domenica, di cui 16.358 alla Galleria delle statue e pitture, 11.874 a Boboli e 6.491 a Palazzo Pitti.<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tra i musei pi\u00f9 visitati al mondo, dove in testa con 2.825.000 presenze sta il Louvre di Parigi, la Galleria delle statue e delle pitture degli Uffizi occupa il ventesimo posto con 969.695 presenze<\/p>\n","protected":false},"author":525,"featured_media":174631,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[494],"tags":[202,207,5402],"class_list":["post-221596","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","tag-firenze","tag-uffizi","tag-uffizi-diffusi"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v25.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trionfo per le Gallerie degli Uffizi: nel 2021 il luogo di cultura pi\u00f9 visitato d&#039;Italia - intoscana<\/title>\n<meta name=\"description\" content=\"Tra i musei pi\u00f9 visitati al mondo la Galleria delle statue e delle pitture degli Uffizi occupa il ventesimo posto con 969.695 presenze\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.intoscana.it\/it\/trionfo-per-le-gallerie-degli-uffizi-nel-2021-il-luogo-di-cultura-piu-visitato-ditalia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trionfo per le Gallerie degli Uffizi: nel 2021 il luogo di cultura pi\u00f9 visitato d&#039;Italia\" \/>\n<meta property=\"og:description\" content=\"Tra i musei pi\u00f9 visitati al mondo la Galleria delle statue e delle pitture degli Uffizi occupa il ventesimo posto con 969.695 presenze\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.intoscana.it\/it\/trionfo-per-le-gallerie-degli-uffizi-nel-2021-il-luogo-di-cultura-piu-visitato-ditalia\/\" \/>\n<meta property=\"og:site_name\" content=\"intoscana\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/intoscana.it\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-04T08:09:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-05T10:26:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/Uffizi-e1620130822566.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1829\" \/>\n\t<meta property=\"og:image:height\" content=\"1556\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@intoscana\" \/>\n<meta name=\"twitter:site\" content=\"@intoscana\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.intoscana.it\/it\/trionfo-per-le-gallerie-degli-uffizi-nel-2021-il-luogo-di-cultura-piu-visitato-ditalia\/\",\"url\":\"https:\/\/www.intoscana.it\/it\/trionfo-per-le-gallerie-degli-uffizi-nel-2021-il-luogo-di-cultura-piu-visitato-ditalia\/\",\"name\":\"Trionfo per le Gallerie degli Uffizi: nel 2021 il luogo di cultura pi\u00f9 visitato d'Italia - intoscana\",\"isPartOf\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/trionfo-per-le-gallerie-degli-uffizi-nel-2021-il-luogo-di-cultura-piu-visitato-ditalia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/trionfo-per-le-gallerie-degli-uffizi-nel-2021-il-luogo-di-cultura-piu-visitato-ditalia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/Uffizi-e1620130822566.jpeg\",\"datePublished\":\"2022-04-04T08:09:28+00:00\",\"dateModified\":\"2022-04-05T10:26:46+00:00\",\"author\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8\"},\"description\":\"Tra i musei pi\u00f9 visitati al mondo la Galleria delle statue e delle pitture degli Uffizi occupa il ventesimo posto con 969.695 presenze\",\"breadcrumb\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/trionfo-per-le-gallerie-degli-uffizi-nel-2021-il-luogo-di-cultura-piu-visitato-ditalia\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.intoscana.it\/it\/trionfo-per-le-gallerie-degli-uffizi-nel-2021-il-luogo-di-cultura-piu-visitato-ditalia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.intoscana.it\/it\/trionfo-per-le-gallerie-degli-uffizi-nel-2021-il-luogo-di-cultura-piu-visitato-ditalia\/#primaryimage\",\"url\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/Uffizi-e1620130822566.jpeg\",\"contentUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/Uffizi-e1620130822566.jpeg\",\"width\":1829,\"height\":1556,\"caption\":\"Uffizi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.intoscana.it\/it\/trionfo-per-le-gallerie-degli-uffizi-nel-2021-il-luogo-di-cultura-piu-visitato-ditalia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.intoscana.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trionfo per le Gallerie degli Uffizi: nel 2021 il luogo di cultura pi\u00f9 visitato d&#8217;Italia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\",\"url\":\"https:\/\/www.intoscana.it\/it\/\",\"name\":\"intoscana\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.intoscana.it\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8\",\"name\":\"Redazione\",\"url\":\"https:\/\/www.intoscana.it\/it\/author\/redazione\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Trionfo per le Gallerie degli Uffizi: nel 2021 il luogo di cultura pi\u00f9 visitato d'Italia - intoscana","description":"Tra i musei pi\u00f9 visitati al mondo la Galleria delle statue e delle pitture degli Uffizi occupa il ventesimo posto con 969.695 presenze","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.intoscana.it\/it\/trionfo-per-le-gallerie-degli-uffizi-nel-2021-il-luogo-di-cultura-piu-visitato-ditalia\/","og_locale":"it_IT","og_type":"article","og_title":"Trionfo per le Gallerie degli Uffizi: nel 2021 il luogo di cultura pi\u00f9 visitato d'Italia","og_description":"Tra i musei pi\u00f9 visitati al mondo la Galleria delle statue e delle pitture degli Uffizi occupa il ventesimo posto con 969.695 presenze","og_url":"https:\/\/www.intoscana.it\/it\/trionfo-per-le-gallerie-degli-uffizi-nel-2021-il-luogo-di-cultura-piu-visitato-ditalia\/","og_site_name":"intoscana","article_publisher":"https:\/\/www.facebook.com\/intoscana.it","article_published_time":"2022-04-04T08:09:28+00:00","article_modified_time":"2022-04-05T10:26:46+00:00","og_image":[{"width":1829,"height":1556,"url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/Uffizi-e1620130822566.jpeg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@intoscana","twitter_site":"@intoscana","twitter_misc":{"Written by":"Redazione","Est. reading time":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.intoscana.it\/it\/trionfo-per-le-gallerie-degli-uffizi-nel-2021-il-luogo-di-cultura-piu-visitato-ditalia\/","url":"https:\/\/www.intoscana.it\/it\/trionfo-per-le-gallerie-degli-uffizi-nel-2021-il-luogo-di-cultura-piu-visitato-ditalia\/","name":"Trionfo per le Gallerie degli Uffizi: nel 2021 il luogo di cultura pi\u00f9 visitato d'Italia - intoscana","isPartOf":{"@id":"https:\/\/www.intoscana.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.intoscana.it\/it\/trionfo-per-le-gallerie-degli-uffizi-nel-2021-il-luogo-di-cultura-piu-visitato-ditalia\/#primaryimage"},"image":{"@id":"https:\/\/www.intoscana.it\/it\/trionfo-per-le-gallerie-degli-uffizi-nel-2021-il-luogo-di-cultura-piu-visitato-ditalia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/Uffizi-e1620130822566.jpeg","datePublished":"2022-04-04T08:09:28+00:00","dateModified":"2022-04-05T10:26:46+00:00","author":{"@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8"},"description":"Tra i musei pi\u00f9 visitati al mondo la Galleria delle statue e delle pitture degli Uffizi occupa il ventesimo posto con 969.695 presenze","breadcrumb":{"@id":"https:\/\/www.intoscana.it\/it\/trionfo-per-le-gallerie-degli-uffizi-nel-2021-il-luogo-di-cultura-piu-visitato-ditalia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.intoscana.it\/it\/trionfo-per-le-gallerie-degli-uffizi-nel-2021-il-luogo-di-cultura-piu-visitato-ditalia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.intoscana.it\/it\/trionfo-per-le-gallerie-degli-uffizi-nel-2021-il-luogo-di-cultura-piu-visitato-ditalia\/#primaryimage","url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/Uffizi-e1620130822566.jpeg","contentUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/Uffizi-e1620130822566.jpeg","width":1829,"height":1556,"caption":"Uffizi"},{"@type":"BreadcrumbList","@id":"https:\/\/www.intoscana.it\/it\/trionfo-per-le-gallerie-degli-uffizi-nel-2021-il-luogo-di-cultura-piu-visitato-ditalia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.intoscana.it\/it\/"},{"@type":"ListItem","position":2,"name":"Trionfo per le Gallerie degli Uffizi: nel 2021 il luogo di cultura pi\u00f9 visitato d&#8217;Italia"}]},{"@type":"WebSite","@id":"https:\/\/www.intoscana.it\/it\/#website","url":"https:\/\/www.intoscana.it\/it\/","name":"intoscana","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intoscana.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8","name":"Redazione","url":"https:\/\/www.intoscana.it\/it\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/221596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/users\/525"}],"replies":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/comments?post=221596"}],"version-history":[{"count":0,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/221596\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media\/174631"}],"wp:attachment":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media?parent=221596"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/categories?post=221596"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/tags?post=221596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}