{"id":225408,"date":"2022-04-26T17:19:11","date_gmt":"2022-04-26T15:19:11","guid":{"rendered":"https:\/\/www.intoscana.it\/it\/?p=225408"},"modified":"2022-04-27T16:36:58","modified_gmt":"2022-04-27T14:36:58","slug":"la-regione-salva-mercato-dei-fiori-di-pescia-chiusura-scongiurata","status":"publish","type":"post","link":"https:\/\/www.intoscana.it\/it\/la-regione-salva-mercato-dei-fiori-di-pescia-chiusura-scongiurata\/","title":{"rendered":"La Regione salva il Mercato dei fiori di Pescia, chiusura scongiurata"},"content":{"rendered":"<p>Il <strong>Mercato dei Fiori di Pescia \u00e8 salvo<\/strong>. Scongiurata un&#8217;eventuale chiusura dopo il finanziamento straordinario di <strong>due milioni di euro<\/strong> deliberato <strong>dalla giunta regionale<\/strong>. I soldi serviranno per sostenere l\u2019adeguamento strutturale dell\u2019edificio che ospita uno dei mercati all\u2019ingrosso attivi pi\u00f9 grandi d\u2019Italia. Un\u2019opera ingegneristica che figura tra le costruzioni di interesse storico-artistico realizzate sul territorio nazionale dal 1945 ad oggi.<\/p>\n<h3>La Regione in soccorso del Mercato dei fiori<\/h3>\n<p>\u201c<em>In questo modo veniamo incontro alla richiesta di aiuto che ci era arrivata dal commissario prefettizio che amministra in questo momento il Comune<\/em>\u201d spiega il presidente della Toscana, <strong>Eugenio Giani<\/strong>. Il finanziamento si somma ad <strong>altri 3 milioni di euro<\/strong> gi\u00e0 messi a disposizione <strong>dalla Regione nel 2016<\/strong>.<\/p>\n<p>&#8220;<em>Un altro milione ce lo metter\u00e0 il Comune<\/em>&#8221; assicura il vice prefetto <strong>Vittorio De Cristofaro<\/strong>, commissario a Pescia dal 1 febbraio, ringraziando il presidente della Toscana e il consigliere regionale <strong>Marco Niccolai<\/strong> per la disponibilit\u00e0 e il lavoro fatto.<\/p>\n<figure id=\"post-225446 media-225446\" class=\"align-none\"><img decoding=\"async\" src=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/61621504_1632886043510085_5375857727991971840_n.jpg\" alt=\"\" \/><\/figure>\n<div class=\"titleimg\">Il mercato dei fiori a Pescia \u2013 \u00a9 pagina Facebook Mercato fiori piante Toscana<\/div>\n<h3>Mefit, il nuovo mercato dopo il 1988<\/h3>\n<p><strong>Il Mercato dei Fiori di Pescia<\/strong> \u00a0&#8211; il Mefit, chiamato il \u2018<em>nuovo<\/em>\u2019 mercato perch\u00e9 sostitu\u00ec nel 1988 quello, oramai diventato piccolo, realizzato negli anni Cinquanta &#8211; \u00a0\u00e8 stato progettato negli anni Settanta e sorge vicino alla stazione ferroviaria. Si contraddistingue architettonicamente per <strong>sei doppi pennoni<\/strong> posti su due lati opposti e sostenuti da tiranti in acciaio e grandi vetrate.<\/p>\n<p><mark>Conta la superficie coperta senza pilastri pi\u00f9 ampia d\u2019Italia<\/mark>, un quadrato di oltre un ettaro che ospita <strong>il salone delle contrattazioni<\/strong>, a cui si aggiungono lateralmente<strong> 89 magazzini<\/strong> per una superficie quasi identica, 55 box per 1900 metri quadrati, serre per 1.875 e un\u2019area a verde per 25.500, oltre agli uffici, i parcheggi e l\u2019area di carico e scarico. \u00a0Una struttura che necessitava di un adeguamento strutturale, non pi\u00f9 rinviabile, e <mark>senza l\u2019intervento della Regione rischiava la chiusura<\/mark>.<\/p>\n<p>\u201c<em>I soldi messi dalla Regione sono indispensabili<\/em> \u2013 spiega il viceprefetto <strong>De Cristofaro<\/strong> &#8211; <em>per avviare la messa in sicurezza dello stabile e quindi evitare il possibile sequestro da parte dell\u2019autorit\u00e0 giudiziaria per pericolo<\/em>\u201d.<\/p>\n<p>Il termine ultimo imposto dalla <strong>procedura gi\u00e0 avviata \u00e8 il 22 giugno<\/strong>: dopo quella data i vigili del fuoco avranno sessanta giorni per fare un sopralluogo ed altri trenta per riferire all\u2019autorit\u00e0 giudiziaria. Ma se i lavori saranno gi\u00e0 partiti \u2013 i tempi ci sono \u2013 sequestro e chiusura potranno essere evitati.<\/p>\n<h3>Un mercato passato di mano in mano<\/h3>\n<p>Quando il Mercato dei fiori di Pescia fu costruito, era <strong>di propriet\u00e0 del Ministero dell\u2019agricoltura<\/strong>. Poi, negli anni Duemila, \u00e8 passato alla Regione (assieme alla competenze agricole); dal 2016, in base ad un legge regionale approvata nel 2009 ed un successivo accordo di programma, la propriet\u00e0 \u00e8 stata<strong> trasferita al Comune, che dal 2013<\/strong>, tramite un\u2019azienda speciale, cura anche il servizio di mercato all\u2019ingrosso, dopo il fallimento del consorzio Comicent.<\/p>\n<p>\u201c<em>Si tratta di un\u2019attivit\u00e0 economica importante, per il territorio pesciatino ma non solo per Pescia, e per questo abbiamo deciso di intervenire prontamente al fine di scongiurarne la chiusura<\/em> \u2013 sottolinea il presidente <strong>Giani<\/strong> \u2013, <em>anche se, lo voglio ricordare, la Regione non ha alcuna competenza o titolarit\u00e0 oramai sulla struttura. La sua chiusura sarebbe stata per\u00f2 un danno economico e sociale di rilievo regionale<\/em>\u201d.<\/p>\n<h3>Un riferimento per 500 produttori agricoli<\/h3>\n<p>Il mercato all\u2019ingrosso \u00e8 infatti un punto di riferimento per<strong> 500 produttori agricoli<\/strong>, ma vi girano attorno centinaia di aziende, dai commercianti ai trasportatori per finire ai servizi: in tutto si arriva a circa <strong>4mila addetti.<\/strong><\/p>\n<p>L\u2019intervento sull\u2019edificio, che sar\u00e0 realizzato grazie al contributo della Regione, servir\u00e0 a renderlo da subito di nuovo sicuro e quindi successivamente idoneo rispetto alle mutate norme in materia di sicurezza ed antincendio, oltre a supplire alla manutenzione ordinaria straordinaria che negli ultimi anni non \u00e8 stata realizzata.<\/p>\n<p>\u201c<em>Questo contributo dimostra come la Regione sia in campo non a chiacchiere ma con risorse ed azioni concrete<\/em>\u201d puntualizza e risponde alle polemiche il consigliere regionale <strong>Marco Niccolai<\/strong>, presidente della Commissione Aree interne.<\/p>\n<figure id=\"post-225454 media-225454\" class=\"align-none\"><img decoding=\"async\" src=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/PRT_3896.jpeg\" alt=\"\" \/><\/figure>\n<div class=\"titleimg\">Un momento della conferenza stampa: da sinistra il vice prefetto De Cristofaro, il presidente Giani e il consigliere regionale Niccolai<\/div>\n<p>\u201c<em>Due mesi fa il mercato era spacciato, oggi pu\u00f2 guardare al futuro: grazie al lavoro che in soli due mesi dall\u2019insediamento ha fatto il commissario prefettizio, che ha definito il progetto in modo serio e credibile e ce l\u2019ha presentato<\/em> \u2013 aggiunge -, \u00a0e<em>vitiamo uno shock e un disastro economico e sociale che avrebbe riguardato tutto il territorio della provincia di Pistoia, colpendo peraltro un hub fondamentale per il commercio dei fiori in Italia<\/em>\u201d.<\/p>\n<p>\u201c<em>Ringrazio<\/em> \u2013 termina \u2013 <em>il presidente Giani e la giunta che, in un momento non certo semplice per i bilanci delle Regioni, al primo momento utile sono riusciti a mettere in campo le risorse necessarie, in questa corsa la corsa contro il tempo per consentire al Comune guidato dal dottor De Cristofaro di potersi presentare in modo credibile agli organi di controllo dello Stato che dovranno verificare la situazione<\/em>\u201d.<\/p>\n<p>\u201c<em>Dal provvedimento dei vigili del fuoco, che c\u2019\u00e8 stato a giugno 2021, a Pescia si sono persi sette mesi inutilmente<\/em> \u2013 evidenzia -: <em>in due mesi siamo riusciti a mettere in campo un intervento, grazie alla seriet\u00e0 e alla credibilit\u00e0 delle proposte che il dottor De Cristofaro ha avanzato e che la Regione ha concretamente recepito<\/em>&#8220;.<\/p>\n<p>\u201c<em>Rimediamo a probabili sottovalutazioni che in passato ci sono state da parte del Comune rispetto ad interventi che invece erano necessari<\/em> \u2013 conclude Giani \u2013 <em>Certo in futuro alla manutenzione dell\u2019immobile dovr\u00e0 pensarci l\u2019amministrazione comunale<\/em>\u201d.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Finanziamento straordinario da due milioni di euro per adeguare la struttura che ospita uno dei mercati all&#8217;ingrosso pi\u00f9 grandi d&#8217;Italia<\/p>\n","protected":false},"author":525,"featured_media":225448,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[494],"tags":[5129,5210],"class_list":["post-225408","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","tag-florovivaismo","tag-pescia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v25.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Regione salva il Mercato dei fiori, chiusura scongiurata - intoscana<\/title>\n<meta name=\"description\" content=\"Finanziamento straordinario da due milioni per adeguare la struttura che ospita a Pescia uno dei mercati all&#039;ingrosso pi\u00f9 grandi d&#039;Italia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.intoscana.it\/it\/la-regione-salva-mercato-dei-fiori-di-pescia-chiusura-scongiurata\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Regione salva il Mercato dei fiori di Pescia, chiusura scongiurata\" \/>\n<meta property=\"og:description\" content=\"Finanziamento straordinario da due milioni per adeguare la struttura che ospita a Pescia uno dei mercati all&#039;ingrosso pi\u00f9 grandi d&#039;Italia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.intoscana.it\/it\/la-regione-salva-mercato-dei-fiori-di-pescia-chiusura-scongiurata\/\" \/>\n<meta property=\"og:site_name\" content=\"intoscana\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/intoscana.it\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-26T15:19:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-27T14:36:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/244525773_2420389761426372_5151564720805565362_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@intoscana\" \/>\n<meta name=\"twitter:site\" content=\"@intoscana\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.intoscana.it\/it\/la-regione-salva-mercato-dei-fiori-di-pescia-chiusura-scongiurata\/\",\"url\":\"https:\/\/www.intoscana.it\/it\/la-regione-salva-mercato-dei-fiori-di-pescia-chiusura-scongiurata\/\",\"name\":\"La Regione salva il Mercato dei fiori, chiusura scongiurata - intoscana\",\"isPartOf\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/la-regione-salva-mercato-dei-fiori-di-pescia-chiusura-scongiurata\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/la-regione-salva-mercato-dei-fiori-di-pescia-chiusura-scongiurata\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/244525773_2420389761426372_5151564720805565362_n.jpg\",\"datePublished\":\"2022-04-26T15:19:11+00:00\",\"dateModified\":\"2022-04-27T14:36:58+00:00\",\"author\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8\"},\"description\":\"Finanziamento straordinario da due milioni per adeguare la struttura che ospita a Pescia uno dei mercati all'ingrosso pi\u00f9 grandi d'Italia\",\"breadcrumb\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/la-regione-salva-mercato-dei-fiori-di-pescia-chiusura-scongiurata\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.intoscana.it\/it\/la-regione-salva-mercato-dei-fiori-di-pescia-chiusura-scongiurata\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.intoscana.it\/it\/la-regione-salva-mercato-dei-fiori-di-pescia-chiusura-scongiurata\/#primaryimage\",\"url\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/244525773_2420389761426372_5151564720805565362_n.jpg\",\"contentUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/244525773_2420389761426372_5151564720805565362_n.jpg\",\"width\":1440,\"height\":1080,\"caption\":\"Il mercato dei fiori a Pescia - \u00a9 pagina Facebook Mercato fiori piante Toscana\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.intoscana.it\/it\/la-regione-salva-mercato-dei-fiori-di-pescia-chiusura-scongiurata\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.intoscana.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Regione salva il Mercato dei fiori di Pescia, chiusura scongiurata\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\",\"url\":\"https:\/\/www.intoscana.it\/it\/\",\"name\":\"intoscana\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.intoscana.it\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8\",\"name\":\"Redazione\",\"url\":\"https:\/\/www.intoscana.it\/it\/author\/redazione\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La Regione salva il Mercato dei fiori, chiusura scongiurata - intoscana","description":"Finanziamento straordinario da due milioni per adeguare la struttura che ospita a Pescia uno dei mercati all'ingrosso pi\u00f9 grandi d'Italia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.intoscana.it\/it\/la-regione-salva-mercato-dei-fiori-di-pescia-chiusura-scongiurata\/","og_locale":"it_IT","og_type":"article","og_title":"La Regione salva il Mercato dei fiori di Pescia, chiusura scongiurata","og_description":"Finanziamento straordinario da due milioni per adeguare la struttura che ospita a Pescia uno dei mercati all'ingrosso pi\u00f9 grandi d'Italia","og_url":"https:\/\/www.intoscana.it\/it\/la-regione-salva-mercato-dei-fiori-di-pescia-chiusura-scongiurata\/","og_site_name":"intoscana","article_publisher":"https:\/\/www.facebook.com\/intoscana.it","article_published_time":"2022-04-26T15:19:11+00:00","article_modified_time":"2022-04-27T14:36:58+00:00","og_image":[{"width":1440,"height":1080,"url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/244525773_2420389761426372_5151564720805565362_n.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@intoscana","twitter_site":"@intoscana","twitter_misc":{"Written by":"Redazione","Est. reading time":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.intoscana.it\/it\/la-regione-salva-mercato-dei-fiori-di-pescia-chiusura-scongiurata\/","url":"https:\/\/www.intoscana.it\/it\/la-regione-salva-mercato-dei-fiori-di-pescia-chiusura-scongiurata\/","name":"La Regione salva il Mercato dei fiori, chiusura scongiurata - intoscana","isPartOf":{"@id":"https:\/\/www.intoscana.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.intoscana.it\/it\/la-regione-salva-mercato-dei-fiori-di-pescia-chiusura-scongiurata\/#primaryimage"},"image":{"@id":"https:\/\/www.intoscana.it\/it\/la-regione-salva-mercato-dei-fiori-di-pescia-chiusura-scongiurata\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/244525773_2420389761426372_5151564720805565362_n.jpg","datePublished":"2022-04-26T15:19:11+00:00","dateModified":"2022-04-27T14:36:58+00:00","author":{"@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8"},"description":"Finanziamento straordinario da due milioni per adeguare la struttura che ospita a Pescia uno dei mercati all'ingrosso pi\u00f9 grandi d'Italia","breadcrumb":{"@id":"https:\/\/www.intoscana.it\/it\/la-regione-salva-mercato-dei-fiori-di-pescia-chiusura-scongiurata\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.intoscana.it\/it\/la-regione-salva-mercato-dei-fiori-di-pescia-chiusura-scongiurata\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.intoscana.it\/it\/la-regione-salva-mercato-dei-fiori-di-pescia-chiusura-scongiurata\/#primaryimage","url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/244525773_2420389761426372_5151564720805565362_n.jpg","contentUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/244525773_2420389761426372_5151564720805565362_n.jpg","width":1440,"height":1080,"caption":"Il mercato dei fiori a Pescia - \u00a9 pagina Facebook Mercato fiori piante Toscana"},{"@type":"BreadcrumbList","@id":"https:\/\/www.intoscana.it\/it\/la-regione-salva-mercato-dei-fiori-di-pescia-chiusura-scongiurata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.intoscana.it\/it\/"},{"@type":"ListItem","position":2,"name":"La Regione salva il Mercato dei fiori di Pescia, chiusura scongiurata"}]},{"@type":"WebSite","@id":"https:\/\/www.intoscana.it\/it\/#website","url":"https:\/\/www.intoscana.it\/it\/","name":"intoscana","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intoscana.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8","name":"Redazione","url":"https:\/\/www.intoscana.it\/it\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/225408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/users\/525"}],"replies":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/comments?post=225408"}],"version-history":[{"count":0,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/225408\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media\/225448"}],"wp:attachment":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media?parent=225408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/categories?post=225408"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/tags?post=225408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}