{"id":291026,"date":"2023-06-23T15:35:16","date_gmt":"2023-06-23T13:35:16","guid":{"rendered":"https:\/\/www.intoscana.it\/it\/?p=291026"},"modified":"2023-06-26T15:20:00","modified_gmt":"2023-06-26T13:20:00","slug":"sabato-24-giugno-la-finale-del-calcio-storico-sara-rossi-contro-azzurri","status":"publish","type":"post","link":"https:\/\/www.intoscana.it\/it\/sabato-24-giugno-la-finale-del-calcio-storico-sara-rossi-contro-azzurri\/","title":{"rendered":"Sabato 24 giugno la finale del calcio storico tra Rossi e Azzurri"},"content":{"rendered":"<p>Sar\u00e0 <strong>Azzurri di Santa Croce contro Rossi<\/strong> <strong>di Santa Maria Novella<\/strong> la finale del Calcio storico fiorentino. L&#8217;appuntamento come tradizione il<strong> 24 giugno prossimo<\/strong>, giorno della festa di <strong>San Giovanni<\/strong>: patrono di Firenze.<\/p>\n<p>A partire dalle 18 le squadre dei due quartieri scenderanno in campo sul terreno di gioco davanti alla Basilica. Gi\u00e0 <strong>tutti venduti i biglietti<\/strong> per la finale, si spiega dal Comune.<\/p>\n<p>I <strong>Rossi di Santa Maria Novella<\/strong> hanno vinto la seconda semifinale, disputata domenica 11 giugno sul sabbione di piazza Santa Croce, contro i Verdi di San Giovanni per 7 cacce a 2.<\/p>\n<p>La domenica prima sono stati gli <strong>Azzurri di Santa Croce<\/strong> a imporsi sui Bianchi di Santo Spirito per <strong>7 cacce a 3 nella prima semifinale.<\/strong><\/p>\n<p>La finale del calcio in costume sar\u00e0 anticipata dal\u00a0tradizionale <strong>corteo storico della Repubblica fiorentina<\/strong> che partir\u00e0 alle ore 15.45 da piazza Santa Maria Novella per sfilare fino a Santa Croce, dove arriver\u00e0 alle ore 17.<\/p>\n<p><strong>Il Magnifico messere<\/strong> sar\u00e0 il lanciatore del peso <strong>Leonardo Fabbri<\/strong>, vincitore della sua gara al Golden Gala &#8211; Pietro Mennea di Firenze dello scorso 2 giugno: con la misura di 21,81 metri, il miglior lanciatore d&#8217;Europa del 2023.<\/p>\n<p>Cambio in corsa per il ruolo di <strong>Leggiadra Madonna del Calcio Storico Fiorentino: <\/strong>sar\u00e0\u00a0<strong>Enrica Merlo,<\/strong> capitana della Savino Del Bene Volley a sostituire\u00a0<strong>Ekaterina Antropova,<\/strong> che ha dovuto rispondere alla<strong> convocazione con la Nazionale italiana<\/strong> in vista degli impegni internazionali delle azzurre.<\/p>\n<h3>Dove vedere il Calcio Storico in tv<\/h3>\n<p>Assicurata la diretta per tutti coloro che non potranno essere in piazza, spiegano dal Comune. Le immagini saranno curate dalla societ\u00e0 <strong>ShowLab<\/strong> che ha vinto il bando di gara indetto da Palazzo Vecchio. Le partite verranno trasmesse in diretta, per tutta la Toscana, dalle 15,45, su <strong>Toscana TV<\/strong> (Canale 11) e <strong>Firenze TV<\/strong> (Canale 80). In replica alle 21 su <strong>Toscana Tv<\/strong> e alle 23 su <strong>Firenze Tv<\/strong>.<\/p>\n<figure id=\"post-291049 media-291049\" class=\"align-none\"><img decoding=\"async\" src=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/347638890_788990482590772_8075905819639457445_n.jpg\" alt=\"\" \/><\/figure>\n<div class=\"titleimg\">Corto storico<\/div>\n<p>&#8220;<em>ShowLab avr\u00e0 la diretta anche su Dazn (in tutta Italia per tutti gli abbonati alla piattaforma) e produrr\u00e0 la versione in 360 insieme a Gold, e ospiter\u00e0 le televisioni di tutto il mondo fra le quali Nhk dal Giappone, Bbc Inghilterra, Cuarto dalla Spagna, World rugby tour dagli Stati Uniti<\/em> &#8211; si spiega il Comune-. <em>\u00c8, inoltre, in lavorazione un documentario sul mondo del Calcio storico fiorentino che verr\u00e0 poi trasmesso in tutto il mondo<\/em>&#8220;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diretta su Toscana TV, Canale 11 e Firenze TV, Canale 80 e anche su Dazn. Presenti emittenti da tutto il mondo, sar\u00e0 realizzato un documentario<\/p>\n","protected":false},"author":554,"featured_media":68615,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[494],"tags":[4891,4474,202,6495],"class_list":["post-291026","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","tag-calcio-storico","tag-eventi","tag-firenze","tag-folklore"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v25.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sabato 24 giugno la finale del calcio storico tra Rossi e Azzurri - intoscana<\/title>\n<meta name=\"description\" content=\"Diretta su Toscana TV, Canale 11 e Firenze TV, Canale 80 e anche su Dazn. Presenti emittenti da tutto il mondo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.intoscana.it\/it\/sabato-24-giugno-la-finale-del-calcio-storico-sara-rossi-contro-azzurri\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sabato 24 giugno la finale del calcio storico tra Rossi e Azzurri\" \/>\n<meta property=\"og:description\" content=\"Diretta su Toscana TV, Canale 11 e Firenze TV, Canale 80 e anche su Dazn. Presenti emittenti da tutto il mondo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.intoscana.it\/it\/sabato-24-giugno-la-finale-del-calcio-storico-sara-rossi-contro-azzurri\/\" \/>\n<meta property=\"og:site_name\" content=\"intoscana\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/intoscana.it\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-23T13:35:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-26T13:20:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/CALCIO1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"830\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Raffaella Galamini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@orio\" \/>\n<meta name=\"twitter:site\" content=\"@intoscana\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Raffaella Galamini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.intoscana.it\/it\/sabato-24-giugno-la-finale-del-calcio-storico-sara-rossi-contro-azzurri\/\",\"url\":\"https:\/\/www.intoscana.it\/it\/sabato-24-giugno-la-finale-del-calcio-storico-sara-rossi-contro-azzurri\/\",\"name\":\"Sabato 24 giugno la finale del calcio storico tra Rossi e Azzurri - intoscana\",\"isPartOf\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/sabato-24-giugno-la-finale-del-calcio-storico-sara-rossi-contro-azzurri\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/sabato-24-giugno-la-finale-del-calcio-storico-sara-rossi-contro-azzurri\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/CALCIO1.jpg\",\"datePublished\":\"2023-06-23T13:35:16+00:00\",\"dateModified\":\"2023-06-26T13:20:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9eb9daa846a49fe51af39a73d9d1986b\"},\"description\":\"Diretta su Toscana TV, Canale 11 e Firenze TV, Canale 80 e anche su Dazn. Presenti emittenti da tutto il mondo\",\"breadcrumb\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/sabato-24-giugno-la-finale-del-calcio-storico-sara-rossi-contro-azzurri\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.intoscana.it\/it\/sabato-24-giugno-la-finale-del-calcio-storico-sara-rossi-contro-azzurri\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.intoscana.it\/it\/sabato-24-giugno-la-finale-del-calcio-storico-sara-rossi-contro-azzurri\/#primaryimage\",\"url\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/CALCIO1.jpg\",\"contentUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/CALCIO1.jpg\",\"width\":1000,\"height\":830},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.intoscana.it\/it\/sabato-24-giugno-la-finale-del-calcio-storico-sara-rossi-contro-azzurri\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.intoscana.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sabato 24 giugno la finale del calcio storico tra Rossi e Azzurri\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\",\"url\":\"https:\/\/www.intoscana.it\/it\/\",\"name\":\"intoscana\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.intoscana.it\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9eb9daa846a49fe51af39a73d9d1986b\",\"name\":\"Raffaella Galamini\",\"sameAs\":[\"https:\/\/x.com\/orio\"],\"url\":\"https:\/\/www.intoscana.it\/it\/author\/r-galamini\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sabato 24 giugno la finale del calcio storico tra Rossi e Azzurri - intoscana","description":"Diretta su Toscana TV, Canale 11 e Firenze TV, Canale 80 e anche su Dazn. Presenti emittenti da tutto il mondo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.intoscana.it\/it\/sabato-24-giugno-la-finale-del-calcio-storico-sara-rossi-contro-azzurri\/","og_locale":"it_IT","og_type":"article","og_title":"Sabato 24 giugno la finale del calcio storico tra Rossi e Azzurri","og_description":"Diretta su Toscana TV, Canale 11 e Firenze TV, Canale 80 e anche su Dazn. Presenti emittenti da tutto il mondo","og_url":"https:\/\/www.intoscana.it\/it\/sabato-24-giugno-la-finale-del-calcio-storico-sara-rossi-contro-azzurri\/","og_site_name":"intoscana","article_publisher":"https:\/\/www.facebook.com\/intoscana.it","article_published_time":"2023-06-23T13:35:16+00:00","article_modified_time":"2023-06-26T13:20:00+00:00","og_image":[{"width":1000,"height":830,"url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/CALCIO1.jpg","type":"image\/jpeg"}],"author":"Raffaella Galamini","twitter_card":"summary_large_image","twitter_creator":"@orio","twitter_site":"@intoscana","twitter_misc":{"Written by":"Raffaella Galamini","Est. reading time":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.intoscana.it\/it\/sabato-24-giugno-la-finale-del-calcio-storico-sara-rossi-contro-azzurri\/","url":"https:\/\/www.intoscana.it\/it\/sabato-24-giugno-la-finale-del-calcio-storico-sara-rossi-contro-azzurri\/","name":"Sabato 24 giugno la finale del calcio storico tra Rossi e Azzurri - intoscana","isPartOf":{"@id":"https:\/\/www.intoscana.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.intoscana.it\/it\/sabato-24-giugno-la-finale-del-calcio-storico-sara-rossi-contro-azzurri\/#primaryimage"},"image":{"@id":"https:\/\/www.intoscana.it\/it\/sabato-24-giugno-la-finale-del-calcio-storico-sara-rossi-contro-azzurri\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/CALCIO1.jpg","datePublished":"2023-06-23T13:35:16+00:00","dateModified":"2023-06-26T13:20:00+00:00","author":{"@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9eb9daa846a49fe51af39a73d9d1986b"},"description":"Diretta su Toscana TV, Canale 11 e Firenze TV, Canale 80 e anche su Dazn. Presenti emittenti da tutto il mondo","breadcrumb":{"@id":"https:\/\/www.intoscana.it\/it\/sabato-24-giugno-la-finale-del-calcio-storico-sara-rossi-contro-azzurri\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.intoscana.it\/it\/sabato-24-giugno-la-finale-del-calcio-storico-sara-rossi-contro-azzurri\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.intoscana.it\/it\/sabato-24-giugno-la-finale-del-calcio-storico-sara-rossi-contro-azzurri\/#primaryimage","url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/CALCIO1.jpg","contentUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/CALCIO1.jpg","width":1000,"height":830},{"@type":"BreadcrumbList","@id":"https:\/\/www.intoscana.it\/it\/sabato-24-giugno-la-finale-del-calcio-storico-sara-rossi-contro-azzurri\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.intoscana.it\/it\/"},{"@type":"ListItem","position":2,"name":"Sabato 24 giugno la finale del calcio storico tra Rossi e Azzurri"}]},{"@type":"WebSite","@id":"https:\/\/www.intoscana.it\/it\/#website","url":"https:\/\/www.intoscana.it\/it\/","name":"intoscana","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intoscana.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9eb9daa846a49fe51af39a73d9d1986b","name":"Raffaella Galamini","sameAs":["https:\/\/x.com\/orio"],"url":"https:\/\/www.intoscana.it\/it\/author\/r-galamini\/"}]}},"_links":{"self":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/291026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/users\/554"}],"replies":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/comments?post=291026"}],"version-history":[{"count":0,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/291026\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media\/68615"}],"wp:attachment":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media?parent=291026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/categories?post=291026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/tags?post=291026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}