{"id":378797,"date":"2025-03-19T09:57:14","date_gmt":"2025-03-19T08:57:14","guid":{"rendered":"https:\/\/www.intoscana.it\/it\/?p=378797"},"modified":"2025-03-19T09:58:25","modified_gmt":"2025-03-19T08:58:25","slug":"al-cango-sonate-bach-la-danza-di-virgilio-sieni-che-mette-in-scena-lorrore-della-guerra","status":"publish","type":"post","link":"https:\/\/www.intoscana.it\/it\/al-cango-sonate-bach-la-danza-di-virgilio-sieni-che-mette-in-scena-lorrore-della-guerra\/","title":{"rendered":"Al Cango &#8220;Sonate Bach&#8221; la danza di Virgilio Sieni che mette in scena l&#8217;orrore della guerra"},"content":{"rendered":"<p>Al teatro<strong> Cango Cantieri Goldonetta<\/strong> di Firenze <strong>da venerd\u00ec 21 marzo a domenica 23 marzo,<\/strong> all&#8217;interno della rassegna <a href=\"https:\/\/www.intoscana.it\/it\/la-democrazia-del-corpo-virgilio-sieni-reinventa-il-gesto-al-cango-di-firenze\/\" target=\"_blank\" rel=\"noopener\"><strong>La Democrazia del corpo<\/strong><\/a>, torna il riallestimento di <strong><em>&#8220;Sonate Bach. Di fronte al dolore degli altri&#8221;<\/em><\/strong>, storica creazione del 2006 tra le pi\u00f9 significative e rappresentative, di <strong>Virgilio Sieni.<\/strong><\/p>\n<p><strong>Cinque danzatori per undici coreografie<\/strong> che deflagrano nel gesto del dolore e della trasfigurazione pittorica rammentandoci altrettanti avvenimenti tragici accaduti in conflitti recenti: <strong>Sarajevo, Kigali in Rwanda, Srebrenica, Tel Aviv, Jenin, Baghdad, Istanbul, Beslan, Gaza, Bentalha, Kabul.<\/strong><\/p>\n<p><strong>Undici date emblematiche<\/strong> raccolte intorno agli undici brani che compongono le <strong>Tre\u00a0Sonate per viola e pianoforte di J.S. Bach.<\/strong><\/p>\n<figure id=\"post-378798 media-378798\" class=\"align-none\"><img decoding=\"async\" src=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/1_-VIRGILIO-SIENI-_-Sonate-Bach-_-ph.-Piero-Tauro-scaled.jpg\" alt=\"\" \/><\/figure>\n<div class=\"titleimg\">VIRGILIO SIENI, Sonate Bach, foto di Piero Tauro<\/div>\n<p><em>&#8220;Il lavoro nasce nel 2006 come riflessione sulle atroci tragedie che si abbattevano sui civili nelle guerre di quei decenni. Tutt\u2019oggi la storia perpetua questo flagello e la ripresa di Sonate Bach assume la forma di una cerimonia che destina il tempo della danza alle declinazioni del dono e della compassione. &#8211; <\/em><strong>ha scritto Virgilio Sieni <\/strong><em>&#8211; Sono 11 coreografie che deflagrano nel gesto del dolore e della pittura e ci rammentano altrettanti avvenimenti tragici accaduti nei conflitti recenti:<strong> Sarajevo, Kigali in Rwanda, Srebrenica, Tel Aviv, Jenin, Baghdad, Istanbul, Beslan, Gaza, Bentalha, Kabul.<\/strong> 11 date emblematiche raccolte intorno agli 11 brani che compongono le tre Sonate di Bach.&#8221;<\/em><div class=\"focuson\"><a href=\"https:\/\/www.intoscana.it\/it\/la-democrazia-del-corpo-virgilio-sieni-reinventa-il-gesto-al-cango-di-firenze\/\"><img decoding=\"async\" class=\"lazy\" src=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/ROBERTO-CASTELLO-_Il-sesso-degli-angeli-_-ph-Mario-Morroni-8449-b_m.jpg\" style=\"\">\n                <div class=\"cat\">La Democrazia del Corpo<\/div>\n                <h4>Tutti gli spettacoli<\/h4><\/a>\n              <\/div><\/p>\n<p><em>&#8220;Centinaia di fotografie tratte dagli archivi dei reporter di guerra hanno fornito i fotogrammi drammatici che compongono la partitura di <strong>una coreografia che assimila quelle posture cercando un approccio irrisolvibile all\u2019orrore.<\/strong> La danza qui afferma lo sforzo di evocare da queste macerie di esistenza<strong> una bellezza impossibile e paradossale,<\/strong> da cesellare con lo strumento etico e politico per eccellenza: il gesto. &#8211;<\/em><strong> prosegue Virgilio Sieni &#8211; <\/strong><em>L\u2019attenzione torna quindi alla questione del corpo, al suo significato, alla sua complessit\u00e0 e attualit\u00e0. Come ci indica Susan Sontag nel suo \u201cDavanti al dolore degli altri\u201d, la sola risposta che si offre \u00e8 ancora quella rivolta allo sguardo del pittore del \u2018300:<strong> la sublimazione della tragedia nella trasfigurazione artistica<\/strong> senza commento, che coinvolge insieme l\u2019umano e il sacro, il singolare e l\u2019universale. Le 11 danze che si succedono sono una continua dedica in memoria, riferita agli eventi che segnano iconograficamente il tessuto coreografico.&#8221;<\/em><\/p>\n<figure id=\"post-378800 media-378800\" class=\"align-none\"><img decoding=\"async\" src=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/Virgilio-Sieni-_-SONATE-BACH-_-ph.-orlando-caponnetto.jpg\" alt=\"\" \/><\/figure>\n<div class=\"titleimg\">Virgilio Sieni, SONATE BACH, foto di Orlando Caponnetto<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dal 21 al 23 marzo cinque danzatori sono impegnati in undici coreografie per raccontare il dolore in una delle creazioni pi\u00f9 significative e rappresentative della visione di Virgilio Sieni<\/p>\n","protected":false},"author":525,"featured_media":378799,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[493],"tags":[202,236],"class_list":["post-378797","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","tag-firenze","tag-teatro"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v25.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Al Cango &quot;Sonate Bach&quot; la danza di Virgilio Sieni che mette in scena l&#039;orrore della guerra - intoscana<\/title>\n<meta name=\"description\" content=\"Dal 21 al 23 marzo cinque danzatori saranno impegnati in undici coreografie per raccontare il dolore in una delle creazioni di Virgilio Sieni\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.intoscana.it\/it\/al-cango-sonate-bach-la-danza-di-virgilio-sieni-che-mette-in-scena-lorrore-della-guerra\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Al Cango &quot;Sonate Bach&quot; la danza di Virgilio Sieni che mette in scena l&#039;orrore della guerra\" \/>\n<meta property=\"og:description\" content=\"Dal 21 al 23 marzo cinque danzatori saranno impegnati in undici coreografie per raccontare il dolore in una delle creazioni di Virgilio Sieni\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.intoscana.it\/it\/al-cango-sonate-bach-la-danza-di-virgilio-sieni-che-mette-in-scena-lorrore-della-guerra\/\" \/>\n<meta property=\"og:site_name\" content=\"intoscana\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/intoscana.it\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-19T08:57:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-19T08:58:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/2.-Virgilio-Sieni-_-SONATE-BACH-_-ph.-orlando-caponnetto-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1460\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@intoscana\" \/>\n<meta name=\"twitter:site\" content=\"@intoscana\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.intoscana.it\/it\/al-cango-sonate-bach-la-danza-di-virgilio-sieni-che-mette-in-scena-lorrore-della-guerra\/\",\"url\":\"https:\/\/www.intoscana.it\/it\/al-cango-sonate-bach-la-danza-di-virgilio-sieni-che-mette-in-scena-lorrore-della-guerra\/\",\"name\":\"Al Cango \\\"Sonate Bach\\\" la danza di Virgilio Sieni che mette in scena l'orrore della guerra - intoscana\",\"isPartOf\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/al-cango-sonate-bach-la-danza-di-virgilio-sieni-che-mette-in-scena-lorrore-della-guerra\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/al-cango-sonate-bach-la-danza-di-virgilio-sieni-che-mette-in-scena-lorrore-della-guerra\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/2.-Virgilio-Sieni-_-SONATE-BACH-_-ph.-orlando-caponnetto-scaled.jpg\",\"datePublished\":\"2025-03-19T08:57:14+00:00\",\"dateModified\":\"2025-03-19T08:58:25+00:00\",\"author\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8\"},\"description\":\"Dal 21 al 23 marzo cinque danzatori saranno impegnati in undici coreografie per raccontare il dolore in una delle creazioni di Virgilio Sieni\",\"breadcrumb\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/al-cango-sonate-bach-la-danza-di-virgilio-sieni-che-mette-in-scena-lorrore-della-guerra\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.intoscana.it\/it\/al-cango-sonate-bach-la-danza-di-virgilio-sieni-che-mette-in-scena-lorrore-della-guerra\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.intoscana.it\/it\/al-cango-sonate-bach-la-danza-di-virgilio-sieni-che-mette-in-scena-lorrore-della-guerra\/#primaryimage\",\"url\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/2.-Virgilio-Sieni-_-SONATE-BACH-_-ph.-orlando-caponnetto-scaled.jpg\",\"contentUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/2.-Virgilio-Sieni-_-SONATE-BACH-_-ph.-orlando-caponnetto-scaled.jpg\",\"width\":2048,\"height\":1460},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.intoscana.it\/it\/al-cango-sonate-bach-la-danza-di-virgilio-sieni-che-mette-in-scena-lorrore-della-guerra\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.intoscana.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Al Cango &#8220;Sonate Bach&#8221; la danza di Virgilio Sieni che mette in scena l&#8217;orrore della guerra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\",\"url\":\"https:\/\/www.intoscana.it\/it\/\",\"name\":\"intoscana\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.intoscana.it\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8\",\"name\":\"Redazione\",\"url\":\"https:\/\/www.intoscana.it\/it\/author\/redazione\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Al Cango \"Sonate Bach\" la danza di Virgilio Sieni che mette in scena l'orrore della guerra - intoscana","description":"Dal 21 al 23 marzo cinque danzatori saranno impegnati in undici coreografie per raccontare il dolore in una delle creazioni di Virgilio Sieni","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.intoscana.it\/it\/al-cango-sonate-bach-la-danza-di-virgilio-sieni-che-mette-in-scena-lorrore-della-guerra\/","og_locale":"it_IT","og_type":"article","og_title":"Al Cango \"Sonate Bach\" la danza di Virgilio Sieni che mette in scena l'orrore della guerra","og_description":"Dal 21 al 23 marzo cinque danzatori saranno impegnati in undici coreografie per raccontare il dolore in una delle creazioni di Virgilio Sieni","og_url":"https:\/\/www.intoscana.it\/it\/al-cango-sonate-bach-la-danza-di-virgilio-sieni-che-mette-in-scena-lorrore-della-guerra\/","og_site_name":"intoscana","article_publisher":"https:\/\/www.facebook.com\/intoscana.it","article_published_time":"2025-03-19T08:57:14+00:00","article_modified_time":"2025-03-19T08:58:25+00:00","og_image":[{"width":2048,"height":1460,"url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/2.-Virgilio-Sieni-_-SONATE-BACH-_-ph.-orlando-caponnetto-scaled.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@intoscana","twitter_site":"@intoscana","twitter_misc":{"Written by":"Redazione","Est. reading time":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.intoscana.it\/it\/al-cango-sonate-bach-la-danza-di-virgilio-sieni-che-mette-in-scena-lorrore-della-guerra\/","url":"https:\/\/www.intoscana.it\/it\/al-cango-sonate-bach-la-danza-di-virgilio-sieni-che-mette-in-scena-lorrore-della-guerra\/","name":"Al Cango \"Sonate Bach\" la danza di Virgilio Sieni che mette in scena l'orrore della guerra - intoscana","isPartOf":{"@id":"https:\/\/www.intoscana.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.intoscana.it\/it\/al-cango-sonate-bach-la-danza-di-virgilio-sieni-che-mette-in-scena-lorrore-della-guerra\/#primaryimage"},"image":{"@id":"https:\/\/www.intoscana.it\/it\/al-cango-sonate-bach-la-danza-di-virgilio-sieni-che-mette-in-scena-lorrore-della-guerra\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/2.-Virgilio-Sieni-_-SONATE-BACH-_-ph.-orlando-caponnetto-scaled.jpg","datePublished":"2025-03-19T08:57:14+00:00","dateModified":"2025-03-19T08:58:25+00:00","author":{"@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8"},"description":"Dal 21 al 23 marzo cinque danzatori saranno impegnati in undici coreografie per raccontare il dolore in una delle creazioni di Virgilio Sieni","breadcrumb":{"@id":"https:\/\/www.intoscana.it\/it\/al-cango-sonate-bach-la-danza-di-virgilio-sieni-che-mette-in-scena-lorrore-della-guerra\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.intoscana.it\/it\/al-cango-sonate-bach-la-danza-di-virgilio-sieni-che-mette-in-scena-lorrore-della-guerra\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.intoscana.it\/it\/al-cango-sonate-bach-la-danza-di-virgilio-sieni-che-mette-in-scena-lorrore-della-guerra\/#primaryimage","url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/2.-Virgilio-Sieni-_-SONATE-BACH-_-ph.-orlando-caponnetto-scaled.jpg","contentUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/2.-Virgilio-Sieni-_-SONATE-BACH-_-ph.-orlando-caponnetto-scaled.jpg","width":2048,"height":1460},{"@type":"BreadcrumbList","@id":"https:\/\/www.intoscana.it\/it\/al-cango-sonate-bach-la-danza-di-virgilio-sieni-che-mette-in-scena-lorrore-della-guerra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.intoscana.it\/it\/"},{"@type":"ListItem","position":2,"name":"Al Cango &#8220;Sonate Bach&#8221; la danza di Virgilio Sieni che mette in scena l&#8217;orrore della guerra"}]},{"@type":"WebSite","@id":"https:\/\/www.intoscana.it\/it\/#website","url":"https:\/\/www.intoscana.it\/it\/","name":"intoscana","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intoscana.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8","name":"Redazione","url":"https:\/\/www.intoscana.it\/it\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/378797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/users\/525"}],"replies":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/comments?post=378797"}],"version-history":[{"count":5,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/378797\/revisions"}],"predecessor-version":[{"id":378819,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/378797\/revisions\/378819"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media\/378799"}],"wp:attachment":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media?parent=378797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/categories?post=378797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/tags?post=378797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}