{"id":406619,"date":"2025-11-10T11:26:10","date_gmt":"2025-11-10T10:26:10","guid":{"rendered":"https:\/\/www.intoscana.it\/it\/?p=406619"},"modified":"2025-11-10T12:07:44","modified_gmt":"2025-11-10T11:07:44","slug":"bto-borsa-turismo-online-firenze-2025","status":"publish","type":"post","link":"https:\/\/www.intoscana.it\/it\/bto-borsa-turismo-online-firenze-2025\/","title":{"rendered":"Al via BTO alla Stazione Leopolda di Firenze, due giorni per scoprire tutte le novit\u00e0 del Turismo Online"},"content":{"rendered":"<p>Marted\u00ec 11 novembre la<strong> Stazione Leopolda di Firenze<\/strong> torna a essere <strong>il cuore pulsante dell\u2019innovazione nel turismo<\/strong>: apre le porte la 17\u00aa edizione di <strong>BTO \u2013 Be Travel Onlife<\/strong>, la pi\u00f9 importante manifestazione italiana dedicata alle <strong>nuove frontiere del viaggio e dell\u2019ospitalit\u00e0 digitale.<\/strong><\/p>\n<p>Per due giorni, fino al 12 novembre, <strong>350 speaker da tutto il mondo e 90 eventi distribuiti in 7 Hall t<\/strong>rasformeranno la Leopolda in un laboratorio di idee, connessioni e visioni future.<\/p>\n<p>Il tema di quest\u2019anno, <strong><em>\u201cCross-Travel\u201d<\/em><\/strong>, invita a <strong>varcare soglie e contaminare linguaggi,<\/strong> costruendo esperienze ibride in cui <strong>la tecnologia diventa alleata dell\u2019intelligenza, dell\u2019empatia e della creativit\u00e0 umana.<\/strong><\/p>\n<p><strong>Un viaggio dentro il viaggio,<\/strong> dove il <strong>confine tra reale e digitale si dissolve<\/strong> per lasciare spazio a <strong>nuove forme di incontro e ispirazione.<\/strong><\/p>\n<p>Alle<strong> 10 si terr\u00e0 il taglio del nastro<\/strong> alla presenza del <strong>presidente della Regione Toscana Eugenio Giani,<\/strong> del presidente della Camera di Commercio di Firenze <strong>Massimo Manetti<\/strong>, del direttore scientifico di BTO 2025<strong> Francesco Tapinassi<\/strong>, del segretario generale della Camera di Commercio di Firenze <strong>Giuseppe Salvini<\/strong>, del presidente di PromoFirenze <strong>Aldo Cursano<\/strong> e del direttore di Fondazione Sistema Toscana <strong>Francesco Palumbo.<\/strong><\/p>\n<p>Subito dopo il momento inaugurale, nella Hall 5 spazio a <strong><em>\u201cDestinazione Toscana\u201d<\/em><\/strong>, il consueto appuntamento su <strong>trend e scenari del turismo regionale,<\/strong> nel quale interverranno, tra gli altri, il presidente della Regione Giani insieme ai vertici di Toscana Promozione e Fondazione Sistema Toscana e al delegato turismo Anci Toscana e sindaco di Montepulciano, Michele Angiolini.<\/p>\n<p>Da non perdere (ore 10 Hall 4 e ore 11 Hall 5), la presentazione del <strong><em>\u201cRapporto sul Turismo Enogastronomico Italiano 2025\u201d<\/em> <\/strong>curato da <strong>Roberta Garibaldi<\/strong> (presidente Associazione italiana Turismo Enogastronomico), che offrir\u00e0 una lettura aggiornata dei trend del turismo enogastronomico nel nostro Paese, con la Toscana leader su molti aspetti.<\/p>\n<p>In mattinata anche il panel <strong><em>\u201cMercati storici e Cross-Travel\u201d<\/em><\/strong> (11\/11 ore 15 Hall 4) che esplorer\u00e0 come i mercati stiano evolvendo attraverso esperienze che uniscono innovazione e rispetto delle radici. A raccontare questa trasformazione tre protagonisti d\u2019eccezione:<strong> il Mercato Storico di San Lorenzo a Firenze,<\/strong> con oltre 150 anni di storia; la <strong>Boqueria di Barcellona<\/strong> con pi\u00f9 di 300 attivit\u00e0 e 25 milioni di visitatori all\u2019anno; e il <strong>Nishiki Market di Kyoto,<\/strong> simbolo della tradizione culinaria giapponese.<\/p>\n<p>Partecipano, tra gli altri: <strong>Massimo Manetti<\/strong> (presidente Consorzio Operatori Mercato Centrale),<strong> Akira Shimizu<\/strong> (Kyoto Nishiki Market Shopping Street Promotion Association Executive Director) e <strong>Jorge Mas Velasco<\/strong> (presidente Mercat de la Boqueria).<\/p>\n<figure id=\"post-406621 media-406621\" class=\"align-none\"><img decoding=\"async\" src=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/conferenza-stampa-BTO-2023-ph-Ilaria-Costanzo-9004-2.jpg\" alt=\"\" \/><\/figure>\n<h3>La tecnologia in aiuto dell\u2019overtourism<\/h3>\n<p>Come trovare un equilibrio virtuoso tra turismo e qualit\u00e0 della vita? Pi\u00f9 che di overtourism, nel caso di Firenze si parla di <strong>unbalanced tourism:<\/strong> una concentrazione di visitatori in alcune aree e momenti, a discapito di un\u2019esperienza equilibrata e di una fruizione pi\u00f9 diffusa del territorio. Un fenomeno che riflette una tendenza nazionale, dove<strong> il 70% dei turisti stranieri si concentra su appena l\u20191% del Paese<\/strong>.<\/p>\n<p>Per invertire la rotta,<strong> il capoluogo toscano ha avviato progetti pilota<\/strong> che sfruttano strumenti digitali e strategie innovative per monitorare i flussi e dialogare in tempo reale con i visitatori suggerendo loro mete alternative, distribuendo cos\u00ec in modo pi\u00f9 armonico le presenze.<\/p>\n<p>Se ne parler\u00e0 nel panel <strong><em>\u201cSmart Florence\u201d<\/em><\/strong> in programma l\u201911 novembre ore 12 in Hall 5. Partecipano, tra gli altri: <strong>Alessandro Monti<\/strong> (Fondazione per la Ricerca e l&#8217;Innovazione dell&#8217;Universit\u00e0 di Firenze General Manager), <strong>Pio Macchiarulo<\/strong> (GetYourGuide Senior Account Manager), <strong>Laura Masi<\/strong> (Fondazione Destination Florence Presidente),<strong> Jacopo Vicini<\/strong> (Comune di Firenze, assessore allo Sviluppo Economico, Turismo, Fiere e Congressi).<\/p>\n<h3>BTO Women<\/h3>\n<p>Torna il <strong>format ideato da Clara Svanera<\/strong> (giornalista, turismo cultura e affari internazionali) per celebrare la creativit\u00e0 e la leadership delle donne che stanno trasformando il modo di viaggiare e di raccontare i territori.<\/p>\n<p><strong>Quattro i talk di BTO Women<\/strong>, questi in programma l\u201911\/11:<strong><em> \u201cRadici e Innovazione\u201d<\/em><\/strong> (ore 11 Hall #1), che vedr\u00e0 la partecipazione della <strong>chef greca Jota Koufatdaki, Alessandra Baruzzi<\/strong> (a capo delle Lady Chef italiane), <strong>Sandra Torre<\/strong> (direttrice generale del Turismo di Genova) e la <strong>Console del Messico Mar\u00eda de los \u00c1ngeles Arriola Aguirre<\/strong>, con storie di tradizioni che si aprono al futuro.<\/p>\n<p><strong><em>\u201cSfida\u201d<\/em> <\/strong>d\u00e0 voce a donne che guidano i cambiamenti verso un turismo sostenibile e percorsi di rinascita, con <strong>Ginevra Moretti<\/strong> (Castello di Sammezzano), <strong>Lina Cha<\/strong> (progetto \u201cVie di pietra che abbracciano il mare\u201d), <strong>Sandra Varaschin<\/strong> (albergo diffuso Sauris) e<strong> Francesca Chiocciolini<\/strong> (rifugio il Barbotto). Sul palco di BTO anche il <strong>Grand Tour delle Donne della Toscana<\/strong>, progetto editoriale che intreccia centinaia di storie femminili legate al turismo e al territorio (11\/11 ore 16 Hall 3).<\/p>\n<p>La prima giornata di BTO si concluder\u00e0 in musica con<strong><em> \u201cCavaller \u2013 IA Rusticana\u201d<\/em><\/strong>, il primo spettacolo in cui <strong>intelligenza artificiale ed esecuzione umana si fondono in tempo reale.<\/strong> Prodotto dal Mascagni Festival e presentato in anteprima mondiale al <strong>padiglione Italia di Expo Osaka 2025,<\/strong> unisce tecnologia e lirica in un\u2019esperienza sensoriale senza precedenti (ore 17 Hall 5).<\/p>\n<p><strong>BTO 2025<\/strong> \u00e8 promossa da <strong>Regione Toscana e Camera di Commercio di Firenze,<\/strong> e organizzata da <strong>Toscana Promozione Turistica, PromoFirenze e Fondazione Sistema Toscana.<\/strong><\/p>\n<figure id=\"post-406622 media-406622\" class=\"align-none\"><img decoding=\"async\" src=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/Francesco-Tapinassi_Direttore-BTO.jpg\" alt=\"\" \/><\/figure>\n<div class=\"titleimg\">Francesco Tapinassi Direttore BTO<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Per due giorni l&#8217;11 e 12 novembre 350 speaker da tutto il mondo e 90 eventi distribuiti in 7 Hall trasformeranno la Leopolda in un laboratorio di idee, connessioni e visioni future<\/p>\n","protected":false},"author":525,"featured_media":406620,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[494],"tags":[1525,168,151,4706],"class_list":["post-406619","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","tag-bto-buy-tourism-online","tag-fondazione-sistema-toscana","tag-regione-toscana","tag-toscana-promozione-turistica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v25.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Al via BTO alla Stazione Leopolda di Firenze, due giorni per scoprire tutte le novit\u00e0 del Turismo Online - intoscana<\/title>\n<meta name=\"description\" content=\"Per due giorni l&#039;11 e 12 novembre 350 speaker da tutto il mondo e 90 eventi distribuiti in 7 Hall trasformeranno la Leopolda in una fucina\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.intoscana.it\/it\/bto-borsa-turismo-online-firenze-2025\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Al via BTO alla Stazione Leopolda di Firenze, due giorni per scoprire tutte le novit\u00e0 del Turismo Online\" \/>\n<meta property=\"og:description\" content=\"Per due giorni l&#039;11 e 12 novembre 350 speaker da tutto il mondo e 90 eventi distribuiti in 7 Hall trasformeranno la Leopolda in una fucina\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.intoscana.it\/it\/bto-borsa-turismo-online-firenze-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"intoscana\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/intoscana.it\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-10T10:26:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-10T11:07:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/BTO_ph-Ilaria-Costanzo-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@intoscana\" \/>\n<meta name=\"twitter:site\" content=\"@intoscana\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.intoscana.it\/it\/bto-borsa-turismo-online-firenze-2025\/\",\"url\":\"https:\/\/www.intoscana.it\/it\/bto-borsa-turismo-online-firenze-2025\/\",\"name\":\"Al via BTO alla Stazione Leopolda di Firenze, due giorni per scoprire tutte le novit\u00e0 del Turismo Online - intoscana\",\"isPartOf\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/bto-borsa-turismo-online-firenze-2025\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/bto-borsa-turismo-online-firenze-2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/BTO_ph-Ilaria-Costanzo-1-1.jpg\",\"datePublished\":\"2025-11-10T10:26:10+00:00\",\"dateModified\":\"2025-11-10T11:07:44+00:00\",\"author\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8\"},\"description\":\"Per due giorni l'11 e 12 novembre 350 speaker da tutto il mondo e 90 eventi distribuiti in 7 Hall trasformeranno la Leopolda in una fucina\",\"breadcrumb\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/bto-borsa-turismo-online-firenze-2025\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.intoscana.it\/it\/bto-borsa-turismo-online-firenze-2025\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.intoscana.it\/it\/bto-borsa-turismo-online-firenze-2025\/#primaryimage\",\"url\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/BTO_ph-Ilaria-Costanzo-1-1.jpg\",\"contentUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/BTO_ph-Ilaria-Costanzo-1-1.jpg\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.intoscana.it\/it\/bto-borsa-turismo-online-firenze-2025\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.intoscana.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Al via BTO alla Stazione Leopolda di Firenze, due giorni per scoprire tutte le novit\u00e0 del Turismo Online\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\",\"url\":\"https:\/\/www.intoscana.it\/it\/\",\"name\":\"intoscana\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.intoscana.it\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8\",\"name\":\"Redazione\",\"url\":\"https:\/\/www.intoscana.it\/it\/author\/redazione\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Al via BTO alla Stazione Leopolda di Firenze, due giorni per scoprire tutte le novit\u00e0 del Turismo Online - intoscana","description":"Per due giorni l'11 e 12 novembre 350 speaker da tutto il mondo e 90 eventi distribuiti in 7 Hall trasformeranno la Leopolda in una fucina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.intoscana.it\/it\/bto-borsa-turismo-online-firenze-2025\/","og_locale":"it_IT","og_type":"article","og_title":"Al via BTO alla Stazione Leopolda di Firenze, due giorni per scoprire tutte le novit\u00e0 del Turismo Online","og_description":"Per due giorni l'11 e 12 novembre 350 speaker da tutto il mondo e 90 eventi distribuiti in 7 Hall trasformeranno la Leopolda in una fucina","og_url":"https:\/\/www.intoscana.it\/it\/bto-borsa-turismo-online-firenze-2025\/","og_site_name":"intoscana","article_publisher":"https:\/\/www.facebook.com\/intoscana.it","article_published_time":"2025-11-10T10:26:10+00:00","article_modified_time":"2025-11-10T11:07:44+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/BTO_ph-Ilaria-Costanzo-1-1.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@intoscana","twitter_site":"@intoscana","twitter_misc":{"Written by":"Redazione","Est. reading time":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.intoscana.it\/it\/bto-borsa-turismo-online-firenze-2025\/","url":"https:\/\/www.intoscana.it\/it\/bto-borsa-turismo-online-firenze-2025\/","name":"Al via BTO alla Stazione Leopolda di Firenze, due giorni per scoprire tutte le novit\u00e0 del Turismo Online - intoscana","isPartOf":{"@id":"https:\/\/www.intoscana.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.intoscana.it\/it\/bto-borsa-turismo-online-firenze-2025\/#primaryimage"},"image":{"@id":"https:\/\/www.intoscana.it\/it\/bto-borsa-turismo-online-firenze-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/BTO_ph-Ilaria-Costanzo-1-1.jpg","datePublished":"2025-11-10T10:26:10+00:00","dateModified":"2025-11-10T11:07:44+00:00","author":{"@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8"},"description":"Per due giorni l'11 e 12 novembre 350 speaker da tutto il mondo e 90 eventi distribuiti in 7 Hall trasformeranno la Leopolda in una fucina","breadcrumb":{"@id":"https:\/\/www.intoscana.it\/it\/bto-borsa-turismo-online-firenze-2025\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.intoscana.it\/it\/bto-borsa-turismo-online-firenze-2025\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.intoscana.it\/it\/bto-borsa-turismo-online-firenze-2025\/#primaryimage","url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/BTO_ph-Ilaria-Costanzo-1-1.jpg","contentUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/BTO_ph-Ilaria-Costanzo-1-1.jpg","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/www.intoscana.it\/it\/bto-borsa-turismo-online-firenze-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.intoscana.it\/it\/"},{"@type":"ListItem","position":2,"name":"Al via BTO alla Stazione Leopolda di Firenze, due giorni per scoprire tutte le novit\u00e0 del Turismo Online"}]},{"@type":"WebSite","@id":"https:\/\/www.intoscana.it\/it\/#website","url":"https:\/\/www.intoscana.it\/it\/","name":"intoscana","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intoscana.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8","name":"Redazione","url":"https:\/\/www.intoscana.it\/it\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/406619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/users\/525"}],"replies":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/comments?post=406619"}],"version-history":[{"count":5,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/406619\/revisions"}],"predecessor-version":[{"id":406646,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/406619\/revisions\/406646"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media\/406620"}],"wp:attachment":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media?parent=406619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/categories?post=406619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/tags?post=406619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}