{"id":406667,"date":"2025-11-10T12:42:54","date_gmt":"2025-11-10T11:42:54","guid":{"rendered":"https:\/\/www.intoscana.it\/it\/?p=406667"},"modified":"2025-11-10T13:09:39","modified_gmt":"2025-11-10T12:09:39","slug":"firenze-65-25-un-convegno-e-un-concerto-in-occasione-dei-160-anni-da-firenze-capitale","status":"publish","type":"post","link":"https:\/\/www.intoscana.it\/it\/firenze-65-25-un-convegno-e-un-concerto-in-occasione-dei-160-anni-da-firenze-capitale\/","title":{"rendered":"\u201cFIRENZE 65\u201325\u201d&#8221;: una giornata di storia, musica e solidariet\u00e0 in occasione dei 160 anni da Firenze Capitale"},"content":{"rendered":"<p>Il <strong>18 novembre<\/strong> 2025 Firenze ricorda i<strong> 160 anni dalla prima seduta del Parlamento del Regno d\u2019Italia<\/strong> a <strong>Palazzo Vecchio<\/strong>, che segn\u00f2 l\u2019inizio del quinquennio in cui la citt\u00e0 fu Capitale del nuovo Stato unitario.<\/p>\n<p>A celebrare l\u2019anniversario sar\u00e0 la<a href=\"https:\/\/legadelchianti.it\" target=\"_blank\" rel=\"noopener\"><strong> Lega del Chianti APS<\/strong><\/a> con <strong><em>\u201cFIRENZE 65\u201325\u201d,<\/em> <\/strong>una giornata di appuntamenti tra storia, musica e impegno civile, dedicata anche alla figura di <strong>Bettino Ricasoli, il \u201cBarone di Ferro\u201d,<\/strong> statista toscano e padre del Chianti moderno.<\/p>\n<p>L\u2019iniziativa \u2013 organizzata con il Comune e la Citt\u00e0 Metropolitana di Firenze, il <strong>Conservatorio \u201cLuigi Cherubini\u201d<\/strong> e con il patrocinio di <strong>Regione Toscana, Universit\u00e0 di Firenze<\/strong> e altre istituzioni \u2013 propone tre momenti principali in luoghi simbolici della citt\u00e0.<\/p>\n<p><strong>Sara Funaro sindaca di Firenze ha dichiarato<\/strong>: &#8220;<em>L&#8217;unit\u00e0 d&#8217;Italia \u00e8 stata all&#8217;origine di un faticoso processo educativo e formativo per vincere l&#8217;analfabetismo, promuovere la scuola e la formazione, fare della cultura un patrimonio di tutti e non un privilegio di pochi. Devo dire che assistiamo con sconcerto a forme di analfabetismo di ritorno, favorite da quell&#8217;idea di sapere che si forma in superficie con gli strumenti digitali ma che non va in profondit\u00e0. Il concerto verdiano del Conservatorio Cherubini in Palazzo Vecchio, propedeutico alla consegna delle borse di studio della Lega del Chianti, ci pone con delicatezza e fermezza al tempo stesso queste domande offrendo una risposta degna di ogni gratitudine.&#8221;<\/em><\/p>\n<p><strong>Giovanni Ricasoli-Firidolfi capitano generale e presidente della Lega del Chianti APS<\/strong> ha aggiunto: &#8220;<em>Sono felice di constatare che, a distanza di 160 anni, il mio antenato Bettino Ricasoli, dopo aver contribuito al progetto politico dell&#8217;Italia unita, continua ad essere ancora oggi una figura di raccordo per il nostro territorio, capace di costruire una sincera un&#8217;unit\u00e0 d&#8217;intenti, come dimostrano i numerosi attori istituzionali, culturali ed economici che hanno aderito a questo progetto celebrativo della Lega del Chianti APS. Con Firenze 65-25, intendiamo celebrare Firenze come capitale culturale, rinnovando anche la sua attenzione alla dimensione umana e solidale, attraverso azioni di ricaduta sociale legate alla manifestazione, come le borse di studio a sostegno della formazione artistica e la raccolta fondi a favore della Caritas Diocesana.&#8221;<\/em><\/p>\n<figure id=\"post-406669 media-406669\" class=\"align-none\"><strong><img decoding=\"async\" src=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/Chianti-Volpaia.jpg\" alt=\"\" \/><\/strong><\/figure>\n<div class=\"titleimg\">Chianti<\/div>\n<h3>Il programma: un convegno, un concerto e una serata di solidariet\u00e0<\/h3>\n<p>Nella <strong>Sala Luca Giordano<\/strong> (ore 9.30) si terr\u00e0 il convegno <strong><em>\u201cFirenze Capitale e il futuro del paesaggio\u201d,<\/em><\/strong> con interventi di storici e studiosi (Sandro Rogari, Zeffiro Ciuffoletti, Marco Frati, Francesco Cotana) e una tavola rotonda su \u201c<strong><em>Firenze e il Chianti di domani\u201d,<\/em> <\/strong>moderata da Marco Hagge.<\/p>\n<p>L\u2019evento, trasmesso in streaming, rifletter\u00e0 sull\u2019eredit\u00e0 di <strong>Firenze Capitale<\/strong> e sulle sfide attuali di tutela e sostenibilit\u00e0 del territorio.<\/p>\n<p>Nel <strong>Salone dei Cinquecento<\/strong> (ore 19) il luogo dove nel 1865 si riun\u00ec il Parlamento italiano, il <strong>Conservatorio \u201cCherubini\u201d render\u00e0 omaggio a Giuseppe Verdi<\/strong>, simbolo musicale del Risorgimento.<\/p>\n<p>Condotto da Annamaria Tossani con la partecipazione del<strong> divulgatore Wikipedro,<\/strong> il concerto premier\u00e0 anche quattro giovani musicisti con le borse di studio \u201cLega del Chianti APS \u2013 Formazione\u201d.<\/p>\n<p>La giornata si concluder\u00e0 al<strong> Circolo dell&#8217;Unione<\/strong> (ore 20.30) con una <strong>cena benefica a favore della Caritas Diocesana di Firenze,<\/strong> destinata a sostenere progetti per la terza et\u00e0.<\/p>\n<p><strong>\u201cFIRENZE 65\u201325\u201d<\/strong> non vuole essere solo una commemorazione, ma un invito a rileggere il ruolo civile e culturale di Firenze Capitale e a guardare al futuro con lo spirito innovatore di Ricasoli, tra identit\u00e0, territorio e responsabilit\u00e0 sociale.<\/p>\n<h3>Gli eventi sono ad ingresso libero previa prenotazione online<\/h3>\n<p>Convegno <a href=\"https:\/\/my.weezevent.com\/convegno-firenze-65-25\" target=\"_blank\" rel=\"noopener\"><strong>https:\/\/my.weezevent.com\/convegno-firenze-65-25<\/strong><\/a><br \/>\nConcerto <a href=\"https:\/\/my.weezevent.com\/convegno-firenze-65-25\" target=\"_blank\" rel=\"noopener\"><strong>https:\/\/my.weezevent.com\/concerto-viva-verdi<\/strong><\/a><\/p>\n<figure id=\"post-406668 media-406668\" class=\"align-none\"><img decoding=\"async\" src=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/Bettino-Ricasoli-scaled.jpg\" alt=\"\" \/><\/figure>\n<p>Bettino Ricasoli<\/p>\n<h3>La Lega del Chianti<\/h3>\n<p>Fondata nel XIII secolo dalla<strong> Repubblica Fiorentina<\/strong> come sodalizio militare a difesa dei castelli e delle popolazioni del Chianti durante le guerre con Siena, l<strong>a Lega del Chianti<\/strong> divenne successivamente l\u2019organo amministrativo e giudiziario del territorio, organizzato nei tre<strong> Terzieri storici di Radda, Gaiole e Castellina.<\/strong><\/p>\n<p><strong>Sciolta nel 1774 dal Granduca Pietro Leopoldo<\/strong> nell\u2019ambito della modernizzazione del Granducato,<strong> la Lega rinacque nel 1970<\/strong> grazie ai discendenti delle antiche famiglie chiantigiane e ai nuovi proprietari dei castelli, con l\u2019obiettivo di valorizzare e promuovere la \u201cTerra del Chianti\u201d in Italia e nel mondo.<\/p>\n<p>Nel corso degli ultimi cinquant\u2019anni, <strong>la Lega ha sviluppato una rete di rappresentanze in Italia e all\u2019estero,<\/strong> collaborando con istituzioni pubbliche e private per diffondere l\u2019identit\u00e0, la cultura e il patrimonio di un territorio simbolo della perfetta<strong> armonia tra uomo, paesaggio e cultura del vino.<\/strong><\/p>\n<p><strong>Dal 2021, con la riforma del Terzo Settore<\/strong>, la Lega del Chianti \u00e8 divenuta <strong>Associazione di Promozione Sociale (APS),<\/strong> ampliando la propria missione a iniziative di valore e ricaduta sociale.<\/p>\n<p>La missione della Lega del Chianti si fonda su tre direttrici principali. Da sempre impegnata nella <strong>tutela del paesaggio,<\/strong> la Lega si \u00e8 fatta portavoce della difesa del territorio chiantigiano, opponendosi alla cementificazione e promuovendo la valorizzazione delle sue risorse naturali e paesaggistiche, in Italia e all\u2019estero.<\/p>\n<p>Allo stesso tempo, l\u2019associazione \u00e8 fortemente <strong>attiva sul piano culturale, sostenendo progetti di restauro, ricerca e divulgazione,<\/strong> e sostenendo la candidatura UNESCO<strong><em> \u201cIl sistema delle ville-fattoria nel Chianti Classico\u201d,<\/em> <\/strong>promossa dalle istituzioni locali e nazionali.<\/p>\n<p>Infine, con la recente trasformazione in APS, la Lega del Chianti ha ampliato il proprio<strong> impegno al settore sociale,<\/strong> promuovendo iniziative a favore delle comunit\u00e0 locali.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marted\u00ec 18 novembre un convegno, un concerto e un cena di beneficienza per celebrare l\u2019anniversario del Parlamento a Palazzo Vecchio a Firenze<\/p>\n","protected":false},"author":525,"featured_media":406670,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[494],"tags":[4474,202,151],"class_list":["post-406667","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","tag-eventi","tag-firenze","tag-regione-toscana"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v25.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u201cFIRENZE 65\u201325\u201d&quot;: una giornata di storia, musica e solidariet\u00e0 in occasione dei 160 anni da Firenze Capitale - intoscana<\/title>\n<meta name=\"description\" content=\"Marted\u00ec 18 novembre una giornata di storia, musica e solidariet\u00e0 per celebrare l\u2019anniversario del Parlamento a Palazzo Vecchio a Firenze\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.intoscana.it\/it\/firenze-65-25-un-convegno-e-un-concerto-in-occasione-dei-160-anni-da-firenze-capitale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cFIRENZE 65\u201325\u201d&quot;: una giornata di storia, musica e solidariet\u00e0 in occasione dei 160 anni da Firenze Capitale\" \/>\n<meta property=\"og:description\" content=\"Marted\u00ec 18 novembre una giornata di storia, musica e solidariet\u00e0 per celebrare l\u2019anniversario del Parlamento a Palazzo Vecchio a Firenze\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.intoscana.it\/it\/firenze-65-25-un-convegno-e-un-concerto-in-occasione-dei-160-anni-da-firenze-capitale\/\" \/>\n<meta property=\"og:site_name\" content=\"intoscana\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/intoscana.it\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-10T11:42:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-10T12:09:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/Coro-Conservatorio-Cherubini-DSC09606-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@intoscana\" \/>\n<meta name=\"twitter:site\" content=\"@intoscana\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.intoscana.it\/it\/firenze-65-25-un-convegno-e-un-concerto-in-occasione-dei-160-anni-da-firenze-capitale\/\",\"url\":\"https:\/\/www.intoscana.it\/it\/firenze-65-25-un-convegno-e-un-concerto-in-occasione-dei-160-anni-da-firenze-capitale\/\",\"name\":\"\u201cFIRENZE 65\u201325\u201d\\\": una giornata di storia, musica e solidariet\u00e0 in occasione dei 160 anni da Firenze Capitale - intoscana\",\"isPartOf\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/firenze-65-25-un-convegno-e-un-concerto-in-occasione-dei-160-anni-da-firenze-capitale\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/firenze-65-25-un-convegno-e-un-concerto-in-occasione-dei-160-anni-da-firenze-capitale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/Coro-Conservatorio-Cherubini-DSC09606-1.jpg\",\"datePublished\":\"2025-11-10T11:42:54+00:00\",\"dateModified\":\"2025-11-10T12:09:39+00:00\",\"author\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8\"},\"description\":\"Marted\u00ec 18 novembre una giornata di storia, musica e solidariet\u00e0 per celebrare l\u2019anniversario del Parlamento a Palazzo Vecchio a Firenze\",\"breadcrumb\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/firenze-65-25-un-convegno-e-un-concerto-in-occasione-dei-160-anni-da-firenze-capitale\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.intoscana.it\/it\/firenze-65-25-un-convegno-e-un-concerto-in-occasione-dei-160-anni-da-firenze-capitale\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.intoscana.it\/it\/firenze-65-25-un-convegno-e-un-concerto-in-occasione-dei-160-anni-da-firenze-capitale\/#primaryimage\",\"url\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/Coro-Conservatorio-Cherubini-DSC09606-1.jpg\",\"contentUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/Coro-Conservatorio-Cherubini-DSC09606-1.jpg\",\"width\":1500,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.intoscana.it\/it\/firenze-65-25-un-convegno-e-un-concerto-in-occasione-dei-160-anni-da-firenze-capitale\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.intoscana.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cFIRENZE 65\u201325\u201d&#8221;: una giornata di storia, musica e solidariet\u00e0 in occasione dei 160 anni da Firenze Capitale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\",\"url\":\"https:\/\/www.intoscana.it\/it\/\",\"name\":\"intoscana\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.intoscana.it\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8\",\"name\":\"Redazione\",\"url\":\"https:\/\/www.intoscana.it\/it\/author\/redazione\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u201cFIRENZE 65\u201325\u201d\": una giornata di storia, musica e solidariet\u00e0 in occasione dei 160 anni da Firenze Capitale - intoscana","description":"Marted\u00ec 18 novembre una giornata di storia, musica e solidariet\u00e0 per celebrare l\u2019anniversario del Parlamento a Palazzo Vecchio a Firenze","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.intoscana.it\/it\/firenze-65-25-un-convegno-e-un-concerto-in-occasione-dei-160-anni-da-firenze-capitale\/","og_locale":"it_IT","og_type":"article","og_title":"\u201cFIRENZE 65\u201325\u201d\": una giornata di storia, musica e solidariet\u00e0 in occasione dei 160 anni da Firenze Capitale","og_description":"Marted\u00ec 18 novembre una giornata di storia, musica e solidariet\u00e0 per celebrare l\u2019anniversario del Parlamento a Palazzo Vecchio a Firenze","og_url":"https:\/\/www.intoscana.it\/it\/firenze-65-25-un-convegno-e-un-concerto-in-occasione-dei-160-anni-da-firenze-capitale\/","og_site_name":"intoscana","article_publisher":"https:\/\/www.facebook.com\/intoscana.it","article_published_time":"2025-11-10T11:42:54+00:00","article_modified_time":"2025-11-10T12:09:39+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/Coro-Conservatorio-Cherubini-DSC09606-1.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@intoscana","twitter_site":"@intoscana","twitter_misc":{"Written by":"Redazione","Est. reading time":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.intoscana.it\/it\/firenze-65-25-un-convegno-e-un-concerto-in-occasione-dei-160-anni-da-firenze-capitale\/","url":"https:\/\/www.intoscana.it\/it\/firenze-65-25-un-convegno-e-un-concerto-in-occasione-dei-160-anni-da-firenze-capitale\/","name":"\u201cFIRENZE 65\u201325\u201d\": una giornata di storia, musica e solidariet\u00e0 in occasione dei 160 anni da Firenze Capitale - intoscana","isPartOf":{"@id":"https:\/\/www.intoscana.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.intoscana.it\/it\/firenze-65-25-un-convegno-e-un-concerto-in-occasione-dei-160-anni-da-firenze-capitale\/#primaryimage"},"image":{"@id":"https:\/\/www.intoscana.it\/it\/firenze-65-25-un-convegno-e-un-concerto-in-occasione-dei-160-anni-da-firenze-capitale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/Coro-Conservatorio-Cherubini-DSC09606-1.jpg","datePublished":"2025-11-10T11:42:54+00:00","dateModified":"2025-11-10T12:09:39+00:00","author":{"@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8"},"description":"Marted\u00ec 18 novembre una giornata di storia, musica e solidariet\u00e0 per celebrare l\u2019anniversario del Parlamento a Palazzo Vecchio a Firenze","breadcrumb":{"@id":"https:\/\/www.intoscana.it\/it\/firenze-65-25-un-convegno-e-un-concerto-in-occasione-dei-160-anni-da-firenze-capitale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.intoscana.it\/it\/firenze-65-25-un-convegno-e-un-concerto-in-occasione-dei-160-anni-da-firenze-capitale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.intoscana.it\/it\/firenze-65-25-un-convegno-e-un-concerto-in-occasione-dei-160-anni-da-firenze-capitale\/#primaryimage","url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/Coro-Conservatorio-Cherubini-DSC09606-1.jpg","contentUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/Coro-Conservatorio-Cherubini-DSC09606-1.jpg","width":1500,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.intoscana.it\/it\/firenze-65-25-un-convegno-e-un-concerto-in-occasione-dei-160-anni-da-firenze-capitale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.intoscana.it\/it\/"},{"@type":"ListItem","position":2,"name":"\u201cFIRENZE 65\u201325\u201d&#8221;: una giornata di storia, musica e solidariet\u00e0 in occasione dei 160 anni da Firenze Capitale"}]},{"@type":"WebSite","@id":"https:\/\/www.intoscana.it\/it\/#website","url":"https:\/\/www.intoscana.it\/it\/","name":"intoscana","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intoscana.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8","name":"Redazione","url":"https:\/\/www.intoscana.it\/it\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/406667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/users\/525"}],"replies":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/comments?post=406667"}],"version-history":[{"count":6,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/406667\/revisions"}],"predecessor-version":[{"id":406693,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/406667\/revisions\/406693"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media\/406670"}],"wp:attachment":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media?parent=406667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/categories?post=406667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/tags?post=406667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}