{"id":412080,"date":"2026-01-05T12:33:02","date_gmt":"2026-01-05T11:33:02","guid":{"rendered":"https:\/\/www.intoscana.it\/it\/?p=412080"},"modified":"2026-01-05T12:33:02","modified_gmt":"2026-01-05T11:33:02","slug":"firenze-concluso-il-restauro-della-cappella-corsini-tornano-allantico-splendore-i-marmi-del-foggini","status":"publish","type":"post","link":"https:\/\/www.intoscana.it\/it\/firenze-concluso-il-restauro-della-cappella-corsini-tornano-allantico-splendore-i-marmi-del-foggini\/","title":{"rendered":"Firenze, concluso il restauro della Cappella Corsini: tornano all&#8217;antico splendore i marmi del Foggini"},"content":{"rendered":"<p>Conclusi i lavori di restauro della <strong>Cappella Corsini nella Basilica di Santa Maria del Carmine a Firenze<\/strong>: mesi di lavori che hanno riportato all&#8217;antica bellezza i marmi e le decorazione del capolavoro di <strong>Giovan Battista Foggini<\/strong>.<\/p>\n<figure id=\"post-412083 media-412083\" class=\"align-none\"><img decoding=\"async\" src=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/IMG-20251216-WA0010.jpg\" alt=\"\" \/><\/figure>\n<div class=\"titleimg\">Cappella Corsini<\/div>\n<p>La presentazione del restauro \u00e8 in programma il<strong> 7 gennaio 2026 <\/strong>con la solenne ricorrenza di Santo Andrea Corsini. L&#8217;intervento, come rende noto la Soprintendenza, rappresenta un traguardo importante nel piano dei restauri \u00a0del patrimonio artistico fiorentino delle chiese del Fondo Edifici di Culto finanziato con il <strong>Pnrr<\/strong>.\u00a0 L&#8217;importo complessivo stanziato \u00e8 di circa 3 milioni di euro, destinati al restauro delle superfici lapidee e decorate delle cappelle del transetto, alla messa in sicurezza e all&#8217;adeguamento impiantistico della sagrestia.<\/p>\n<p>Nel dettaglio, il recupero della Cappella Corsini ha richiesto un investimento di <strong>circa 600.000 euro<\/strong> per la <mark>pulitura delle superfici lapidee, il consolidamento delle fratture con iniezioni di resina epossi-acrilica e stuccature con polveri di marmo e il rifacimento del sistema di illuminazione e il restauro degli infissi piombati.<\/mark><\/p>\n<figure id=\"post-412082 media-412082\" class=\"align-none\"><img decoding=\"async\" src=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/IMG-20251216-WA0009.jpg\" alt=\"\" \/><\/figure>\n<div class=\"titleimg\">Cappella Corsini<\/div>\n<h3><em>La storia<\/em><\/h3>\n<p>La Cappella Corsini fu costruita per onorare la memoria di <strong>Andrea Corsini<\/strong>, vescovo di Fiesole dal 1350. Sebbene il Santo desiderasse essere tumulato al Carmine, alla sua morte, avvenuta nel 1374, fu inizialmente sepolto a Fiesole. <mark>La leggenda narra che i religiosi, con l&#8217;assenso del fratello Neri, ne trafugarono il corpo la notte del 2 febbraio per riportarlo a Firenze.<\/mark> Dopo secoli in un monumento pi\u00f9 modesto, nel 1653 i Corsini acquistarono la cappella nel transetto sinistro. I lavori, affidati nel 1675 all&#8217;architetto Pier Francesco Silvani, furono completati nel 1683.<\/p>\n<p>Il compito di celebrare il Santo fu affidato a <strong>Giovan Battista Foggini<\/strong>, che introdusse a Firenze un linguaggio nuovo, in rottura con la tradizione locale, con uno stile barocco dinamico e teatrale. Tre i suoi pi\u00f9 celebri altorilievi marmorei (1683-1687) &#8211;\u00a0 <em>L&#8217;Apparizione della Madonna, Sant&#8217;Andrea in gloria e il capolavoro Sant&#8217;Andrea alla battaglia di Anghiari<\/em> -. che ora tornano al loro pieno slendore.<\/p>\n<p>A completare l&#8217;opera \u00e8 la cupola affrescata da <strong>Luca Giordano<\/strong> nel 1682, restaurata negli anni &#8217;80, che dopo i lavori \u00e8 ora in perfetta armonia cromatica con i marmi puliti e la nuova illuminazione.<\/p>\n<figure id=\"post-412085 media-412085\" class=\"align-none\"><img decoding=\"async\" src=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/IMG-20251216-WA0011.jpg\" alt=\"\" \/><\/figure>\n<div class=\"titleimg\">Cappella Corsini<\/div>\n<p>Le celebrazioni avranno inizio alle ore 1 con la Santa Messa solenne presieduta dal vescovo di Fiesole, Stefano Manetti, alla presenza dei discendenti della famiglia Corsini.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lavori nella Basilica di Santa Maria del Carmine eseguiti con fondi Pnrr: pulite le superfici lapidee, riparate le\u00a0 fratture e un nuovo sistema di illuminazione per valorizzare il capolavoro del barocco<\/p>\n","protected":false},"author":525,"featured_media":412084,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[493],"tags":[174,202,5246],"class_list":["post-412080","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","tag-arte","tag-firenze","tag-restauro"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v25.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Firenze, concluso il restauro della Cappella Corsini: tornano all&#039;antico splendore i marmi del Foggini - intoscana<\/title>\n<meta name=\"description\" content=\"Lavori nella Basilica di Santa Maria del Carmine eseguiti con fondi Pnrr: pulite le superfici lapidee, riparate le\u00a0 fratture e un nuovo sistema di illuminazione per valorizzare il capolavoro del barocco dedicato al vescovo di Fiesole\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.intoscana.it\/it\/firenze-concluso-il-restauro-della-cappella-corsini-tornano-allantico-splendore-i-marmi-del-foggini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Firenze, concluso il restauro della Cappella Corsini: tornano all&#039;antico splendore i marmi del Foggini\" \/>\n<meta property=\"og:description\" content=\"Lavori nella Basilica di Santa Maria del Carmine eseguiti con fondi Pnrr: pulite le superfici lapidee, riparate le\u00a0 fratture e un nuovo sistema di illuminazione per valorizzare il capolavoro del barocco dedicato al vescovo di Fiesole\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.intoscana.it\/it\/firenze-concluso-il-restauro-della-cappella-corsini-tornano-allantico-splendore-i-marmi-del-foggini\/\" \/>\n<meta property=\"og:site_name\" content=\"intoscana\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/intoscana.it\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-05T11:33:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/IMG-20251216-WA0013-e1767611055682.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"808\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@intoscana\" \/>\n<meta name=\"twitter:site\" content=\"@intoscana\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.intoscana.it\/it\/firenze-concluso-il-restauro-della-cappella-corsini-tornano-allantico-splendore-i-marmi-del-foggini\/\",\"url\":\"https:\/\/www.intoscana.it\/it\/firenze-concluso-il-restauro-della-cappella-corsini-tornano-allantico-splendore-i-marmi-del-foggini\/\",\"name\":\"Firenze, concluso il restauro della Cappella Corsini: tornano all'antico splendore i marmi del Foggini - intoscana\",\"isPartOf\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/firenze-concluso-il-restauro-della-cappella-corsini-tornano-allantico-splendore-i-marmi-del-foggini\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/firenze-concluso-il-restauro-della-cappella-corsini-tornano-allantico-splendore-i-marmi-del-foggini\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/IMG-20251216-WA0013-e1767611055682.jpg\",\"datePublished\":\"2026-01-05T11:33:02+00:00\",\"author\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8\"},\"description\":\"Lavori nella Basilica di Santa Maria del Carmine eseguiti con fondi Pnrr: pulite le superfici lapidee, riparate le\u00a0 fratture e un nuovo sistema di illuminazione per valorizzare il capolavoro del barocco dedicato al vescovo di Fiesole\",\"breadcrumb\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/firenze-concluso-il-restauro-della-cappella-corsini-tornano-allantico-splendore-i-marmi-del-foggini\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.intoscana.it\/it\/firenze-concluso-il-restauro-della-cappella-corsini-tornano-allantico-splendore-i-marmi-del-foggini\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.intoscana.it\/it\/firenze-concluso-il-restauro-della-cappella-corsini-tornano-allantico-splendore-i-marmi-del-foggini\/#primaryimage\",\"url\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/IMG-20251216-WA0013-e1767611055682.jpg\",\"contentUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/IMG-20251216-WA0013-e1767611055682.jpg\",\"width\":1200,\"height\":808},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.intoscana.it\/it\/firenze-concluso-il-restauro-della-cappella-corsini-tornano-allantico-splendore-i-marmi-del-foggini\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.intoscana.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Firenze, concluso il restauro della Cappella Corsini: tornano all&#8217;antico splendore i marmi del Foggini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\",\"url\":\"https:\/\/www.intoscana.it\/it\/\",\"name\":\"intoscana\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.intoscana.it\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8\",\"name\":\"Redazione\",\"url\":\"https:\/\/www.intoscana.it\/it\/author\/redazione\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Firenze, concluso il restauro della Cappella Corsini: tornano all'antico splendore i marmi del Foggini - intoscana","description":"Lavori nella Basilica di Santa Maria del Carmine eseguiti con fondi Pnrr: pulite le superfici lapidee, riparate le\u00a0 fratture e un nuovo sistema di illuminazione per valorizzare il capolavoro del barocco dedicato al vescovo di Fiesole","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.intoscana.it\/it\/firenze-concluso-il-restauro-della-cappella-corsini-tornano-allantico-splendore-i-marmi-del-foggini\/","og_locale":"it_IT","og_type":"article","og_title":"Firenze, concluso il restauro della Cappella Corsini: tornano all'antico splendore i marmi del Foggini","og_description":"Lavori nella Basilica di Santa Maria del Carmine eseguiti con fondi Pnrr: pulite le superfici lapidee, riparate le\u00a0 fratture e un nuovo sistema di illuminazione per valorizzare il capolavoro del barocco dedicato al vescovo di Fiesole","og_url":"https:\/\/www.intoscana.it\/it\/firenze-concluso-il-restauro-della-cappella-corsini-tornano-allantico-splendore-i-marmi-del-foggini\/","og_site_name":"intoscana","article_publisher":"https:\/\/www.facebook.com\/intoscana.it","article_published_time":"2026-01-05T11:33:02+00:00","og_image":[{"width":1200,"height":808,"url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/IMG-20251216-WA0013-e1767611055682.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@intoscana","twitter_site":"@intoscana","twitter_misc":{"Written by":"Redazione","Est. reading time":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.intoscana.it\/it\/firenze-concluso-il-restauro-della-cappella-corsini-tornano-allantico-splendore-i-marmi-del-foggini\/","url":"https:\/\/www.intoscana.it\/it\/firenze-concluso-il-restauro-della-cappella-corsini-tornano-allantico-splendore-i-marmi-del-foggini\/","name":"Firenze, concluso il restauro della Cappella Corsini: tornano all'antico splendore i marmi del Foggini - intoscana","isPartOf":{"@id":"https:\/\/www.intoscana.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.intoscana.it\/it\/firenze-concluso-il-restauro-della-cappella-corsini-tornano-allantico-splendore-i-marmi-del-foggini\/#primaryimage"},"image":{"@id":"https:\/\/www.intoscana.it\/it\/firenze-concluso-il-restauro-della-cappella-corsini-tornano-allantico-splendore-i-marmi-del-foggini\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/IMG-20251216-WA0013-e1767611055682.jpg","datePublished":"2026-01-05T11:33:02+00:00","author":{"@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8"},"description":"Lavori nella Basilica di Santa Maria del Carmine eseguiti con fondi Pnrr: pulite le superfici lapidee, riparate le\u00a0 fratture e un nuovo sistema di illuminazione per valorizzare il capolavoro del barocco dedicato al vescovo di Fiesole","breadcrumb":{"@id":"https:\/\/www.intoscana.it\/it\/firenze-concluso-il-restauro-della-cappella-corsini-tornano-allantico-splendore-i-marmi-del-foggini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.intoscana.it\/it\/firenze-concluso-il-restauro-della-cappella-corsini-tornano-allantico-splendore-i-marmi-del-foggini\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.intoscana.it\/it\/firenze-concluso-il-restauro-della-cappella-corsini-tornano-allantico-splendore-i-marmi-del-foggini\/#primaryimage","url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/IMG-20251216-WA0013-e1767611055682.jpg","contentUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/IMG-20251216-WA0013-e1767611055682.jpg","width":1200,"height":808},{"@type":"BreadcrumbList","@id":"https:\/\/www.intoscana.it\/it\/firenze-concluso-il-restauro-della-cappella-corsini-tornano-allantico-splendore-i-marmi-del-foggini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.intoscana.it\/it\/"},{"@type":"ListItem","position":2,"name":"Firenze, concluso il restauro della Cappella Corsini: tornano all&#8217;antico splendore i marmi del Foggini"}]},{"@type":"WebSite","@id":"https:\/\/www.intoscana.it\/it\/#website","url":"https:\/\/www.intoscana.it\/it\/","name":"intoscana","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intoscana.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8","name":"Redazione","url":"https:\/\/www.intoscana.it\/it\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/412080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/users\/525"}],"replies":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/comments?post=412080"}],"version-history":[{"count":5,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/412080\/revisions"}],"predecessor-version":[{"id":412093,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/412080\/revisions\/412093"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media\/412084"}],"wp:attachment":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media?parent=412080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/categories?post=412080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/tags?post=412080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}