{"id":414710,"date":"2026-01-27T09:49:55","date_gmt":"2026-01-27T08:49:55","guid":{"rendered":"https:\/\/www.intoscana.it\/it\/?p=414710"},"modified":"2026-01-28T14:28:39","modified_gmt":"2026-01-28T13:28:39","slug":"firenze-saluta-rocco-commisso-il-duomo-gremito-per-la-messa-in-suffragio","status":"publish","type":"post","link":"https:\/\/www.intoscana.it\/it\/firenze-saluta-rocco-commisso-il-duomo-gremito-per-la-messa-in-suffragio\/","title":{"rendered":"Firenze saluta Rocco Commisso: il Duomo gremito per la messa in suffragio"},"content":{"rendered":"<p>Un Duomo colmo di silenzio, commozione e partecipazione ha accolto ieri sera la messa in suffragio per <strong>Rocco Commisso<\/strong>, presidente della <strong>Fiorentina<\/strong> scomparso il 16 gennaio, celebrata nella cattedrale di Santa Maria del Fiore. <strong>Oltre duemila persone<\/strong> hanno voluto rendere omaggio a una figura che ha segnato profondamente non solo la storia recente del club viola, ma anche la vita civile e sportiva della citt\u00e0.<\/p>\n<p>Accanto alla famiglia \u2013 <strong>la moglie Catherine e il figlio Joseph<\/strong> \u2013 erano presenti la dirigenza della Fiorentina,<strong> la prima squadra<\/strong>, numerose personalit\u00e0 istituzionali e del mondo del calcio. Tra questi il presidente della<strong> FIGC Gabriele Gravina<\/strong>, l\u2019amministratore delegato della Lega Serie A <strong>Luigi De Siervo<\/strong>, il presidente della Lega Pro <strong>Matteo Marani,<\/strong> il ministro per lo Sport <strong>Andrea Abodi<\/strong>, il presidente della Regione Toscana <strong>Eugenio Giani,<\/strong> la sindaca di Firenze<strong> Sara Funaro,<\/strong> l\u2019ex sindaco ed europarlamentare Dario Nardella, oltre a dirigenti sportivi, imprenditori, ex calciatori viola come <strong>Borja Valero, S\u00e9bastien Frey e Manuel Pasqual<\/strong>.<\/p>\n<p>Un momento di forte intensit\u00e0 emotiva \u00e8 stato rappresentato dall\u2019omelia del cardinale Giuseppe Betori, gi\u00e0 arcivescovo di Firenze, che ha ricordato la vita di Commisso come un &#8220;<em>molteplice servizio<\/em>&#8221; alla famiglia, al lavoro, all\u2019impegno sociale e allo sport. Betori ha rievocato anche il legame tra Commisso e il <strong>Viola Park<\/strong>, simbolo concreto della sua visione: un progetto che unisce dimensione sportiva, educativa e spirituale, con la presenza di una cappella voluta dalla famiglia Commisso all\u2019interno del centro sportivo.<\/p>\n<figure id=\"post-414711 media-414711\" class=\"align-none\"><img decoding=\"async\" src=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/messa-commiato-commisso.jpg\" alt=\"\" \/><\/figure>\n<div class=\"titleimg\">\u00a9 ACF Fiorentina<\/div>\n<p>Numerose e toccanti le testimonianze. Il presidente del Pisa Giuseppe Corrado ha sottolineato la visione industriale e strutturale del progetto sportivo di Commisso, mentre Emma Severini, calciatrice della Fiorentina femminile, lo ha ricordato <strong>come un esempio per il calcio femminile<\/strong> e per la citt\u00e0, capace di creare un rapporto umano diretto e autentico con atlete e staff.<\/p>\n<p>Particolarmente intensa anche la testimonianza del difensore viola <strong>Pietro Comuzzo<\/strong>, che ha definito Commisso &#8220;<strong><em>come un secondo pap\u00e0<\/em><\/strong>&#8220;, ricordando la sua vicinanza personale nei momenti pi\u00f9 difficili e la sua capacit\u00e0 di essere sempre presente con un gesto semplice: una stretta di mano, un sorriso, una parola di incoraggiamento.<\/p>\n<p>Commoventi le parole della moglie Catherine, che ha tracciato un <strong>ritratto umano e spirituale del marito<\/strong>: un uomo legato ai valori della famiglia, del lavoro, della fede e della comunit\u00e0. &#8220;<em>Continueremo a portare avanti ci\u00f2 che lui ha iniziato a fare con la stessa determinazione e con lo stesso amore<\/em>&#8220;, ha detto, ricordando il lungo cammino di vita condiviso e il legame profondo con Firenze e con la Fiorentina. Un legame reso concreto dal Rocco B. Commisso Viola Park, definito come \u201cuna casa\u201d per il club e per tutte le sue squadre.<\/p>\n<p>Il figlio <strong>Joseph Commisso<\/strong> ha affidato alla cattedrale un messaggio che \u00e8 insieme promessa e visione: &#8220;<em>Sotto la nostra guida continueremo<strong> a costruire la Fiorentina<\/strong>, con visione, disciplina e rispetto per Firenze e per i tifosi<\/em>&#8220;. Parole accolte da lunghi applausi, che hanno suggellato un impegno di continuit\u00e0 nel nome del padre e nel segno di un legame profondo con la citt\u00e0.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Familiari, istituzioni, mondo dello sport e oltre duemila persone nella cattedrale di Santa Maria del Fiore per l\u2019ultimo omaggio al presidente della Fiorentina. Parole di fede, memoria e impegno per il futuro<\/p>\n","protected":false},"author":507,"featured_media":414712,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[494],"tags":[199,202],"class_list":["post-414710","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","tag-fiorentina","tag-firenze"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v25.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Firenze saluta Rocco Commisso: il Duomo gremito per la messa in suffragio - intoscana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.intoscana.it\/it\/firenze-saluta-rocco-commisso-il-duomo-gremito-per-la-messa-in-suffragio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Firenze saluta Rocco Commisso: il Duomo gremito per la messa in suffragio\" \/>\n<meta property=\"og:description\" content=\"Familiari, istituzioni, mondo dello sport e oltre duemila persone nella cattedrale di Santa Maria del Fiore per l\u2019ultimo omaggio al presidente della Fiorentina. Parole di fede, memoria e impegno per il futuro\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.intoscana.it\/it\/firenze-saluta-rocco-commisso-il-duomo-gremito-per-la-messa-in-suffragio\/\" \/>\n<meta property=\"og:site_name\" content=\"intoscana\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/intoscana.it\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-27T08:49:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-28T13:28:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/messa-commiato-commisso-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1638\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chiara Bianchini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@intoscana\" \/>\n<meta name=\"twitter:site\" content=\"@intoscana\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chiara Bianchini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.intoscana.it\/it\/firenze-saluta-rocco-commisso-il-duomo-gremito-per-la-messa-in-suffragio\/\",\"url\":\"https:\/\/www.intoscana.it\/it\/firenze-saluta-rocco-commisso-il-duomo-gremito-per-la-messa-in-suffragio\/\",\"name\":\"Firenze saluta Rocco Commisso: il Duomo gremito per la messa in suffragio - intoscana\",\"isPartOf\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/firenze-saluta-rocco-commisso-il-duomo-gremito-per-la-messa-in-suffragio\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/firenze-saluta-rocco-commisso-il-duomo-gremito-per-la-messa-in-suffragio\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/messa-commiato-commisso-1.jpg\",\"datePublished\":\"2026-01-27T08:49:55+00:00\",\"dateModified\":\"2026-01-28T13:28:39+00:00\",\"author\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/010af92117f50561886339ad5b873a41\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/firenze-saluta-rocco-commisso-il-duomo-gremito-per-la-messa-in-suffragio\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.intoscana.it\/it\/firenze-saluta-rocco-commisso-il-duomo-gremito-per-la-messa-in-suffragio\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.intoscana.it\/it\/firenze-saluta-rocco-commisso-il-duomo-gremito-per-la-messa-in-suffragio\/#primaryimage\",\"url\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/messa-commiato-commisso-1.jpg\",\"contentUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/messa-commiato-commisso-1.jpg\",\"width\":1638,\"height\":2048},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.intoscana.it\/it\/firenze-saluta-rocco-commisso-il-duomo-gremito-per-la-messa-in-suffragio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.intoscana.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Firenze saluta Rocco Commisso: il Duomo gremito per la messa in suffragio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\",\"url\":\"https:\/\/www.intoscana.it\/it\/\",\"name\":\"intoscana\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.intoscana.it\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/010af92117f50561886339ad5b873a41\",\"name\":\"Chiara Bianchini\",\"sameAs\":[\"c.bianchini@fst.it\"],\"url\":\"https:\/\/www.intoscana.it\/it\/author\/chiara-bianchini\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Firenze saluta Rocco Commisso: il Duomo gremito per la messa in suffragio - intoscana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.intoscana.it\/it\/firenze-saluta-rocco-commisso-il-duomo-gremito-per-la-messa-in-suffragio\/","og_locale":"it_IT","og_type":"article","og_title":"Firenze saluta Rocco Commisso: il Duomo gremito per la messa in suffragio","og_description":"Familiari, istituzioni, mondo dello sport e oltre duemila persone nella cattedrale di Santa Maria del Fiore per l\u2019ultimo omaggio al presidente della Fiorentina. Parole di fede, memoria e impegno per il futuro","og_url":"https:\/\/www.intoscana.it\/it\/firenze-saluta-rocco-commisso-il-duomo-gremito-per-la-messa-in-suffragio\/","og_site_name":"intoscana","article_publisher":"https:\/\/www.facebook.com\/intoscana.it","article_published_time":"2026-01-27T08:49:55+00:00","article_modified_time":"2026-01-28T13:28:39+00:00","og_image":[{"width":1638,"height":2048,"url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/messa-commiato-commisso-1.jpg","type":"image\/jpeg"}],"author":"Chiara Bianchini","twitter_card":"summary_large_image","twitter_creator":"@intoscana","twitter_site":"@intoscana","twitter_misc":{"Written by":"Chiara Bianchini","Est. reading time":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.intoscana.it\/it\/firenze-saluta-rocco-commisso-il-duomo-gremito-per-la-messa-in-suffragio\/","url":"https:\/\/www.intoscana.it\/it\/firenze-saluta-rocco-commisso-il-duomo-gremito-per-la-messa-in-suffragio\/","name":"Firenze saluta Rocco Commisso: il Duomo gremito per la messa in suffragio - intoscana","isPartOf":{"@id":"https:\/\/www.intoscana.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.intoscana.it\/it\/firenze-saluta-rocco-commisso-il-duomo-gremito-per-la-messa-in-suffragio\/#primaryimage"},"image":{"@id":"https:\/\/www.intoscana.it\/it\/firenze-saluta-rocco-commisso-il-duomo-gremito-per-la-messa-in-suffragio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/messa-commiato-commisso-1.jpg","datePublished":"2026-01-27T08:49:55+00:00","dateModified":"2026-01-28T13:28:39+00:00","author":{"@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/010af92117f50561886339ad5b873a41"},"breadcrumb":{"@id":"https:\/\/www.intoscana.it\/it\/firenze-saluta-rocco-commisso-il-duomo-gremito-per-la-messa-in-suffragio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.intoscana.it\/it\/firenze-saluta-rocco-commisso-il-duomo-gremito-per-la-messa-in-suffragio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.intoscana.it\/it\/firenze-saluta-rocco-commisso-il-duomo-gremito-per-la-messa-in-suffragio\/#primaryimage","url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/messa-commiato-commisso-1.jpg","contentUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/messa-commiato-commisso-1.jpg","width":1638,"height":2048},{"@type":"BreadcrumbList","@id":"https:\/\/www.intoscana.it\/it\/firenze-saluta-rocco-commisso-il-duomo-gremito-per-la-messa-in-suffragio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.intoscana.it\/it\/"},{"@type":"ListItem","position":2,"name":"Firenze saluta Rocco Commisso: il Duomo gremito per la messa in suffragio"}]},{"@type":"WebSite","@id":"https:\/\/www.intoscana.it\/it\/#website","url":"https:\/\/www.intoscana.it\/it\/","name":"intoscana","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intoscana.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/010af92117f50561886339ad5b873a41","name":"Chiara Bianchini","sameAs":["c.bianchini@fst.it"],"url":"https:\/\/www.intoscana.it\/it\/author\/chiara-bianchini\/"}]}},"_links":{"self":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/414710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/users\/507"}],"replies":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/comments?post=414710"}],"version-history":[{"count":1,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/414710\/revisions"}],"predecessor-version":[{"id":414713,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/414710\/revisions\/414713"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media\/414712"}],"wp:attachment":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media?parent=414710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/categories?post=414710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/tags?post=414710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}