{"id":419133,"date":"2026-03-03T12:07:24","date_gmt":"2026-03-03T11:07:24","guid":{"rendered":"https:\/\/www.intoscana.it\/it\/?p=419133"},"modified":"2026-03-06T09:15:28","modified_gmt":"2026-03-06T08:15:28","slug":"un-sondaggio-per-il-nome-del-nuovo-ponte-sullarno-a-firenze-le-sorelle-nencioni-in-testa","status":"publish","type":"post","link":"https:\/\/www.intoscana.it\/it\/un-sondaggio-per-il-nome-del-nuovo-ponte-sullarno-a-firenze-le-sorelle-nencioni-in-testa\/","title":{"rendered":"Un sondaggio per il nome del nuovo ponte sull&#8217;Arno a Firenze: le sorelle Nencioni in testa"},"content":{"rendered":"<p><strong>Le sorelle Caterina e Nadia Nencioni<\/strong>, che persero la vita nella <strong>strage dei Georgofili,<\/strong> sono le pi\u00f9 votate al sondaggio online lanciato dal Comune di Firenze per <strong>decidere\u00a0il nome del<a href=\"https:\/\/www.intoscana.it\/it\/tramvia-di-firenze-varato-il-nuovo-ponte-sullarno-tra-bellariva-e-anconella\/\" target=\"_blank\" rel=\"noopener\"> nuovo ponte sull&#8217;Arno<\/a>,<\/strong> tra Bellariva e il Parco dell\u2019Anconella, snodo strategico della nuova\u00a0linea tramviaria verso Bagno a Ripoli, che \u00e8 stato varato la scorsa settimana.<\/p>\n<h3>10mila cittadini hanno votato il sondaggio<\/h3>\n<p>Al sondaggio, ha reso noto la sindaca Sara Funaro, hanno votato circa<strong> 10.000 cittadini: di questi circa 3.500 si sono espresso per le sorelline Nencioni,<\/strong> che sono abbondantemente in testa.<\/p>\n<p><em>&#8220;Nonostante i nomi siano tutti importanti <\/em><mark><em>penso che questo sia un segnale di quanto la citt\u00e0 si ricordi quel momento drammatico dei Georgofili<\/em><\/mark><em>\u00a0&#8211; <\/em>ha detto Funaro &#8211;<em> di quanto la citt\u00e0 ci tenga a lottare contro la mafia e quanto abbia memoria e nel cuore le due sorelline che sono diventate un simbolo di Firenze&#8221;.<\/em><\/p>\n<p><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fsarafunarofirenze%2Fposts%2Fpfbid02hfTp1ZwwJHYENBNkbGhKaD54GJiXsgktGr8kF2wwCU6svcEoXbFgRkjXSza6RYL4l&amp;show_text=true&amp;width=500\" width=\"500\" height=\"250\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>Oltre a Caterina e Nadia Nencioni, vittime della strage dei Georgofili, le altre opzioni contenute nel sondaggio sono la scienziata e premio Nobel <strong>Rita Levi-Montalcini,<\/strong> la prima donna Ministra della Repubblica <strong>Tina Anselmi<\/strong> e la partigiana fiorentina <strong>Gilda Larocca.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Su 10mila votanti al sondaggio online lanciato dal Comune in 3.500 si sono espressi per le due sorelle vittime della strage dei Georgofili<\/p>\n","protected":false},"author":525,"featured_media":418782,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[494],"tags":[245,202,4418,6029],"class_list":["post-419133","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","tag-arno","tag-firenze","tag-infrastrutture","tag-strage-dei-georgofili"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v25.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un sondaggio per il nome del nuovo ponte sull&#039;Arno a Firenze: le sorelle Nencioni in testa - intoscana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.intoscana.it\/it\/un-sondaggio-per-il-nome-del-nuovo-ponte-sullarno-a-firenze-le-sorelle-nencioni-in-testa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un sondaggio per il nome del nuovo ponte sull&#039;Arno a Firenze: le sorelle Nencioni in testa\" \/>\n<meta property=\"og:description\" content=\"Su 10mila votanti al sondaggio online lanciato dal Comune in 3.500 si sono espressi per le due sorelle vittime della strage dei Georgofili\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.intoscana.it\/it\/un-sondaggio-per-il-nome-del-nuovo-ponte-sullarno-a-firenze-le-sorelle-nencioni-in-testa\/\" \/>\n<meta property=\"og:site_name\" content=\"intoscana\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/intoscana.it\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-03T11:07:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-06T08:15:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/ponte-tramvia-2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"898\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@intoscana\" \/>\n<meta name=\"twitter:site\" content=\"@intoscana\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.intoscana.it\/it\/un-sondaggio-per-il-nome-del-nuovo-ponte-sullarno-a-firenze-le-sorelle-nencioni-in-testa\/\",\"url\":\"https:\/\/www.intoscana.it\/it\/un-sondaggio-per-il-nome-del-nuovo-ponte-sullarno-a-firenze-le-sorelle-nencioni-in-testa\/\",\"name\":\"Un sondaggio per il nome del nuovo ponte sull'Arno a Firenze: le sorelle Nencioni in testa - intoscana\",\"isPartOf\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/un-sondaggio-per-il-nome-del-nuovo-ponte-sullarno-a-firenze-le-sorelle-nencioni-in-testa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/un-sondaggio-per-il-nome-del-nuovo-ponte-sullarno-a-firenze-le-sorelle-nencioni-in-testa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/ponte-tramvia-2.jpeg\",\"datePublished\":\"2026-03-03T11:07:24+00:00\",\"dateModified\":\"2026-03-06T08:15:28+00:00\",\"author\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/un-sondaggio-per-il-nome-del-nuovo-ponte-sullarno-a-firenze-le-sorelle-nencioni-in-testa\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.intoscana.it\/it\/un-sondaggio-per-il-nome-del-nuovo-ponte-sullarno-a-firenze-le-sorelle-nencioni-in-testa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.intoscana.it\/it\/un-sondaggio-per-il-nome-del-nuovo-ponte-sullarno-a-firenze-le-sorelle-nencioni-in-testa\/#primaryimage\",\"url\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/ponte-tramvia-2.jpeg\",\"contentUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/ponte-tramvia-2.jpeg\",\"width\":1600,\"height\":898},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.intoscana.it\/it\/un-sondaggio-per-il-nome-del-nuovo-ponte-sullarno-a-firenze-le-sorelle-nencioni-in-testa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.intoscana.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un sondaggio per il nome del nuovo ponte sull&#8217;Arno a Firenze: le sorelle Nencioni in testa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\",\"url\":\"https:\/\/www.intoscana.it\/it\/\",\"name\":\"intoscana\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.intoscana.it\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8\",\"name\":\"Redazione\",\"url\":\"https:\/\/www.intoscana.it\/it\/author\/redazione\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Un sondaggio per il nome del nuovo ponte sull'Arno a Firenze: le sorelle Nencioni in testa - intoscana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.intoscana.it\/it\/un-sondaggio-per-il-nome-del-nuovo-ponte-sullarno-a-firenze-le-sorelle-nencioni-in-testa\/","og_locale":"it_IT","og_type":"article","og_title":"Un sondaggio per il nome del nuovo ponte sull'Arno a Firenze: le sorelle Nencioni in testa","og_description":"Su 10mila votanti al sondaggio online lanciato dal Comune in 3.500 si sono espressi per le due sorelle vittime della strage dei Georgofili","og_url":"https:\/\/www.intoscana.it\/it\/un-sondaggio-per-il-nome-del-nuovo-ponte-sullarno-a-firenze-le-sorelle-nencioni-in-testa\/","og_site_name":"intoscana","article_publisher":"https:\/\/www.facebook.com\/intoscana.it","article_published_time":"2026-03-03T11:07:24+00:00","article_modified_time":"2026-03-06T08:15:28+00:00","og_image":[{"width":1600,"height":898,"url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/ponte-tramvia-2.jpeg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@intoscana","twitter_site":"@intoscana","twitter_misc":{"Written by":"Redazione","Est. reading time":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.intoscana.it\/it\/un-sondaggio-per-il-nome-del-nuovo-ponte-sullarno-a-firenze-le-sorelle-nencioni-in-testa\/","url":"https:\/\/www.intoscana.it\/it\/un-sondaggio-per-il-nome-del-nuovo-ponte-sullarno-a-firenze-le-sorelle-nencioni-in-testa\/","name":"Un sondaggio per il nome del nuovo ponte sull'Arno a Firenze: le sorelle Nencioni in testa - intoscana","isPartOf":{"@id":"https:\/\/www.intoscana.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.intoscana.it\/it\/un-sondaggio-per-il-nome-del-nuovo-ponte-sullarno-a-firenze-le-sorelle-nencioni-in-testa\/#primaryimage"},"image":{"@id":"https:\/\/www.intoscana.it\/it\/un-sondaggio-per-il-nome-del-nuovo-ponte-sullarno-a-firenze-le-sorelle-nencioni-in-testa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/ponte-tramvia-2.jpeg","datePublished":"2026-03-03T11:07:24+00:00","dateModified":"2026-03-06T08:15:28+00:00","author":{"@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8"},"breadcrumb":{"@id":"https:\/\/www.intoscana.it\/it\/un-sondaggio-per-il-nome-del-nuovo-ponte-sullarno-a-firenze-le-sorelle-nencioni-in-testa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.intoscana.it\/it\/un-sondaggio-per-il-nome-del-nuovo-ponte-sullarno-a-firenze-le-sorelle-nencioni-in-testa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.intoscana.it\/it\/un-sondaggio-per-il-nome-del-nuovo-ponte-sullarno-a-firenze-le-sorelle-nencioni-in-testa\/#primaryimage","url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/ponte-tramvia-2.jpeg","contentUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/ponte-tramvia-2.jpeg","width":1600,"height":898},{"@type":"BreadcrumbList","@id":"https:\/\/www.intoscana.it\/it\/un-sondaggio-per-il-nome-del-nuovo-ponte-sullarno-a-firenze-le-sorelle-nencioni-in-testa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.intoscana.it\/it\/"},{"@type":"ListItem","position":2,"name":"Un sondaggio per il nome del nuovo ponte sull&#8217;Arno a Firenze: le sorelle Nencioni in testa"}]},{"@type":"WebSite","@id":"https:\/\/www.intoscana.it\/it\/#website","url":"https:\/\/www.intoscana.it\/it\/","name":"intoscana","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intoscana.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8","name":"Redazione","url":"https:\/\/www.intoscana.it\/it\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/419133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/users\/525"}],"replies":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/comments?post=419133"}],"version-history":[{"count":5,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/419133\/revisions"}],"predecessor-version":[{"id":419671,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/419133\/revisions\/419671"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media\/418782"}],"wp:attachment":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media?parent=419133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/categories?post=419133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/tags?post=419133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}