{"id":421641,"date":"2026-03-21T07:58:56","date_gmt":"2026-03-21T06:58:56","guid":{"rendered":"https:\/\/www.intoscana.it\/it\/?p=421641"},"modified":"2026-03-21T07:58:56","modified_gmt":"2026-03-21T06:58:56","slug":"castagna-monte-amiata-igp-novita-nel-disciplinare-ampliata-larea-di-produzione","status":"publish","type":"post","link":"https:\/\/www.intoscana.it\/it\/castagna-monte-amiata-igp-novita-nel-disciplinare-ampliata-larea-di-produzione\/","title":{"rendered":"Castagna Monte Amiata Igp, novit\u00e0 nel disciplinare: ampliata l&#8217;area di produzione"},"content":{"rendered":"<p>Novit\u00e0 per la <strong>Castagna del Monte Amiata Igp<\/strong>. La Giunta della Regione Toscana ha infatti approvato la modifica del <strong>disciplinare di produzione<\/strong> a seguito della richiesta presentata da un gruppo di produttori locali rappresentativi della IGP.<\/p>\n<p>Tra i principali cambiamenti c\u2019\u00e8 <mark>l\u2019estensione dell\u2019area d\u2019interesse della produzione ai Comuni di Castell\u2019Azzara e Semproniano (Grosseto) e al Comune di Sorano (Siena), che storicamente ha produzione con le stesse caratteristiche.<\/mark> Un altro aggiornamento importante riguarda la possibilit\u00e0 di <strong>vendita frazionata<\/strong> del prodotto prelevato da un contenitore certificato e tracciato: molto pi\u00f9 agevole per il pubblico delle sagre che in autunno si svolgono in tanti comuni dell&#8217;Amiata.<\/p>\n<p>Come spiega l\u2019assessore all\u2019economia, attivit\u00e0 produttive e agricoltura, <strong>Leonardo Marras<\/strong>, \u201cparliamo di un settore che torna ad essere competitivo dopo gli anni del forte calo produttivo dovuto all\u2019infestazione da cinipide, che ha determinato quasi l\u2019azzeramento della produzione di castagne fresche, prodotto per il quale la castagna del Monte Amiata ha ottenuto la Igp nel 2000. <mark>Oggi, grazie all\u2019iniziativa di un gruppo di produttori locali, si adeguano le norme di individuazione, produzione e utilizzo della produzione senza stravolgere il legame con l\u2019ambiente e la tradizionale qualit\u00e0,<\/mark> con l\u2019obbiettivo di far ripartire la certificazione del prodotto, ormai quasi assente da anni\u201d.<\/p>\n<p>Tra le altre novit\u00e0 \u00e8 stata introdotta anche la <strong>dimensione<\/strong> del prodotto calibrato che sar\u00e0 riportato in etichetta nelle seguenti tipologie: fino a 80 frutti per kg \u201cfrutto grande\u201d, oltre da 81 e fino a 95 frutti per kg \u201cfrutto medio\u201d assicurando cos\u00ec una pezzatura maggiormente ricercata dal mercato. Per salvaguardare la <strong>redditivit\u00e0<\/strong> dei castanicoltori, si potranno utilizzare i frutti di calibro inadeguato alla vendita del fresco per i trasformati o per farne castagne secche potendo scrivere che contengono &#8220;Castagna del Monte Amiata&#8221; IGP.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estesa l\u2019area d\u2019interesse ai comuni di Castell\u2019Azzara e Semproniano e al comune di Sorano. Marras: &#8220;Grazie all\u2019iniziativa di un gruppo di produttori locali si adeguano le norme senza stravolgere il legame con l\u2019ambiente e la tradizionale qualit\u00e0&#8221;<\/p>\n","protected":false},"author":525,"featured_media":105074,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8],"tags":[363,1513,5008,4625],"class_list":["post-421641","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-enogastronomia","tag-agricoltura","tag-castagne","tag-leonardo-marras","tag-monte-amiata"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v25.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Castagna Monte Amiata Igp, novit\u00e0 nel disciplinare: ampliata l&#039;area di produzione - intoscana<\/title>\n<meta name=\"description\" content=\"Estesa l\u2019area d\u2019interesse ai comuni di Castell\u2019Azzara e Semproniano e al comune di Sorano. Marras: &quot;Grazie all\u2019iniziativa di un gruppo di produttori locali si adeguano le norme senza stravolgere il legame con l\u2019ambiente e la tradizionale qualit\u00e0&quot;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.intoscana.it\/it\/castagna-monte-amiata-igp-novita-nel-disciplinare-ampliata-larea-di-produzione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Castagna Monte Amiata Igp, novit\u00e0 nel disciplinare: ampliata l&#039;area di produzione\" \/>\n<meta property=\"og:description\" content=\"Estesa l\u2019area d\u2019interesse ai comuni di Castell\u2019Azzara e Semproniano e al comune di Sorano. Marras: &quot;Grazie all\u2019iniziativa di un gruppo di produttori locali si adeguano le norme senza stravolgere il legame con l\u2019ambiente e la tradizionale qualit\u00e0&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.intoscana.it\/it\/castagna-monte-amiata-igp-novita-nel-disciplinare-ampliata-larea-di-produzione\/\" \/>\n<meta property=\"og:site_name\" content=\"intoscana\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/intoscana.it\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-21T06:58:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/castagneti-del-monte-amiata_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"460\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@intoscana\" \/>\n<meta name=\"twitter:site\" content=\"@intoscana\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.intoscana.it\/it\/castagna-monte-amiata-igp-novita-nel-disciplinare-ampliata-larea-di-produzione\/\",\"url\":\"https:\/\/www.intoscana.it\/it\/castagna-monte-amiata-igp-novita-nel-disciplinare-ampliata-larea-di-produzione\/\",\"name\":\"Castagna Monte Amiata Igp, novit\u00e0 nel disciplinare: ampliata l'area di produzione - intoscana\",\"isPartOf\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/castagna-monte-amiata-igp-novita-nel-disciplinare-ampliata-larea-di-produzione\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/castagna-monte-amiata-igp-novita-nel-disciplinare-ampliata-larea-di-produzione\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/castagneti-del-monte-amiata_1.jpg\",\"datePublished\":\"2026-03-21T06:58:56+00:00\",\"author\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8\"},\"description\":\"Estesa l\u2019area d\u2019interesse ai comuni di Castell\u2019Azzara e Semproniano e al comune di Sorano. Marras: \\\"Grazie all\u2019iniziativa di un gruppo di produttori locali si adeguano le norme senza stravolgere il legame con l\u2019ambiente e la tradizionale qualit\u00e0\\\"\",\"breadcrumb\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/castagna-monte-amiata-igp-novita-nel-disciplinare-ampliata-larea-di-produzione\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.intoscana.it\/it\/castagna-monte-amiata-igp-novita-nel-disciplinare-ampliata-larea-di-produzione\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.intoscana.it\/it\/castagna-monte-amiata-igp-novita-nel-disciplinare-ampliata-larea-di-produzione\/#primaryimage\",\"url\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/castagneti-del-monte-amiata_1.jpg\",\"contentUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/castagneti-del-monte-amiata_1.jpg\",\"width\":700,\"height\":460,\"caption\":\"Il foliage nei castagneti del Monte Amiata\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.intoscana.it\/it\/castagna-monte-amiata-igp-novita-nel-disciplinare-ampliata-larea-di-produzione\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.intoscana.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Castagna Monte Amiata Igp, novit\u00e0 nel disciplinare: ampliata l&#8217;area di produzione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\",\"url\":\"https:\/\/www.intoscana.it\/it\/\",\"name\":\"intoscana\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.intoscana.it\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8\",\"name\":\"Redazione\",\"url\":\"https:\/\/www.intoscana.it\/it\/author\/redazione\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Castagna Monte Amiata Igp, novit\u00e0 nel disciplinare: ampliata l'area di produzione - intoscana","description":"Estesa l\u2019area d\u2019interesse ai comuni di Castell\u2019Azzara e Semproniano e al comune di Sorano. Marras: \"Grazie all\u2019iniziativa di un gruppo di produttori locali si adeguano le norme senza stravolgere il legame con l\u2019ambiente e la tradizionale qualit\u00e0\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.intoscana.it\/it\/castagna-monte-amiata-igp-novita-nel-disciplinare-ampliata-larea-di-produzione\/","og_locale":"it_IT","og_type":"article","og_title":"Castagna Monte Amiata Igp, novit\u00e0 nel disciplinare: ampliata l'area di produzione","og_description":"Estesa l\u2019area d\u2019interesse ai comuni di Castell\u2019Azzara e Semproniano e al comune di Sorano. Marras: \"Grazie all\u2019iniziativa di un gruppo di produttori locali si adeguano le norme senza stravolgere il legame con l\u2019ambiente e la tradizionale qualit\u00e0\"","og_url":"https:\/\/www.intoscana.it\/it\/castagna-monte-amiata-igp-novita-nel-disciplinare-ampliata-larea-di-produzione\/","og_site_name":"intoscana","article_publisher":"https:\/\/www.facebook.com\/intoscana.it","article_published_time":"2026-03-21T06:58:56+00:00","og_image":[{"width":700,"height":460,"url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/castagneti-del-monte-amiata_1.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@intoscana","twitter_site":"@intoscana","twitter_misc":{"Written by":"Redazione","Est. reading time":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.intoscana.it\/it\/castagna-monte-amiata-igp-novita-nel-disciplinare-ampliata-larea-di-produzione\/","url":"https:\/\/www.intoscana.it\/it\/castagna-monte-amiata-igp-novita-nel-disciplinare-ampliata-larea-di-produzione\/","name":"Castagna Monte Amiata Igp, novit\u00e0 nel disciplinare: ampliata l'area di produzione - intoscana","isPartOf":{"@id":"https:\/\/www.intoscana.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.intoscana.it\/it\/castagna-monte-amiata-igp-novita-nel-disciplinare-ampliata-larea-di-produzione\/#primaryimage"},"image":{"@id":"https:\/\/www.intoscana.it\/it\/castagna-monte-amiata-igp-novita-nel-disciplinare-ampliata-larea-di-produzione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/castagneti-del-monte-amiata_1.jpg","datePublished":"2026-03-21T06:58:56+00:00","author":{"@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8"},"description":"Estesa l\u2019area d\u2019interesse ai comuni di Castell\u2019Azzara e Semproniano e al comune di Sorano. Marras: \"Grazie all\u2019iniziativa di un gruppo di produttori locali si adeguano le norme senza stravolgere il legame con l\u2019ambiente e la tradizionale qualit\u00e0\"","breadcrumb":{"@id":"https:\/\/www.intoscana.it\/it\/castagna-monte-amiata-igp-novita-nel-disciplinare-ampliata-larea-di-produzione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.intoscana.it\/it\/castagna-monte-amiata-igp-novita-nel-disciplinare-ampliata-larea-di-produzione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.intoscana.it\/it\/castagna-monte-amiata-igp-novita-nel-disciplinare-ampliata-larea-di-produzione\/#primaryimage","url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/castagneti-del-monte-amiata_1.jpg","contentUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/castagneti-del-monte-amiata_1.jpg","width":700,"height":460,"caption":"Il foliage nei castagneti del Monte Amiata"},{"@type":"BreadcrumbList","@id":"https:\/\/www.intoscana.it\/it\/castagna-monte-amiata-igp-novita-nel-disciplinare-ampliata-larea-di-produzione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.intoscana.it\/it\/"},{"@type":"ListItem","position":2,"name":"Castagna Monte Amiata Igp, novit\u00e0 nel disciplinare: ampliata l&#8217;area di produzione"}]},{"@type":"WebSite","@id":"https:\/\/www.intoscana.it\/it\/#website","url":"https:\/\/www.intoscana.it\/it\/","name":"intoscana","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intoscana.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8","name":"Redazione","url":"https:\/\/www.intoscana.it\/it\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/421641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/users\/525"}],"replies":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/comments?post=421641"}],"version-history":[{"count":4,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/421641\/revisions"}],"predecessor-version":[{"id":421656,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/421641\/revisions\/421656"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media\/105074"}],"wp:attachment":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media?parent=421641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/categories?post=421641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/tags?post=421641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}