{"id":422440,"date":"2026-03-28T14:52:56","date_gmt":"2026-03-28T13:52:56","guid":{"rendered":"https:\/\/www.intoscana.it\/it\/?p=422440"},"modified":"2026-03-30T11:55:27","modified_gmt":"2026-03-30T09:55:27","slug":"a-chiesina-uzzanese-una-nuova-rotatoria-realizzata-grazie-a-295-mila-euro-dalla-regione-toscana","status":"publish","type":"post","link":"https:\/\/www.intoscana.it\/it\/a-chiesina-uzzanese-una-nuova-rotatoria-realizzata-grazie-a-295-mila-euro-dalla-regione-toscana\/","title":{"rendered":"A Chiesina Uzzanese una nuova rotatoria realizzata grazie a 295 mila euro della Regione Toscana"},"content":{"rendered":"<p>La nuova rotatoria di Chiesina Uzzanese (Pistoia), in via Ponte alla Ciliegia, intitolata a <strong>Guttmann e Maglio, due figure di medici straordinari, neurochirurghi rivoluzionari delle terapie riabilitative<\/strong> che diedero un contributo fondamentale alla nascita dei Giochi Paralimpici, \u00e8 stata inaugurata dal <strong>presidente della Regione Toscana Eugenio Giani e dal sottosegretario alla presidenza della Regione Bernard Dika<\/strong> con il sindaco Fabio Berti.<\/p>\n<p>L&#8217;intervento \u00e8 stato finanziato dalla Regione con<strong> un contributo di 295 mila euro da fondi Fsc<\/strong> e ha previsto la modifica dell&#8217;intersezione dell<strong>&#8216;incrocio libero a raso tra via Ponte alla Ciliegia e la circonvallazione Sp45<\/strong> con la realizzazione di una rotatoria.<\/p>\n<p>Una trasformazione utile per <strong>migliorare la rete stradale esistente, incrementandone la sicurezza e l&#8217;efficienza<\/strong> della circolazione dei veicoli, ridurre i tempi di attesa all&#8217;intersezione con conseguente <strong>riduzione del rumore e di emissioni inquinanti.<\/strong><\/p>\n<p><em>\u201cUn intervento che migliora decisamente la viabilit\u00e0 in un punto cruciale per l\u2019accesso all\u2019abitato del Comune- <\/em><strong>hanno spiegato il presidente Giani e il sottosegretario Dika-<\/strong><em> Dove prima c\u2019era un incrocio pericoloso infatti, con questa opera restituiamo ai cittadini una viabilit\u00e0 moderna funzionale e meno impattante dal punto di vista acustico e ambientale. Siamo molto soddisfatti di poter rispondere alle richieste delle amministrazioni con investimenti come questo che vanno a migliorare concretamente la vita delle comunit\u00e0 nella Toscana diffusa\u201d.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019intervento ha previsto la modifica dell\u2019intersezione dell\u2019incrocio libero a raso tra Via Ponte alla Ciliegia e la circonvallazione SP45 con la realizzazione di una rotatoria<\/p>\n","protected":false},"author":525,"featured_media":422441,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[494],"tags":[158,1577,151],"class_list":["post-422440","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","tag-eugenio-giani","tag-muoversi-in-toscana","tag-regione-toscana"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v25.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A Chiesina Uzzanese una nuova rotatoria realizzata grazie a 295 mila euro della Regione Toscana - intoscana<\/title>\n<meta name=\"description\" content=\"L\u2019intervento ha previsto la modifica dell\u2019intersezione dell\u2019incrocio libero a raso tra Via Ponte alla Ciliegia e la circonvallazione SP45\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.intoscana.it\/it\/a-chiesina-uzzanese-una-nuova-rotatoria-realizzata-grazie-a-295-mila-euro-dalla-regione-toscana\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Chiesina Uzzanese una nuova rotatoria realizzata grazie a 295 mila euro della Regione Toscana\" \/>\n<meta property=\"og:description\" content=\"L\u2019intervento ha previsto la modifica dell\u2019intersezione dell\u2019incrocio libero a raso tra Via Ponte alla Ciliegia e la circonvallazione SP45\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.intoscana.it\/it\/a-chiesina-uzzanese-una-nuova-rotatoria-realizzata-grazie-a-295-mila-euro-dalla-regione-toscana\/\" \/>\n<meta property=\"og:site_name\" content=\"intoscana\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/intoscana.it\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-28T13:52:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-30T09:55:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/2042df86-5b4a-4dc9-bb0f-949e2beb3b17-e1774705966152.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"830\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@intoscana\" \/>\n<meta name=\"twitter:site\" content=\"@intoscana\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.intoscana.it\/it\/a-chiesina-uzzanese-una-nuova-rotatoria-realizzata-grazie-a-295-mila-euro-dalla-regione-toscana\/\",\"url\":\"https:\/\/www.intoscana.it\/it\/a-chiesina-uzzanese-una-nuova-rotatoria-realizzata-grazie-a-295-mila-euro-dalla-regione-toscana\/\",\"name\":\"A Chiesina Uzzanese una nuova rotatoria realizzata grazie a 295 mila euro della Regione Toscana - intoscana\",\"isPartOf\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/a-chiesina-uzzanese-una-nuova-rotatoria-realizzata-grazie-a-295-mila-euro-dalla-regione-toscana\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/a-chiesina-uzzanese-una-nuova-rotatoria-realizzata-grazie-a-295-mila-euro-dalla-regione-toscana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/2042df86-5b4a-4dc9-bb0f-949e2beb3b17-e1774705966152.jpeg\",\"datePublished\":\"2026-03-28T13:52:56+00:00\",\"dateModified\":\"2026-03-30T09:55:27+00:00\",\"author\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8\"},\"description\":\"L\u2019intervento ha previsto la modifica dell\u2019intersezione dell\u2019incrocio libero a raso tra Via Ponte alla Ciliegia e la circonvallazione SP45\",\"breadcrumb\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/a-chiesina-uzzanese-una-nuova-rotatoria-realizzata-grazie-a-295-mila-euro-dalla-regione-toscana\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.intoscana.it\/it\/a-chiesina-uzzanese-una-nuova-rotatoria-realizzata-grazie-a-295-mila-euro-dalla-regione-toscana\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.intoscana.it\/it\/a-chiesina-uzzanese-una-nuova-rotatoria-realizzata-grazie-a-295-mila-euro-dalla-regione-toscana\/#primaryimage\",\"url\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/2042df86-5b4a-4dc9-bb0f-949e2beb3b17-e1774705966152.jpeg\",\"contentUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/2042df86-5b4a-4dc9-bb0f-949e2beb3b17-e1774705966152.jpeg\",\"width\":1200,\"height\":830},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.intoscana.it\/it\/a-chiesina-uzzanese-una-nuova-rotatoria-realizzata-grazie-a-295-mila-euro-dalla-regione-toscana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.intoscana.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Chiesina Uzzanese una nuova rotatoria realizzata grazie a 295 mila euro della Regione Toscana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\",\"url\":\"https:\/\/www.intoscana.it\/it\/\",\"name\":\"intoscana\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.intoscana.it\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8\",\"name\":\"Redazione\",\"url\":\"https:\/\/www.intoscana.it\/it\/author\/redazione\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"A Chiesina Uzzanese una nuova rotatoria realizzata grazie a 295 mila euro della Regione Toscana - intoscana","description":"L\u2019intervento ha previsto la modifica dell\u2019intersezione dell\u2019incrocio libero a raso tra Via Ponte alla Ciliegia e la circonvallazione SP45","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.intoscana.it\/it\/a-chiesina-uzzanese-una-nuova-rotatoria-realizzata-grazie-a-295-mila-euro-dalla-regione-toscana\/","og_locale":"it_IT","og_type":"article","og_title":"A Chiesina Uzzanese una nuova rotatoria realizzata grazie a 295 mila euro della Regione Toscana","og_description":"L\u2019intervento ha previsto la modifica dell\u2019intersezione dell\u2019incrocio libero a raso tra Via Ponte alla Ciliegia e la circonvallazione SP45","og_url":"https:\/\/www.intoscana.it\/it\/a-chiesina-uzzanese-una-nuova-rotatoria-realizzata-grazie-a-295-mila-euro-dalla-regione-toscana\/","og_site_name":"intoscana","article_publisher":"https:\/\/www.facebook.com\/intoscana.it","article_published_time":"2026-03-28T13:52:56+00:00","article_modified_time":"2026-03-30T09:55:27+00:00","og_image":[{"width":1200,"height":830,"url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/2042df86-5b4a-4dc9-bb0f-949e2beb3b17-e1774705966152.jpeg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@intoscana","twitter_site":"@intoscana","twitter_misc":{"Written by":"Redazione","Est. reading time":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.intoscana.it\/it\/a-chiesina-uzzanese-una-nuova-rotatoria-realizzata-grazie-a-295-mila-euro-dalla-regione-toscana\/","url":"https:\/\/www.intoscana.it\/it\/a-chiesina-uzzanese-una-nuova-rotatoria-realizzata-grazie-a-295-mila-euro-dalla-regione-toscana\/","name":"A Chiesina Uzzanese una nuova rotatoria realizzata grazie a 295 mila euro della Regione Toscana - intoscana","isPartOf":{"@id":"https:\/\/www.intoscana.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.intoscana.it\/it\/a-chiesina-uzzanese-una-nuova-rotatoria-realizzata-grazie-a-295-mila-euro-dalla-regione-toscana\/#primaryimage"},"image":{"@id":"https:\/\/www.intoscana.it\/it\/a-chiesina-uzzanese-una-nuova-rotatoria-realizzata-grazie-a-295-mila-euro-dalla-regione-toscana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/2042df86-5b4a-4dc9-bb0f-949e2beb3b17-e1774705966152.jpeg","datePublished":"2026-03-28T13:52:56+00:00","dateModified":"2026-03-30T09:55:27+00:00","author":{"@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8"},"description":"L\u2019intervento ha previsto la modifica dell\u2019intersezione dell\u2019incrocio libero a raso tra Via Ponte alla Ciliegia e la circonvallazione SP45","breadcrumb":{"@id":"https:\/\/www.intoscana.it\/it\/a-chiesina-uzzanese-una-nuova-rotatoria-realizzata-grazie-a-295-mila-euro-dalla-regione-toscana\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.intoscana.it\/it\/a-chiesina-uzzanese-una-nuova-rotatoria-realizzata-grazie-a-295-mila-euro-dalla-regione-toscana\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.intoscana.it\/it\/a-chiesina-uzzanese-una-nuova-rotatoria-realizzata-grazie-a-295-mila-euro-dalla-regione-toscana\/#primaryimage","url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/2042df86-5b4a-4dc9-bb0f-949e2beb3b17-e1774705966152.jpeg","contentUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/2042df86-5b4a-4dc9-bb0f-949e2beb3b17-e1774705966152.jpeg","width":1200,"height":830},{"@type":"BreadcrumbList","@id":"https:\/\/www.intoscana.it\/it\/a-chiesina-uzzanese-una-nuova-rotatoria-realizzata-grazie-a-295-mila-euro-dalla-regione-toscana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.intoscana.it\/it\/"},{"@type":"ListItem","position":2,"name":"A Chiesina Uzzanese una nuova rotatoria realizzata grazie a 295 mila euro della Regione Toscana"}]},{"@type":"WebSite","@id":"https:\/\/www.intoscana.it\/it\/#website","url":"https:\/\/www.intoscana.it\/it\/","name":"intoscana","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intoscana.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/9223810753230f20bd670fdd322661f8","name":"Redazione","url":"https:\/\/www.intoscana.it\/it\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/422440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/users\/525"}],"replies":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/comments?post=422440"}],"version-history":[{"count":4,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/422440\/revisions"}],"predecessor-version":[{"id":422498,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/422440\/revisions\/422498"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media\/422441"}],"wp:attachment":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media?parent=422440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/categories?post=422440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/tags?post=422440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}