{"id":427474,"date":"2026-05-13T14:39:56","date_gmt":"2026-05-13T12:39:56","guid":{"rendered":"https:\/\/www.intoscana.it\/it\/?p=427474"},"modified":"2026-05-13T14:58:13","modified_gmt":"2026-05-13T12:58:13","slug":"supernova-diventare-madre-libro-nina-gigante","status":"publish","type":"post","link":"https:\/\/www.intoscana.it\/it\/supernova-diventare-madre-libro-nina-gigante\/","title":{"rendered":"Diventare madre \u00e8 una &#8220;Supernova&#8221;: la metamorfosi della matrescenza nel libro di Nina Gigante"},"content":{"rendered":"<p><strong>La supernova \u00e8 una spettacolare esplosione<\/strong> che segna la morte di una stella e rilascia in poco tempo una quantit\u00e0 di energia enorme, capace superare la luminosit\u00e0 di un&#8217;intera galassia, da cui nascono stelle di neutroni, materiali che poi formeranno nuovi sistemi stellari e persino buchi neri. La supernova quindi \u00e8 la fine di un ciclo vitale e allo stesso la nascita di qualcosa di nuovo: per questo \u00e8 <mark>un\u2019immagine potente per raccontare ci\u00f2 che accade nella maternit\u00e0, quando una donna crea una nuova esistenza<\/mark> riconfigurando completamente se stessa nel processo. \u00c8 la metafora stellare da cui prende le mosse <strong><em>\u201cSupernova. Quando nasce una madre: le trasformazioni di cui nessuno ti ha mai parlato\u201d<\/em>,<\/strong> il saggio pubblicato dalla <strong>casa editrice toscana Aboca<\/strong> della giornalista e integrative health coach specializzata in medicine orientali <strong>Nina Gigante<\/strong>, che si addentra nella trasformazione radicale che accompagna il diventare madre.<br \/>\nAttraverso <strong>neuroscienze, antropologia, psicologia, femminismo e vissuto personale<\/strong>, Nina Gigante \u2013 che presenter\u00e0 il libro a Firenze il 6 giugno all\u2019interno del festival \u201cLa citt\u00e0 dei lettori&#8221; \u2013 affronta temi ancora poco discussi: la matrescenza, l\u2019ambivalenza materna, il carico mentale, la solitudine del postpartum e il bisogno di una rete di cura che oggi \u00e8 venuta a mancare.<\/p>\n<p><em>Questo libro \u00e8 nato da una domanda: quando si diventa madri? \u00c8 cos\u00ec che sei approdata al termine matrescenza, che in Italia \u00e8 ancora molto poco conosciuto e identifica il diventare madre non come un momento che cambia tutto ma come un processo. Come l\u2019hai scoperto e perch\u00e9 \u00e8 cos\u00ec importante?<\/em><\/p>\n<p>Ci sono arrivata cos\u00ec: una notte ero disperata, con il mio bambino piccolo in braccio, davanti al frigorifero, di cui ricordo ancora perfettamente la luce tagliente, e mi sentivo<strong> completamente sola ed estranea a me stessa<\/strong>. Avendo partorito in pandemia quella solitudine era amplificata, ma credo sia un sentimento che accomuna molte madri. In quel momento dolorosissimo ho preso il telefono e mi \u00e8 comparso un post che diceva: <strong>\u201cYou\u2019re not broken, you\u2019re becoming\u201d.<\/strong> Ho fatto uno screenshot e sono finita su un podcast in cui due ragazze parlavano di matrescenza.<br \/>\nQuella notte stessa ho iniziato a cercare, a leggere, e ho scoperto <strong>Dana Raphael, antropologa allieva di Margaret Mead<\/strong>, che negli anni Settanta ha introdotto il concetto di matrescenza, perch\u00e9 aveva intuito che mancava qualcosa nel modo in cui raccontavamo la maternit\u00e0: uno sguardo sulla donna che diventa madre.<br \/>\nLa sua intuizione oggi \u00e8 confermata dalle neuroscienze: i <strong>cambiamenti ormonali, neurologici e identitari<\/strong> che attraversiamo sono paragonabili a quelli dell\u2019adolescenza. Solo che all\u2019adolescenza concediamo tempo e variabilit\u00e0, mentre alla maternit\u00e0 no. <mark>Questo termine \u00e8 importante perch\u00e9 spiega cosa ci accade e ci insegna ad essere pi\u00f9 pazienti con noi stesse, a stare dentro il cambiamento.<\/mark><\/p>\n<p><em>Nel libro spieghi che la matrescenza non finisce mai, mi ha colpito il fatto che le cellule del bambino rimangano per sempre dentro il corpo della sua mamma.<\/em><\/p>\n<p>S\u00ec, c\u2019\u00e8 uno studio su questo fenomeno, che si chiama <strong>microchimerismo<\/strong>, che ha trovato cellule dei figli nel corpo di donne di 94 anni. Ma la cosa straordinaria \u00e8 che non si tratta di cellule inermi: entrano nei tessuti, diventano parte del corpo materno.<br \/>\nQuesto significa che<mark> la maternit\u00e0 riscrive davvero la materia e, simbolicamente, anche l\u2019identit\u00e0. <\/mark>Per me \u00e8 bellissima questa idea di identit\u00e0 porosa: noi ci costruiamo nella relazione con l\u2019altro, in questo caso con nostro figlio.<br \/>\nIl problema \u00e8 che tutto questo <strong>non \u00e8 stato studiato per decenni.<\/strong> Sul corpo femminile esiste un enorme bias, sappiamo che fino al 1996 i trial clinici venivano condotti solo sugli uomini, e sul corpo materno il bias \u00e8 ancora pi\u00f9 forte. Abbiamo dato per scontato che le donne fossero \u201cfatte per quello\u201d, senza chiederci cosa accadesse davvero dentro i loro corpi e le loro menti, senza capire di cosa ha fisiologicamente bisogno una neo mamma.<\/p>\n<p><em>Il concetto di matrescenza apre alla possibilit\u00e0 che esistano tante maternit\u00e0, non una soltanto, e anche all\u2019ambivalenza materna: \u00e8 normale amare profondamente un figlio e, allo stesso tempo, desiderare uno spazio per s\u00e9. Questa ambivalenza se non viene riconosciuta \u00e8 pericolosa, quanti danni pu\u00f2 fare il mito del sacrificio?<\/em><\/p>\n<p>Tantissimi. Noi prima abbiamo raccontato una maternit\u00e0 tutta luce, amore e gioia, poi da qualche tempo stiamo vedendo anche i lati oscuri ma ancora non riusciamo a tenerli tutti insieme. <mark>Noi parliamo solo dei casi estremi, della mamma depressa e della mamma felicissima, ma provare sentimenti ambivalenti \u00e8 costitutivo della matrescenza. <\/mark>Posso amare immensamente mio figlio e contemporaneamente desiderare un\u2019ora da sola, una doccia in silenzio, e questo fa parte dell\u2019esperienza psichica della maternit\u00e0.<br \/>\n<strong>Alle madri non concediamo ci\u00f2 che invece consideriamo normale in altri passaggi della vita.<\/strong> Diciamo che \u00e8 sano che un adolescente provi rabbia o ribellione ma una madre che dice \u201cnon ce la faccio pi\u00f9\u201d viene subito giudicata come cattiva madre. Invece sono sentimenti costitutivi dell\u2019esperienza materna, non ci deve essere nessuna vergogna e non \u00e8 questa la misura dell\u2019amore per il proprio bambino.<\/p>\n<figure id=\"post-427480 media-427480\" class=\"align-none\">\n<p><figure style=\"width: 1654px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/COPgiganteSupernova_low-scaled.jpg\" alt=\"\" width=\"1654\" height=\"2539\" \/><figcaption class=\"wp-caption-text\">Supernova di Nina Gigante<\/figcaption><\/figure><\/figure>\n<p><em>In &#8220;Supernova&#8221; sottolinei anche quanto il postpartum sia un periodo delicatissimo, che in molte culture in tutto il mondo prevedeva diverse forme di sostegno e aiuto per le madri che invece oggi sono spesso lasciate sole.<\/em><\/p>\n<p>Quando parliamo di salute mentale perinatale parliamo quasi esclusivamente di<strong> depressione postpartum<\/strong>, di cui soffre una donna su cinque. Ma ci sono moltissime altre forme di sofferenza: ansia, sovraccarico, smarrimento identitario.<br \/>\nUna donna pu\u00f2 non essere depressa e sentirsi comunque travolta dal nuovo rapporto con se stessa, con il lavoro, con il partner, con il bambino. Dopo il parto non torni quella di prima dopo sei settimane. Non funziona cos\u00ec. La matrescenza, come dice la psicologa clinica Aur\u00e9lie Athan, pu\u00f2 durare tutta la vita. Ogni fase del figlio ti trasforma di nuovo.<\/p>\n<p><em>Mi ha colpito molto lo studio che riporti in \u201cSupernova\u201d che dimostra che non solo il cervello delle madri cambia nell\u2019accudimento: anche quello dei padri si pu\u00f2 modificare nella relazione con il figlio.<\/em><\/p>\n<p>S\u00ec, gli studi dimostrano che <mark>anche il cervello dei padri e dei caregiver cambia, ma a una condizione: che siano coinvolti nella cura. <\/mark>Il problema \u00e8 che non esiste ancora una <strong>cultura del lavoro compatibile con la genitorialit\u00e0.<\/strong> Se a noi donne viene chiesto di lavorare come se non facessimo figli e di fare figli come se non lavorassimo anche per i padri non \u00e8 diverso. Dobbiamo capire che la cura nel postpartum non \u00e8 negoziabile, mamma e pap\u00e0 devono prendersi cura entrambi del bambino, sia per la salute della madre ma anche per la relazione che si genera tra i pap\u00e0 e i figli.<\/p>\n<p><em>Arriviamo alla parte pi\u00f9 politica del libro, quella finale, dove sostieni che il femminismo abbia fallito con la maternit\u00e0. Secondo te perch\u00e9 e da dove possiamo ripartire?<\/em><\/p>\n<p><strong>Il femminismo ha dimenticato le sale parto<\/strong>. Storicamente \u00e8 comprensibile: le donne erano schiacciate dentro il ruolo materno e hanno giustamente rivendicato il diritto a essere altro. Ma in questo salto abbiamo lasciato sole le madri. Per questo oggi sento fortissima la necessit\u00e0 di un <strong>femminismo matricentrico,<\/strong> in cui ogni madre possa riconoscere degli strumenti attraverso cui leggersi e rivendicare i propri bisogni. Il suicidio \u00e8 la prima causa di morte nelle madri perch\u00e9 non siamo sostenute, non siamo viste, non c\u2019\u00e8 una cassetta degli attrezzi per noi, n\u00e9 culturale n\u00e9 medica n\u00e9 politica. <mark>Occuparci delle madri \u00e8 una battaglia di civilt\u00e0 fondativa della democrazia, perch\u00e9 senza madri non c\u2019\u00e8 futuro.<\/mark><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tra neuroscienze, antropologia, psicologia e vissuto personale, il saggio pubblicato da Aboca racconta il processo profondo che trasforma una donna quando ha un figlio, tra ambivalenza, postpartum, carico mentale e solitudine per ripensare la maternit\u00e0 oltre i miti del sacrificio e della perfezione<\/p>\n","protected":false},"author":502,"featured_media":427481,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[493],"tags":[210],"class_list":["post-427474","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","tag-libri"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v25.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Diventare madre \u00e8 una &quot;Supernova&quot;: la metamorfosi della matrescenza nel libro di Nina Gigante - intoscana<\/title>\n<meta name=\"description\" content=\"Intervista alla giornalista Nina Gigante che nel suo libro &quot;Supernova&quot; (Aboca Edizioni) racconta le trasformazioni della maternit\u00e0.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.intoscana.it\/it\/supernova-diventare-madre-libro-nina-gigante\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diventare madre \u00e8 una &quot;Supernova&quot;: la metamorfosi della matrescenza nel libro di Nina Gigante\" \/>\n<meta property=\"og:description\" content=\"Intervista alla giornalista Nina Gigante che nel suo libro &quot;Supernova&quot; (Aboca Edizioni) racconta le trasformazioni della maternit\u00e0.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.intoscana.it\/it\/supernova-diventare-madre-libro-nina-gigante\/\" \/>\n<meta property=\"og:site_name\" content=\"intoscana\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/intoscana.it\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T12:39:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T12:58:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/BLU_NinaGiga2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1278\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ilaria Giannini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@i.giannini@fst.it\" \/>\n<meta name=\"twitter:site\" content=\"@intoscana\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ilaria Giannini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.intoscana.it\/it\/supernova-diventare-madre-libro-nina-gigante\/\",\"url\":\"https:\/\/www.intoscana.it\/it\/supernova-diventare-madre-libro-nina-gigante\/\",\"name\":\"Diventare madre \u00e8 una \\\"Supernova\\\": la metamorfosi della matrescenza nel libro di Nina Gigante - intoscana\",\"isPartOf\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/supernova-diventare-madre-libro-nina-gigante\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/supernova-diventare-madre-libro-nina-gigante\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/BLU_NinaGiga2.jpg\",\"datePublished\":\"2026-05-13T12:39:56+00:00\",\"dateModified\":\"2026-05-13T12:58:13+00:00\",\"author\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/de95e1ed2c1c8c30a6922bbba3a90185\"},\"description\":\"Intervista alla giornalista Nina Gigante che nel suo libro \\\"Supernova\\\" (Aboca Edizioni) racconta le trasformazioni della maternit\u00e0.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/supernova-diventare-madre-libro-nina-gigante\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.intoscana.it\/it\/supernova-diventare-madre-libro-nina-gigante\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.intoscana.it\/it\/supernova-diventare-madre-libro-nina-gigante\/#primaryimage\",\"url\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/BLU_NinaGiga2.jpg\",\"contentUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/BLU_NinaGiga2.jpg\",\"width\":1920,\"height\":1278,\"caption\":\"Nina Gigante\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.intoscana.it\/it\/supernova-diventare-madre-libro-nina-gigante\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.intoscana.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diventare madre \u00e8 una &#8220;Supernova&#8221;: la metamorfosi della matrescenza nel libro di Nina Gigante\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\",\"url\":\"https:\/\/www.intoscana.it\/it\/\",\"name\":\"intoscana\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.intoscana.it\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/de95e1ed2c1c8c30a6922bbba3a90185\",\"name\":\"Ilaria Giannini\",\"sameAs\":[\"https:\/\/x.com\/i.giannini@fst.it\"],\"url\":\"https:\/\/www.intoscana.it\/it\/author\/ilaria-giannini\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Diventare madre \u00e8 una \"Supernova\": la metamorfosi della matrescenza nel libro di Nina Gigante - intoscana","description":"Intervista alla giornalista Nina Gigante che nel suo libro \"Supernova\" (Aboca Edizioni) racconta le trasformazioni della maternit\u00e0.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.intoscana.it\/it\/supernova-diventare-madre-libro-nina-gigante\/","og_locale":"it_IT","og_type":"article","og_title":"Diventare madre \u00e8 una \"Supernova\": la metamorfosi della matrescenza nel libro di Nina Gigante","og_description":"Intervista alla giornalista Nina Gigante che nel suo libro \"Supernova\" (Aboca Edizioni) racconta le trasformazioni della maternit\u00e0.","og_url":"https:\/\/www.intoscana.it\/it\/supernova-diventare-madre-libro-nina-gigante\/","og_site_name":"intoscana","article_publisher":"https:\/\/www.facebook.com\/intoscana.it","article_published_time":"2026-05-13T12:39:56+00:00","article_modified_time":"2026-05-13T12:58:13+00:00","og_image":[{"width":1920,"height":1278,"url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/BLU_NinaGiga2.jpg","type":"image\/jpeg"}],"author":"Ilaria Giannini","twitter_card":"summary_large_image","twitter_creator":"@i.giannini@fst.it","twitter_site":"@intoscana","twitter_misc":{"Written by":"Ilaria Giannini","Est. reading time":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.intoscana.it\/it\/supernova-diventare-madre-libro-nina-gigante\/","url":"https:\/\/www.intoscana.it\/it\/supernova-diventare-madre-libro-nina-gigante\/","name":"Diventare madre \u00e8 una \"Supernova\": la metamorfosi della matrescenza nel libro di Nina Gigante - intoscana","isPartOf":{"@id":"https:\/\/www.intoscana.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.intoscana.it\/it\/supernova-diventare-madre-libro-nina-gigante\/#primaryimage"},"image":{"@id":"https:\/\/www.intoscana.it\/it\/supernova-diventare-madre-libro-nina-gigante\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/BLU_NinaGiga2.jpg","datePublished":"2026-05-13T12:39:56+00:00","dateModified":"2026-05-13T12:58:13+00:00","author":{"@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/de95e1ed2c1c8c30a6922bbba3a90185"},"description":"Intervista alla giornalista Nina Gigante che nel suo libro \"Supernova\" (Aboca Edizioni) racconta le trasformazioni della maternit\u00e0.","breadcrumb":{"@id":"https:\/\/www.intoscana.it\/it\/supernova-diventare-madre-libro-nina-gigante\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.intoscana.it\/it\/supernova-diventare-madre-libro-nina-gigante\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.intoscana.it\/it\/supernova-diventare-madre-libro-nina-gigante\/#primaryimage","url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/BLU_NinaGiga2.jpg","contentUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/BLU_NinaGiga2.jpg","width":1920,"height":1278,"caption":"Nina Gigante"},{"@type":"BreadcrumbList","@id":"https:\/\/www.intoscana.it\/it\/supernova-diventare-madre-libro-nina-gigante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.intoscana.it\/it\/"},{"@type":"ListItem","position":2,"name":"Diventare madre \u00e8 una &#8220;Supernova&#8221;: la metamorfosi della matrescenza nel libro di Nina Gigante"}]},{"@type":"WebSite","@id":"https:\/\/www.intoscana.it\/it\/#website","url":"https:\/\/www.intoscana.it\/it\/","name":"intoscana","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intoscana.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/de95e1ed2c1c8c30a6922bbba3a90185","name":"Ilaria Giannini","sameAs":["https:\/\/x.com\/i.giannini@fst.it"],"url":"https:\/\/www.intoscana.it\/it\/author\/ilaria-giannini\/"}]}},"_links":{"self":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/427474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/users\/502"}],"replies":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/comments?post=427474"}],"version-history":[{"count":5,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/427474\/revisions"}],"predecessor-version":[{"id":427548,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/427474\/revisions\/427548"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media\/427481"}],"wp:attachment":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media?parent=427474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/categories?post=427474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/tags?post=427474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}