{"id":434995,"date":"2026-07-15T13:21:33","date_gmt":"2026-07-15T11:21:33","guid":{"rendered":"https:\/\/www.intoscana.it\/it\/?p=434995"},"modified":"2026-07-15T13:39:12","modified_gmt":"2026-07-15T11:39:12","slug":"120-anni-michelin-in-italia","status":"publish","type":"post","link":"https:\/\/www.intoscana.it\/it\/120-anni-michelin-in-italia\/","title":{"rendered":"Grandi chef reinterpretano la tradizione per celebrare i 120 anni di Michelin in Italia"},"content":{"rendered":"<p>Michelin festeggia <strong>120 anni<\/strong> di presenza nel nostro Paese e, per celebrare l&#8217;anniversario, ha promosso il progetto &#8220;<strong>L&#8217;Italia nel piatto<\/strong>&#8220;. L&#8217;iniziativa coinvolge i ristoranti stellati e Bib Gourmand della <strong>Guida 2026<\/strong>, che sono stati invitati a proporre una ricetta classica della cucina locale, rivisitata attraverso il proprio stile e preparata con materie prime locali.<\/p>\n<p>La <strong>Toscana<\/strong> partecipa all&#8217;iniziativa con quindici insegne, i cui contributi sono stati inseriti nel &#8220;Volume 1&#8221;, contenente le prime 120 preparazioni.<\/p>\n<h3>I ristoranti toscani per L&#8217;Italia nel piatto<\/h3>\n<figure id=\"post-295929 media-295929\" class=\"align-none\"><img decoding=\"async\" src=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/Le-pappardelle-sulla-lepre-di-Valeria-Piccini-\u00a9-Lido-Vannucchi.jpeg\" alt=\"\" \/><\/figure>\n<div class=\"titleimg\">Le pappardelle sulla lepre di Valeria Piccini \u2013 \u00a9 Lido Vannucchi<\/div>\n<p>La selezione dei ristoranti toscani copre diverse province della regione, con ricette che spaziano dalla cucina di terra a quella basata sulla cacciagione e sui prodotti locali. A <strong>Lucca<\/strong>, lo chef Aurelio Barattini dell&#8217;Antica Locanda di Sesto (Bib Gourmand) ha inserito la pasta e fagioli, cucinata con ditalini al farro, fagioli borlotti secchi, lardo, aglio, salvia e rosmarino. A <strong>Colle di Val d&#8217;Elsa<\/strong>, Gaetano Trovato del ristorante Arnolfo (due Stelle Michelin) propone invece il piatto Ortica, zafferano &#8220;Crocus&#8221;, agrumi, basato su gnudi di ricotta di pecora cotti a vapore. La tradizione della cacciagione \u00e8 rappresentata dal ristorante Caino (due Stelle Michelin) di <strong>Montemerano<\/strong>, dove la chef Valeria Piccini firma le Pappardelle sulla lepre, seguendo il procedimento tradizionale che prevede l&#8217;uso del sangue dell&#8217;animale per legare il sugo a fine cottura. A <strong>Firenze<\/strong>, lo chef Vito Mollica di Atto di Vito Mollica (una Stelle Michelin) propone una Galantina di fagianella, castagne, mandarino e Vin Santo.<\/p>\n<figure id=\"post-435014 media-435014\" class=\"align-none\"><img decoding=\"async\" src=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/Antica-Locanda-di-Sesto.jpeg\" alt=\"\" \/><\/figure>\n<div class=\"titleimg\">\u00a9 Antica Locanda di Sesto<\/div>\n<p>Lo chef Paolo Lavezzini del ristorante Il Palagio (una Stella) firma la Ricciola del Tirreno leggermente scottata, erbe di stagione, crema di salicornia e salsa olandese all&#8217;ostrica.<\/p>\n<p>Sempre a Firenze, lo chef Claudio Mengoni del ristorante Borgo San Jacopo (una Stella) partecipa con il Cannellone di genovese di agnello, finferli, fonduta di Parmigiano e tartufo nero. Spostandosi a <strong>Castelnuovo Berardenga<\/strong>, lo chef Davide Canella del ristorante Contrada (una Stella) propone il Raviolo di anguilla, juice di vitello, uva di mare, garum, mentre Senio Venturi de L&#8217;Asinello (una Stella) inserisce nel ricettario il Piccione in casseruola con datteri e cacao. A <strong>Monteriggioni<\/strong>, Samuele Bravi della Futura Osteria (Bib Gourmand) presenta gli Spaghettini del Pastificio Martelli alla salsa di pomodoro arrosto.<\/p>\n<figure id=\"post-435010 media-435010\" class=\"align-none\"><img decoding=\"async\" src=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/Locanda-de-banchieri.jpg\" alt=\"\" \/><\/figure>\n<div class=\"titleimg\">\u00a9 Locanda Dei Banchieri<\/div>\n<p>Sul litorale, a <strong>Viareggio<\/strong>, lo chef Giuseppe Mancino del ristorante Il Piccolo Principe (due Stelle) propone invece lo spaghetto in bianco, un piatto mantecato naturalmente sfruttando l&#8217;acqua ricavata dalla decantazione di cinque diverse variet\u00e0 di pomodori. A <strong>Forte dei Marmi<\/strong>, lo chef Marco Bernardo del ristorante La Magnolia (una Stella) inserisce la terrina di acciughe, pomodoro canestrino e pane sfogliato alla marinara, mentre Gioacchino Pontrelli del ristorante Lorenzo (una Stella, Forte dei Marmi) firma il piatto bavette sul pesce.<\/p>\n<p>A<strong> Tavarnelle Val di Pesa <\/strong>lo chef Giovanni Luca Di Pirro del ristorante La Torre (una Stella) firma la ricciola marinata, acqua di pomodoro chiarificata, basilico, uva spina. Infine, a <strong>Castiglione della Pescaia<\/strong>, lo chef Bruno De Moura Cossio del ristorante La Trattoria Enrico Bartolini (una Stella) propone triglia, cacciucco e zafferano, dove il pesce subisce una maturazione controllata di 4-5 giorni prima della cottura.<\/p>\n<p><span style=\"font-weight: 400;\">Lo chef Giacomo Devoto della Locanda Dei Banchieri a <strong>Fosdinovo<\/strong> ha contribuito con un risotto all&#8217;estratto di zuppa di mare.<\/span><\/p>\n<h3>L&#8217;iniziativa di Michelin Italiana<\/h3>\n<p>Il progetto L&#8217;Italia nel piatto documenta lo stato della gastronomia attraverso formule e schede tecniche complete di ingredienti e descrizioni dei procedimenti. Il Gruppo Michelin, presente in Italia dal <strong>1906<\/strong> con i suoi stabilimenti industriali e dal <strong>1956<\/strong> con la prima edizione della Guida gastronomica, ha strutturato la pubblicazione del ricettario in due momenti.<\/p>\n<p>Ad oggi \u00e8 disponibile per il download gratuito il &#8220;<a href=\"https:\/\/lulop.com\/michelin\/it_IT\/post\/show\/354691\/\" target=\"_blank\" rel=\"noopener\" class=\"broken_link\"><strong>Volume 1<\/strong><\/a>&#8220;, che contiene le prime 120 ricette, incluse quelle degli chef toscani. La seconda parte della raccolta sar\u00e0 invece pubblicata e resa scaricabile sul sito ufficiale della Guida il prossimo<strong> 27 agosto<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da Aurelio Barattini a Gaetano Trovato, passando per Valeria Piccini e Vito Mollica: quindici ristoranti stellati e Bib Gourmand della Toscana firmano l&#8217;esclusivo ricettario &#8220;L&#8217;Italia nel piatto&#8221; che unisce memoria e innovazione<\/p>\n","protected":false},"author":483,"featured_media":435004,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8],"tags":[4817,5023,6000,5022,5222],"class_list":["post-434995","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-enogastronomia","tag-chef","tag-guida-michelin","tag-ricette","tag-ristoranti","tag-stelle-michelin"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v25.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Grandi chef reinterpretano la tradizione per celebrare i 120 anni di Michelin in Italia - intoscana<\/title>\n<meta name=\"description\" content=\"Michelin Italiana festeggia 120 anni di presenza in Italia. Gli chef toscani celebrano questo traguardo con tante ricette innovative.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.intoscana.it\/it\/120-anni-michelin-in-italia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grandi chef reinterpretano la tradizione per celebrare i 120 anni di Michelin in Italia\" \/>\n<meta property=\"og:description\" content=\"Michelin Italiana festeggia 120 anni di presenza in Italia. Gli chef toscani celebrano questo traguardo con tante ricette innovative.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.intoscana.it\/it\/120-anni-michelin-in-italia\/\" \/>\n<meta property=\"og:site_name\" content=\"intoscana\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/intoscana.it\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T11:21:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T11:39:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.intoscana.it\/wp-content\/uploads\/michelin-italia-120-anni.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marta Mancini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@intoscana\" \/>\n<meta name=\"twitter:site\" content=\"@intoscana\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marta Mancini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.intoscana.it\/it\/120-anni-michelin-in-italia\/\",\"url\":\"https:\/\/www.intoscana.it\/it\/120-anni-michelin-in-italia\/\",\"name\":\"Grandi chef reinterpretano la tradizione per celebrare i 120 anni di Michelin in Italia - intoscana\",\"isPartOf\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/120-anni-michelin-in-italia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/120-anni-michelin-in-italia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/michelin-italia-120-anni.jpg\",\"datePublished\":\"2026-07-15T11:21:33+00:00\",\"dateModified\":\"2026-07-15T11:39:12+00:00\",\"author\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/ba955c49c389f39a8208f182b0652479\"},\"description\":\"Michelin Italiana festeggia 120 anni di presenza in Italia. Gli chef toscani celebrano questo traguardo con tante ricette innovative.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.intoscana.it\/it\/120-anni-michelin-in-italia\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.intoscana.it\/it\/120-anni-michelin-in-italia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.intoscana.it\/it\/120-anni-michelin-in-italia\/#primaryimage\",\"url\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/michelin-italia-120-anni.jpg\",\"contentUrl\":\"https:\/\/www.intoscana.it\/wp-content\/uploads\/michelin-italia-120-anni.jpg\",\"width\":1080,\"height\":1350,\"caption\":\"Michelin Italiana celebra 120 anni con L\u2019Italia nel Piatto\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.intoscana.it\/it\/120-anni-michelin-in-italia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.intoscana.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Grandi chef reinterpretano la tradizione per celebrare i 120 anni di Michelin in Italia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#website\",\"url\":\"https:\/\/www.intoscana.it\/it\/\",\"name\":\"intoscana\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.intoscana.it\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/ba955c49c389f39a8208f182b0652479\",\"name\":\"Marta Mancini\",\"url\":\"https:\/\/www.intoscana.it\/it\/author\/marta-mancini\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Grandi chef reinterpretano la tradizione per celebrare i 120 anni di Michelin in Italia - intoscana","description":"Michelin Italiana festeggia 120 anni di presenza in Italia. Gli chef toscani celebrano questo traguardo con tante ricette innovative.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.intoscana.it\/it\/120-anni-michelin-in-italia\/","og_locale":"it_IT","og_type":"article","og_title":"Grandi chef reinterpretano la tradizione per celebrare i 120 anni di Michelin in Italia","og_description":"Michelin Italiana festeggia 120 anni di presenza in Italia. Gli chef toscani celebrano questo traguardo con tante ricette innovative.","og_url":"https:\/\/www.intoscana.it\/it\/120-anni-michelin-in-italia\/","og_site_name":"intoscana","article_publisher":"https:\/\/www.facebook.com\/intoscana.it","article_published_time":"2026-07-15T11:21:33+00:00","article_modified_time":"2026-07-15T11:39:12+00:00","og_image":[{"width":1080,"height":1350,"url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/michelin-italia-120-anni.jpg","type":"image\/jpeg"}],"author":"Marta Mancini","twitter_card":"summary_large_image","twitter_creator":"@intoscana","twitter_site":"@intoscana","twitter_misc":{"Written by":"Marta Mancini","Est. reading time":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.intoscana.it\/it\/120-anni-michelin-in-italia\/","url":"https:\/\/www.intoscana.it\/it\/120-anni-michelin-in-italia\/","name":"Grandi chef reinterpretano la tradizione per celebrare i 120 anni di Michelin in Italia - intoscana","isPartOf":{"@id":"https:\/\/www.intoscana.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.intoscana.it\/it\/120-anni-michelin-in-italia\/#primaryimage"},"image":{"@id":"https:\/\/www.intoscana.it\/it\/120-anni-michelin-in-italia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/michelin-italia-120-anni.jpg","datePublished":"2026-07-15T11:21:33+00:00","dateModified":"2026-07-15T11:39:12+00:00","author":{"@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/ba955c49c389f39a8208f182b0652479"},"description":"Michelin Italiana festeggia 120 anni di presenza in Italia. Gli chef toscani celebrano questo traguardo con tante ricette innovative.","breadcrumb":{"@id":"https:\/\/www.intoscana.it\/it\/120-anni-michelin-in-italia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.intoscana.it\/it\/120-anni-michelin-in-italia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.intoscana.it\/it\/120-anni-michelin-in-italia\/#primaryimage","url":"https:\/\/www.intoscana.it\/wp-content\/uploads\/michelin-italia-120-anni.jpg","contentUrl":"https:\/\/www.intoscana.it\/wp-content\/uploads\/michelin-italia-120-anni.jpg","width":1080,"height":1350,"caption":"Michelin Italiana celebra 120 anni con L\u2019Italia nel Piatto"},{"@type":"BreadcrumbList","@id":"https:\/\/www.intoscana.it\/it\/120-anni-michelin-in-italia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.intoscana.it\/it\/"},{"@type":"ListItem","position":2,"name":"Grandi chef reinterpretano la tradizione per celebrare i 120 anni di Michelin in Italia"}]},{"@type":"WebSite","@id":"https:\/\/www.intoscana.it\/it\/#website","url":"https:\/\/www.intoscana.it\/it\/","name":"intoscana","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intoscana.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.intoscana.it\/it\/#\/schema\/person\/ba955c49c389f39a8208f182b0652479","name":"Marta Mancini","url":"https:\/\/www.intoscana.it\/it\/author\/marta-mancini\/"}]}},"_links":{"self":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/434995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/users\/483"}],"replies":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/comments?post=434995"}],"version-history":[{"count":5,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/434995\/revisions"}],"predecessor-version":[{"id":435021,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/posts\/434995\/revisions\/435021"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media\/435004"}],"wp:attachment":[{"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/media?parent=434995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/categories?post=434995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.intoscana.it\/it\/wp-json\/wp\/v2\/tags?post=434995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}